{"id":9487,"date":"2019-10-22T09:00:00","date_gmt":"2019-10-22T08:00:00","guid":{"rendered":"https:\/\/test.ifesworld.org\/?post_type=prayerline&#038;p=9487"},"modified":"2019-10-22T10:57:29","modified_gmt":"2019-10-22T09:57:29","slug":"les-defis-rencontres-par-monique-en-defrichant-de-nouveaux-territoires","status":"publish","type":"prayerline","link":"https:\/\/test.ifesworld.org\/fr\/prayerline\/les-defis-rencontres-par-monique-en-defrichant-de-nouveaux-territoires\/","title":{"rendered":"Les d\u00e9fis rencontr\u00e9s par Monique en d\u00e9frichant de nouveaux territoires"},"content":{"rendered":"<div class=\"wp-block block-core-paragraph\">\n<p class=\"has-md-font-size wp-block-paragraph\">ll se trouve sur une\nminuscule \u00eele des Cara\u00efbes. C&rsquo;est l&rsquo;un des plus petits points sur une carte du\nmonde. Vous n&rsquo;en avez peut-\u00eatre jamais entendu parler, mais Sint Maarten\n(royaume des Pays-Bas) a besoin de vos pri\u00e8res.<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Monique est en train de d\u00e9marrer un nouveau mouvement de l&rsquo;IFES \u00e0 Sint Maarten. Elle travaille en partenariat avec le mouvement de l&rsquo;IFES au Suriname voisin, et est soutenue par le projet pionnier de l&rsquo;IFES <em><a href=\"https:\/\/test.ifesworld.org\/fr\/pionnier\/\">D\u00e9fricher de nouveaux territoires<\/a><\/em>.<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Mais ce n&rsquo;est pas une\nt\u00e2che facile. Monique s&rsquo;est d\u00e9j\u00e0 adress\u00e9e \u00e0 cinq \u00e9coles, mais aucune d&rsquo;entre\nelles n&rsquo;a voulu la laisser y d\u00e9marrer un groupe biblique\nlyc\u00e9en. L&rsquo;universit\u00e9 de Sint Maarten, quant \u00e0 elle,\nest petite et la plupart des cursus ne durent que deux ans, ce qui fait que les\n\u00e9tudiants ne restent pas longtemps.<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Il serait facile d&rsquo;\u00eatre d\u00e9courag\u00e9 et de se sentir seul face \u00e0 ces difficult\u00e9s. Mais cette semaine, Monique n&rsquo;est pas seule. Elle a rejoint <strong>? ? <\/strong>30 autres personnes \u00e0 l\u2019occasion de la rencontre <em>D\u00e9fricher de nouveaux territoires<\/em> au Canada. Les jeunes pionniers apprendront \u00e0 d\u00e9marrer de nouveaux groupes et pourront parler ensemble de leurs difficult\u00e9s et des meilleures pratiques.<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-heading\">\n<h4 class=\"wp-block-heading\">Priez avec nous pour\nMonique et pour la rencontre de cette semaine :<\/h4>\n<\/div>\n\n<div class=\"wp-block block-core-list\">\n<ul class=\"wp-block-list\"><li>Priez que\nMonique trouve quelqu&rsquo;un sur l&rsquo;\u00eele qui pourra prier avec\nelle et r\u00e9fl\u00e9chir \u00e0 la fa\u00e7on dont ils pourraient\nd\u00e9marrer un nouveau mouvement.<\/li><li>Priez que\nMonique et les autres participants \u00e0 la rencontre <em>D\u00e9fricher de nouveaux territoires<\/em> soient encourag\u00e9s par leur temps\nensemble et outill\u00e9s pour d\u00e9marrer des groupes autochtones partout dans le monde.<\/li><\/ul>\n<\/div>","protected":false},"featured_media":9488,"template":"","area":[948,980],"theme":[1230],"class_list":["post-9487","prayerline","type-prayerline","status-publish","has-post-thumbnail","hentry","area-caraibe","area-saint-martin-caraibe","theme-defricher-de-nouveaux-territoires"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les d\u00e9fis rencontr\u00e9s par Monique en d\u00e9frichant de nouveaux territoires &#183; IFES Prayerline<\/title>\n<meta name=\"description\" content=\"ll se trouve sur une minuscule \u00eele des Cara\u00efbes. C&#039;est l&#039;un des plus petits points sur une carte du monde. Vous n&#039;en avez peut-\u00eatre jamais entendu parler,\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les d\u00e9fis rencontr\u00e9s par Monique en d\u00e9frichant de nouveaux territoires &#183; IFES Prayerline\" \/>\n<meta property=\"og:description\" content=\"ll se trouve sur une minuscule \u00eele des Cara\u00efbes. C&#039;est l&#039;un des plus petits points sur une carte du monde. Vous n&#039;en avez peut-\u00eatre jamais entendu parler,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/prayerline\/monique-faces-challenges-in-breaking-new-ground\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-22T09:57:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/10\/PL191021-Sint-Maarten-Monique2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/monique-faces-challenges-in-breaking-new-ground\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/monique-faces-challenges-in-breaking-new-ground\\\/\",\"name\":\"Les d\u00e9fis rencontr\u00e9s par Monique en d\u00e9frichant de nouveaux territoires &#183; IFES Prayerline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/monique-faces-challenges-in-breaking-new-ground\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/monique-faces-challenges-in-breaking-new-ground\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/PL191021-Sint-Maarten-Monique2.jpg\",\"datePublished\":\"2019-10-22T08:00:00+00:00\",\"dateModified\":\"2019-10-22T09:57:29+00:00\",\"description\":\"ll se trouve sur une minuscule \u00eele des Cara\u00efbes. C'est l'un des plus petits points sur une carte du monde. Vous n'en avez peut-\u00eatre jamais entendu parler,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/monique-faces-challenges-in-breaking-new-ground\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/monique-faces-challenges-in-breaking-new-ground\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/monique-faces-challenges-in-breaking-new-ground\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/PL191021-Sint-Maarten-Monique2.jpg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/PL191021-Sint-Maarten-Monique2.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/monique-faces-challenges-in-breaking-new-ground\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prayerline\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les d\u00e9fis rencontr\u00e9s par Monique en d\u00e9frichant de nouveaux territoires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les d\u00e9fis rencontr\u00e9s par Monique en d\u00e9frichant de nouveaux territoires &#183; IFES Prayerline","description":"ll se trouve sur une minuscule \u00eele des Cara\u00efbes. C'est l'un des plus petits points sur une carte du monde. Vous n'en avez peut-\u00eatre jamais entendu parler,","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Les d\u00e9fis rencontr\u00e9s par Monique en d\u00e9frichant de nouveaux territoires &#183; IFES Prayerline","og_description":"ll se trouve sur une minuscule \u00eele des Cara\u00efbes. C'est l'un des plus petits points sur une carte du monde. Vous n'en avez peut-\u00eatre jamais entendu parler,","og_url":"https:\/\/test.ifesworld.org\/en\/prayerline\/monique-faces-challenges-in-breaking-new-ground\/","og_site_name":"IFES","article_modified_time":"2019-10-22T09:57:29+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/10\/PL191021-Sint-Maarten-Monique2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/monique-faces-challenges-in-breaking-new-ground\/","url":"https:\/\/test.ifesworld.org\/en\/prayerline\/monique-faces-challenges-in-breaking-new-ground\/","name":"Les d\u00e9fis rencontr\u00e9s par Monique en d\u00e9frichant de nouveaux territoires &#183; IFES Prayerline","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/monique-faces-challenges-in-breaking-new-ground\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/monique-faces-challenges-in-breaking-new-ground\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/10\/PL191021-Sint-Maarten-Monique2.jpg","datePublished":"2019-10-22T08:00:00+00:00","dateModified":"2019-10-22T09:57:29+00:00","description":"ll se trouve sur une minuscule \u00eele des Cara\u00efbes. C'est l'un des plus petits points sur une carte du monde. Vous n'en avez peut-\u00eatre jamais entendu parler,","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/monique-faces-challenges-in-breaking-new-ground\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/prayerline\/monique-faces-challenges-in-breaking-new-ground\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/monique-faces-challenges-in-breaking-new-ground\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/10\/PL191021-Sint-Maarten-Monique2.jpg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/10\/PL191021-Sint-Maarten-Monique2.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/monique-faces-challenges-in-breaking-new-ground\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Prayerline","item":"https:\/\/test.ifesworld.org\/en\/prayerline\/"},{"@type":"ListItem","position":3,"name":"Les d\u00e9fis rencontr\u00e9s par Monique en d\u00e9frichant de nouveaux territoires"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/prayerline\/9487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/prayerline"}],"about":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/types\/prayerline"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media\/9488"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media?parent=9487"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/area?post=9487"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/theme?post=9487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}