{"id":2342,"date":"2018-08-14T15:00:00","date_gmt":"2018-08-14T15:00:00","guid":{"rendered":"https:\/\/test.ifesworld.org\/prayerline\/priez-pour-les-nouveaux-etudiants-dans-le-monde\/"},"modified":"2019-05-30T14:50:39","modified_gmt":"2019-05-30T14:50:39","slug":"priez-pour-les-nouveaux-etudiants-dans-le-monde","status":"publish","type":"prayerline","link":"https:\/\/test.ifesworld.org\/fr\/prayerline\/priez-pour-les-nouveaux-etudiants-dans-le-monde\/","title":{"rendered":"Priez pour les nouveaux \u00e9tudiants dans le monde"},"content":{"rendered":"<p>Dans les prochaines semaines, des millions d&rsquo;\u00e9tudiants dans le monde iront \u00e0 l&rsquo;universit\u00e9 pour la premi\u00e8re fois. Laura qui a 18 ans en fait partie. Elle \u00e9tudiera la psychologie dans une universit\u00e9 au Br\u00e9sil. Elle fait part de ses r\u00e9flexions :<\/p>\n\n<div class=\"wp-block block-core-quote\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p> Je vais commencer l&rsquo;universit\u00e9 ce mois-ci. M\u00eame si je le sais depuis f\u00e9vrier, je suis malgr\u00e9 tout inqui\u00e8te \u00e0 ce propos. Le sentiment de quitter ma zone de confort dans une \u00e9cole o\u00f9 j&rsquo;ai \u00e9tudi\u00e9 pendant des ann\u00e9es avec les m\u00eames amis, et circuler dans un environnement totalement nouveau pour moi, c&rsquo;est ce qui me pr\u00e9occupe. Est-ce que je vais pouvoir me faire de nouveaux amis ? Les cours sont-ils aussi difficiles qu&rsquo;on me l&rsquo;a dit ? Est-ce que je vais subir de la discrimination parce que suis chr\u00e9tienne ? Il s&rsquo;agit l\u00e0 de quelques-unes de mes inqui\u00e9tudes concernant l&rsquo;universit\u00e9. Les grands changements g\u00e9n\u00e8rent de grandes peurs.<\/p><p><br> Mais c&rsquo;est aussi une nouvelle opportunit\u00e9 de croissance. Je veux me faire de nouveaux amis. Je veux \u00eatre mise au d\u00e9fi intellectuellement. Je veux marquer la diff\u00e9rence pour Christ dans mon universit\u00e9. Je veux en apprendre davantage sur les id\u00e9ologies politiques de mes amis de classe pour aider ceux qui ne sont pas encore venus \u00e0 Christ. L&rsquo;universit\u00e9 est un espace o\u00f9 Dieu va cro\u00eetre en moi. M\u00eame si j&rsquo;ai des craintes, je sais que je n&rsquo;ai pas \u00e0 avoir peur parce qu&rsquo;Il est avec moi. <\/p><\/blockquote>\n<\/div>\n\n<p>Cette semaine, merci de prier avec nous pour Laura et d&rsquo;autres \u00e9tudiants qui commencent l&rsquo;universit\u00e9 pour la premi\u00e8re fois :<\/p>\n<ul>\n<li>Priez pour l&rsquo;ABUB Br\u00e9sil afin qu&rsquo;ils soient forts dans l&rsquo;accueil de nouveaux \u00e9tudiants comme Laura en les aidant \u00e0 s&rsquo;int\u00e9grer dans de bonnes \u00e9glises locales et qu&rsquo;ils trouvent le soutien et la communion dont ils ont besoin pour s&rsquo;\u00e9panouir dans leur foi chr\u00e9tienne.<\/li>\n<li>Priez pour que les \u00e9tudiants ne soient pas bloqu\u00e9s dans une bulle chr\u00e9tienne mais qu&rsquo;ils s&rsquo;engagent dans la vie universitaire et qu&rsquo;ils soient actifs dans le partage de leur foi avec leurs amis d\u00e8s les d\u00e9buts.<\/li>\n<li>Priez pour les opportunit\u00e9s pendant les semaines d&rsquo;orientation afin qu&rsquo;ils aillent vers les \u00e9tudiants non-chr\u00e9tiens.<\/li>\n<\/ul>\n<p>Merci de prier avec nous !<\/p>","protected":false},"featured_media":2892,"template":"","area":[954,1115],"theme":[1259],"class_list":["post-2342","prayerline","type-prayerline","status-publish","has-post-thumbnail","hentry","area-amerique-latine","area-bresil","theme-mon-histoire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Priez pour les nouveaux \u00e9tudiants dans le monde &#183; IFES Prayerline<\/title>\n<meta name=\"description\" content=\"Dans les prochaines semaines, des millions d&#039;\u00e9tudiants dans le monde iront \u00e0 l&#039;universit\u00e9 pour la premi\u00e8re fois. Laura qui a 18 ans en fait partie. Elle\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Priez pour les nouveaux \u00e9tudiants dans le monde &#183; IFES Prayerline\" \/>\n<meta property=\"og:description\" content=\"Dans les prochaines semaines, des millions d&#039;\u00e9tudiants dans le monde iront \u00e0 l&#039;universit\u00e9 pour la premi\u00e8re fois. Laura qui a 18 ans en fait partie. Elle\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/prayerline\/pray-for-new-students-around-the-world\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-30T14:50:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2018\/08\/180814-Brazil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/pray-for-new-students-around-the-world\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/pray-for-new-students-around-the-world\\\/\",\"name\":\"Priez pour les nouveaux \u00e9tudiants dans le monde &#183; IFES Prayerline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/pray-for-new-students-around-the-world\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/pray-for-new-students-around-the-world\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/180814-Brazil.jpg\",\"datePublished\":\"2018-08-14T15:00:00+00:00\",\"dateModified\":\"2019-05-30T14:50:39+00:00\",\"description\":\"Dans les prochaines semaines, des millions d'\u00e9tudiants dans le monde iront \u00e0 l'universit\u00e9 pour la premi\u00e8re fois. Laura qui a 18 ans en fait partie. Elle\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/pray-for-new-students-around-the-world\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/pray-for-new-students-around-the-world\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/pray-for-new-students-around-the-world\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/180814-Brazil.jpg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/180814-Brazil.jpg\",\"width\":1280,\"height\":720,\"caption\":\"180814 Brazil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/pray-for-new-students-around-the-world\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prayerline\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Priez pour les nouveaux \u00e9tudiants dans le monde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Priez pour les nouveaux \u00e9tudiants dans le monde &#183; IFES Prayerline","description":"Dans les prochaines semaines, des millions d'\u00e9tudiants dans le monde iront \u00e0 l'universit\u00e9 pour la premi\u00e8re fois. Laura qui a 18 ans en fait partie. Elle","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Priez pour les nouveaux \u00e9tudiants dans le monde &#183; IFES Prayerline","og_description":"Dans les prochaines semaines, des millions d'\u00e9tudiants dans le monde iront \u00e0 l'universit\u00e9 pour la premi\u00e8re fois. Laura qui a 18 ans en fait partie. Elle","og_url":"https:\/\/test.ifesworld.org\/en\/prayerline\/pray-for-new-students-around-the-world\/","og_site_name":"IFES","article_modified_time":"2019-05-30T14:50:39+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2018\/08\/180814-Brazil.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/pray-for-new-students-around-the-world\/","url":"https:\/\/test.ifesworld.org\/en\/prayerline\/pray-for-new-students-around-the-world\/","name":"Priez pour les nouveaux \u00e9tudiants dans le monde &#183; IFES Prayerline","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/pray-for-new-students-around-the-world\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/pray-for-new-students-around-the-world\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2018\/08\/180814-Brazil.jpg","datePublished":"2018-08-14T15:00:00+00:00","dateModified":"2019-05-30T14:50:39+00:00","description":"Dans les prochaines semaines, des millions d'\u00e9tudiants dans le monde iront \u00e0 l'universit\u00e9 pour la premi\u00e8re fois. Laura qui a 18 ans en fait partie. Elle","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/pray-for-new-students-around-the-world\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/prayerline\/pray-for-new-students-around-the-world\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/pray-for-new-students-around-the-world\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2018\/08\/180814-Brazil.jpg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2018\/08\/180814-Brazil.jpg","width":1280,"height":720,"caption":"180814 Brazil"},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/pray-for-new-students-around-the-world\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Prayerline","item":"https:\/\/test.ifesworld.org\/en\/prayerline\/"},{"@type":"ListItem","position":3,"name":"Priez pour les nouveaux \u00e9tudiants dans le monde"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/prayerline\/2342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/prayerline"}],"about":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/types\/prayerline"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media\/2892"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media?parent=2342"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/area?post=2342"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/theme?post=2342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}