{"id":2338,"date":"2018-10-23T15:00:00","date_gmt":"2018-10-23T15:00:00","guid":{"rendered":"https:\/\/test.ifesworld.org\/prayerline\/la-lumiere-de-dieu-au-chiapas-et-%e2%80%afle-cercle-du-silence%e2%80%af\/"},"modified":"2019-05-29T15:28:38","modified_gmt":"2019-05-29T15:28:38","slug":"la-lumiere-de-dieu-au-chiapas-et-%e2%80%afle-cercle-du-silence%e2%80%af","status":"publish","type":"prayerline","link":"https:\/\/test.ifesworld.org\/fr\/prayerline\/la-lumiere-de-dieu-au-chiapas-et-%e2%80%afle-cercle-du-silence%e2%80%af\/","title":{"rendered":"La lumi\u00e8re de Dieu au Chiapas et \u00ab\u202fLe Cercle du Silence\u202f\u00bb"},"content":{"rendered":"<p>Jes\u00fas et sa fianc\u00e9e Jessie sont des \u00e9tudiants en m\u00e9decine dans la pauvre mais belle r\u00e9gion mexicaine du Chiapas. La plupart des \u00e9tudiants \u00e0 leur universit\u00e9 sont originaires des communaut\u00e9s autochtones locales. C&rsquo;est une universit\u00e9 distinctive car tous les \u00e9tudiants doivent \u00e0 la fois parler et \u00e9tudier un dialecte local dans le cadre de leurs \u00e9tudes. C&rsquo;est l&rsquo;une des strat\u00e9gies du gouvernement pour encourager les \u00e9tudiants \u00e0 trouver un travail parmi les communaut\u00e9s autochtones apr\u00e8s avoir re\u00e7u leur dipl\u00f4me.<\/p>\n<p>M\u00eame si les chr\u00e9tiens ne sont que peu nombreux sur le campus, pour les \u00e9tudiants comme Jessie et Jes\u00fas, c&rsquo;est id\u00e9al pour la formation missionnaire. En dehors de leurs \u00e9tudes de langue et de m\u00e9decine, ils animent le petit groupe d&rsquo;\u00e9tude biblique COMPA. On voit souvent Jes\u00fas faire le tour du campus pour vendre des bonbons. Il invite chaque \u00e9tudiant qu&rsquo;il rencontre \u00e0 l&rsquo;\u00e9tude biblique. Jes\u00fas et Jessie ont un profond d\u00e9sir de voir plus de gens rencontrer le Christ ressuscit\u00e9 cette ann\u00e9e.<\/p>\n<p>Plus au nord du Mexique, il existe une r\u00e9gion connue sous le nom de \u00ab\u202fCercle du Silence\u202f\u00bb o\u00f9 l&rsquo;\u00c9vangile n&rsquo;a que peu avanc\u00e9. Mais m\u00eame l\u00e0, Dieu est \u00e0 l&rsquo;\u0153uvre. Sandra, une \u00e9tudiante en ing\u00e9nierie, a rencontr\u00e9 le personnel de COMPA il y a un an\u202f; elle ne semblait alors que vaguement int\u00e9ress\u00e9e. Mais au cours de l&rsquo;ann\u00e9e, Dieu l&rsquo;a fait grandir et lui a donn\u00e9 une nouvelle passion pour sa Parole. Ce semestre, elle a commenc\u00e9 un groupe d&rsquo;\u00e9tude biblique sur le campus \u2013 le tout premier de cette universit\u00e9 \u2013 et se r\u00e9jouit d&rsquo;y accueillir l&rsquo;un de ses amis non-chr\u00e9tiens.<\/p>\n<p>Joignez-vous \u00e0 nous pour prier pour Jes\u00fas, Jessie et Sandra alors qu&rsquo;ils animent les \u00e9tudes bibliques et apportent la lumi\u00e8re de Dieu aux campus t\u00e9n\u00e9breux du Mexique.<\/p>\n<ul>\n<li>Priez que beaucoup d&rsquo;\u00e9tudiants viennent \u00e0 conna\u00eetre Christ cette ann\u00e9e gr\u00e2ce \u00e0 ces groupes.<\/li>\n<li>Priez que, suite \u00e0 leurs \u00e9tudes, les \u00e9tudiants chr\u00e9tiens dans ces r\u00e9gions difficiles du Mexique aient un impact puissant sur leur \u00e9glise et leur communaut\u00e9.<\/li>\n<\/ul>\n<p>Merci de prier avec nous !<\/p>\n","protected":false},"featured_media":2839,"template":"","area":[954,1124],"theme":[1248],"class_list":["post-2338","prayerline","type-prayerline","status-publish","has-post-thumbnail","hentry","area-amerique-latine","area-mexique","theme-evangelisation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La lumi\u00e8re de Dieu au Chiapas et \u00ab\u202fLe Cercle du Silence\u202f\u00bb &#183; IFES Prayerline<\/title>\n<meta name=\"description\" content=\"Jes\u00fas et sa fianc\u00e9e Jessie sont des \u00e9tudiants en m\u00e9decine dans la pauvre mais belle r\u00e9gion mexicaine du Chiapas. La plupart des \u00e9tudiants \u00e0 leur\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La lumi\u00e8re de Dieu au Chiapas et \u00ab\u202fLe Cercle du Silence\u202f\u00bb &#183; IFES Prayerline\" \/>\n<meta property=\"og:description\" content=\"Jes\u00fas et sa fianc\u00e9e Jessie sont des \u00e9tudiants en m\u00e9decine dans la pauvre mais belle r\u00e9gion mexicaine du Chiapas. La plupart des \u00e9tudiants \u00e0 leur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/prayerline\/gods-light-inchiapas-and-the-circle-of-silence\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-29T15:28:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2018\/10\/181023-Mexico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/gods-light-inchiapas-and-the-circle-of-silence\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/gods-light-inchiapas-and-the-circle-of-silence\\\/\",\"name\":\"La lumi\u00e8re de Dieu au Chiapas et \u00ab\u202fLe Cercle du Silence\u202f\u00bb &#183; IFES Prayerline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/gods-light-inchiapas-and-the-circle-of-silence\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/gods-light-inchiapas-and-the-circle-of-silence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/181023-Mexico.jpg\",\"datePublished\":\"2018-10-23T15:00:00+00:00\",\"dateModified\":\"2019-05-29T15:28:38+00:00\",\"description\":\"Jes\u00fas et sa fianc\u00e9e Jessie sont des \u00e9tudiants en m\u00e9decine dans la pauvre mais belle r\u00e9gion mexicaine du Chiapas. La plupart des \u00e9tudiants \u00e0 leur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/gods-light-inchiapas-and-the-circle-of-silence\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/gods-light-inchiapas-and-the-circle-of-silence\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/gods-light-inchiapas-and-the-circle-of-silence\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/181023-Mexico.jpg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/181023-Mexico.jpg\",\"width\":1280,\"height\":960,\"caption\":\"181023 Mexico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/gods-light-inchiapas-and-the-circle-of-silence\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prayerline\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La lumi\u00e8re de Dieu au Chiapas et \u00ab\u202fLe Cercle du Silence\u202f\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La lumi\u00e8re de Dieu au Chiapas et \u00ab\u202fLe Cercle du Silence\u202f\u00bb &#183; IFES Prayerline","description":"Jes\u00fas et sa fianc\u00e9e Jessie sont des \u00e9tudiants en m\u00e9decine dans la pauvre mais belle r\u00e9gion mexicaine du Chiapas. La plupart des \u00e9tudiants \u00e0 leur","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"La lumi\u00e8re de Dieu au Chiapas et \u00ab\u202fLe Cercle du Silence\u202f\u00bb &#183; IFES Prayerline","og_description":"Jes\u00fas et sa fianc\u00e9e Jessie sont des \u00e9tudiants en m\u00e9decine dans la pauvre mais belle r\u00e9gion mexicaine du Chiapas. La plupart des \u00e9tudiants \u00e0 leur","og_url":"https:\/\/test.ifesworld.org\/en\/prayerline\/gods-light-inchiapas-and-the-circle-of-silence\/","og_site_name":"IFES","article_modified_time":"2019-05-29T15:28:38+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2018\/10\/181023-Mexico.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/gods-light-inchiapas-and-the-circle-of-silence\/","url":"https:\/\/test.ifesworld.org\/en\/prayerline\/gods-light-inchiapas-and-the-circle-of-silence\/","name":"La lumi\u00e8re de Dieu au Chiapas et \u00ab\u202fLe Cercle du Silence\u202f\u00bb &#183; IFES Prayerline","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/gods-light-inchiapas-and-the-circle-of-silence\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/gods-light-inchiapas-and-the-circle-of-silence\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2018\/10\/181023-Mexico.jpg","datePublished":"2018-10-23T15:00:00+00:00","dateModified":"2019-05-29T15:28:38+00:00","description":"Jes\u00fas et sa fianc\u00e9e Jessie sont des \u00e9tudiants en m\u00e9decine dans la pauvre mais belle r\u00e9gion mexicaine du Chiapas. La plupart des \u00e9tudiants \u00e0 leur","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/gods-light-inchiapas-and-the-circle-of-silence\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/prayerline\/gods-light-inchiapas-and-the-circle-of-silence\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/gods-light-inchiapas-and-the-circle-of-silence\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2018\/10\/181023-Mexico.jpg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2018\/10\/181023-Mexico.jpg","width":1280,"height":960,"caption":"181023 Mexico"},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/gods-light-inchiapas-and-the-circle-of-silence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Prayerline","item":"https:\/\/test.ifesworld.org\/en\/prayerline\/"},{"@type":"ListItem","position":3,"name":"La lumi\u00e8re de Dieu au Chiapas et \u00ab\u202fLe Cercle du Silence\u202f\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/prayerline\/2338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/prayerline"}],"about":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/types\/prayerline"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media\/2839"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media?parent=2338"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/area?post=2338"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/theme?post=2338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}