{"id":2328,"date":"2019-01-29T14:00:00","date_gmt":"2019-01-29T14:00:00","guid":{"rendered":"https:\/\/test.ifesworld.org\/prayerline\/que-les-portes-souvrent-pour-un-travail-pionnier-sur-un-nouveau-campus\/"},"modified":"2019-05-24T11:53:40","modified_gmt":"2019-05-24T11:53:40","slug":"que-les-portes-souvrent-pour-un-travail-pionnier-sur-un-nouveau-campus","status":"publish","type":"prayerline","link":"https:\/\/test.ifesworld.org\/fr\/prayerline\/que-les-portes-souvrent-pour-un-travail-pionnier-sur-un-nouveau-campus\/","title":{"rendered":"Que les portes s\u2019ouvrent pour un travail pionnier sur un nouveau campus"},"content":{"rendered":"<p>C&rsquo;\u00e9tait un plan ambitieux : d\u00e9marrer un nouveau groupe \u00e9tudiant sur un campus non atteint en une semaine avec une \u00e9quipe compos\u00e9e de 13 \u00e9tudiants, \u00e9quipiers et b\u00e9n\u00e9voles de LIFES Liberia. Lorsqu&rsquo;ils sont arriv\u00e9s sur le campus, ils ont pu constater que le Seigneur avait d\u00e9j\u00e0 aplani le sentier devant eux.<\/p>\n<p>Le doyen aux affaires \u00e9tudiantes leur a r\u00e9serv\u00e9 un accueil enthousiaste sur le campus et ils se sont s\u00e9par\u00e9s en paires pour demander aux \u00e9tudiants s&rsquo;ils \u00e9taient int\u00e9ress\u00e9s \u00e0 se joindre \u00e0 un groupe chr\u00e9tien. Certains professeurs leur ont m\u00eame permis de faire des annonces \u00e0 ce sujet en classe.<\/p>\n<p>Liz et Becky ont amorc\u00e9 une conversation avec un \u00e9tudiant du nom d&rsquo;Emmanuel. Becky lui a demand\u00e9 : \u00ab\u202fQue d\u00e9sirerais-tu que Dieu fasse pour toi ?\u202f\u00bb Il a r\u00e9pondu : \u00ab\u202fJ&rsquo;aimerais qu&rsquo;il me transforme. J&rsquo;aimerais \u00eatre comme vous \u2013 me d\u00e9placer ici et l\u00e0 sur le campus et parler de J\u00e9sus avec mes amis.\u202f\u00bb Quelques minutes plus tard, Emmanuel accompagnait Liz et Becky tandis qu&rsquo;elles partageaient la vision de LIFES et invitaient ses pairs \u00e0 se joindre au nouveau groupe.<\/p>\n<p>Le lendemain, lors de la rencontre de d\u00e9marrage, Emmanuel s&rsquo;est pr\u00e9sent\u00e9, accompagn\u00e9 de 100 autres \u00e9tudiants ! Apr\u00e8s une br\u00e8ve description de LIFES faite par le Secr\u00e9taire g\u00e9n\u00e9ral, ces 100 \u00e9tudiants se sont s\u00e9par\u00e9s en petits groupes et ont fait l&rsquo;exp\u00e9rience d&rsquo;une \u00e9tude biblique inductive dirig\u00e9e par des \u00e9tudiants. Au cours de la troisi\u00e8me journ\u00e9e, des \u00e9tudiants comme Emmanuel, qui avaient exprim\u00e9 le d\u00e9sir de servir en tant que leaders, se sont rassembl\u00e9s pour un premier de plusieurs autres ateliers de formation au leadership.<\/p>\n<ul>\n<li>Louez Dieu pour l&rsquo;audace des membres de ce mouvement cherchant \u00e0 implanter un groupe sur de nouveaux campus, ainsi que pour les portes ouvertes qu&rsquo;ils ont trouv\u00e9es \u00e0 l&rsquo;universit\u00e9.<\/li>\n<li>Priez pour Emmanuel et pour les autres 100 \u00e9tudiants, afin qu&rsquo;ils demeurent fid\u00e8les et se consacrent fid\u00e8lement \u00e0 l&rsquo;\u00e9vang\u00e9lisation, \u00e0 la formation de disciple, \u00e0 la pri\u00e8re et \u00e0 l&rsquo;\u00e9tude biblique.<\/li>\n<li>Priez pour les membres du personnel de LIFES qui parcourent de longues distances entre douze campus, le plus souvent sur de mauvaises routes. Priez pour leur s\u00e9curit\u00e9, pour leur t\u00e9nacit\u00e9 et leur efficacit\u00e9 dans le minist\u00e8re.<\/li>\n<li>Louez Dieu pour quatre nouveaux \u00e9quipiers qui se sont joints \u00e0 l&rsquo;\u00e9quipe de LIFES \u00e0 la fin de 2018. Priez pour Mo\u00efse, le Secr\u00e9taire g\u00e9n\u00e9ral, tandis qu&rsquo;il dirige cette petite \u00e9quipe.<\/li>\n<\/ul>\n<p>Merci de prier avec nous !<\/p>\n","protected":false},"featured_media":2179,"template":"","area":[950,1015],"theme":[1261],"class_list":["post-2328","prayerline","type-prayerline","status-publish","has-post-thumbnail","hentry","area-afrique-anglophone-et-lusophone","area-liberia-afrique-anglophone-et-lusophone","theme-travail-pionnier"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Que les portes s\u2019ouvrent pour un travail pionnier sur un nouveau campus &#183; IFES Prayerline<\/title>\n<meta name=\"description\" content=\"C&#039;\u00e9tait un plan ambitieux : d\u00e9marrer un nouveau groupe \u00e9tudiant sur un campus non atteint en une semaine avec une \u00e9quipe compos\u00e9e de 13 \u00e9tudiants,\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Que les portes s\u2019ouvrent pour un travail pionnier sur un nouveau campus &#183; IFES Prayerline\" \/>\n<meta property=\"og:description\" content=\"C&#039;\u00e9tait un plan ambitieux : d\u00e9marrer un nouveau groupe \u00e9tudiant sur un campus non atteint en une semaine avec une \u00e9quipe compos\u00e9e de 13 \u00e9tudiants,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/prayerline\/open-doors-for-planting-on-a-new-campus\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-24T11:53:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/190129-LIFES-Liberia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/open-doors-for-planting-on-a-new-campus\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/open-doors-for-planting-on-a-new-campus\\\/\",\"name\":\"Que les portes s\u2019ouvrent pour un travail pionnier sur un nouveau campus &#183; IFES Prayerline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/open-doors-for-planting-on-a-new-campus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/open-doors-for-planting-on-a-new-campus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/190129-LIFES-Liberia.jpg\",\"datePublished\":\"2019-01-29T14:00:00+00:00\",\"dateModified\":\"2019-05-24T11:53:40+00:00\",\"description\":\"C'\u00e9tait un plan ambitieux : d\u00e9marrer un nouveau groupe \u00e9tudiant sur un campus non atteint en une semaine avec une \u00e9quipe compos\u00e9e de 13 \u00e9tudiants,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/open-doors-for-planting-on-a-new-campus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/open-doors-for-planting-on-a-new-campus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/open-doors-for-planting-on-a-new-campus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/190129-LIFES-Liberia.jpg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/190129-LIFES-Liberia.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/open-doors-for-planting-on-a-new-campus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prayerline\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Que les portes s\u2019ouvrent pour un travail pionnier sur un nouveau campus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Que les portes s\u2019ouvrent pour un travail pionnier sur un nouveau campus &#183; IFES Prayerline","description":"C'\u00e9tait un plan ambitieux : d\u00e9marrer un nouveau groupe \u00e9tudiant sur un campus non atteint en une semaine avec une \u00e9quipe compos\u00e9e de 13 \u00e9tudiants,","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Que les portes s\u2019ouvrent pour un travail pionnier sur un nouveau campus &#183; IFES Prayerline","og_description":"C'\u00e9tait un plan ambitieux : d\u00e9marrer un nouveau groupe \u00e9tudiant sur un campus non atteint en une semaine avec une \u00e9quipe compos\u00e9e de 13 \u00e9tudiants,","og_url":"https:\/\/test.ifesworld.org\/en\/prayerline\/open-doors-for-planting-on-a-new-campus\/","og_site_name":"IFES","article_modified_time":"2019-05-24T11:53:40+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/190129-LIFES-Liberia.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/open-doors-for-planting-on-a-new-campus\/","url":"https:\/\/test.ifesworld.org\/en\/prayerline\/open-doors-for-planting-on-a-new-campus\/","name":"Que les portes s\u2019ouvrent pour un travail pionnier sur un nouveau campus &#183; IFES Prayerline","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/open-doors-for-planting-on-a-new-campus\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/open-doors-for-planting-on-a-new-campus\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/190129-LIFES-Liberia.jpg","datePublished":"2019-01-29T14:00:00+00:00","dateModified":"2019-05-24T11:53:40+00:00","description":"C'\u00e9tait un plan ambitieux : d\u00e9marrer un nouveau groupe \u00e9tudiant sur un campus non atteint en une semaine avec une \u00e9quipe compos\u00e9e de 13 \u00e9tudiants,","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/open-doors-for-planting-on-a-new-campus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/prayerline\/open-doors-for-planting-on-a-new-campus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/open-doors-for-planting-on-a-new-campus\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/190129-LIFES-Liberia.jpg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/190129-LIFES-Liberia.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/open-doors-for-planting-on-a-new-campus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Prayerline","item":"https:\/\/test.ifesworld.org\/en\/prayerline\/"},{"@type":"ListItem","position":3,"name":"Que les portes s\u2019ouvrent pour un travail pionnier sur un nouveau campus"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/prayerline\/2328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/prayerline"}],"about":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/types\/prayerline"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media\/2179"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media?parent=2328"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/area?post=2328"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/theme?post=2328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}