{"id":19454,"date":"2022-08-16T06:16:00","date_gmt":"2022-08-16T05:16:00","guid":{"rendered":"https:\/\/test.ifesworld.org\/?post_type=prayerline&#038;p=19454"},"modified":"2022-08-15T13:34:23","modified_gmt":"2022-08-15T12:34:23","slug":"neanmoins-dieu-est-a-loeuvre","status":"publish","type":"prayerline","link":"https:\/\/test.ifesworld.org\/fr\/prayerline\/neanmoins-dieu-est-a-loeuvre\/","title":{"rendered":"N\u00e9anmoins Dieu est \u00e0 l\u2019\u0153uvre"},"content":{"rendered":"<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Depuis le coup d\u2019\u00c9tat militaire survenu en f\u00e9vrier l&rsquo;ann\u00e9e pass\u00e9e, le peuple du Myanmar est victime d\u2019une violence g\u00e9n\u00e9ralis\u00e9e aux mains de la junte militaire. Le conflit arm\u00e9 a d\u00e9plac\u00e9 des milliers de personnes et,<a href=\"https:\/\/www.ohchr.org\/en\/statements\/2022\/06\/50th-session-human-rights-council-oral-update-myanmar\" target=\"_blank\" rel=\"noreferrer noopener\"> selon la Haut-Commissaire des Nations unies aux droits de l&rsquo;homme<\/a>, la nation demeure \u00ab\u202fpi\u00e9g\u00e9e dans un cycle de pauvret\u00e9, de d\u00e9placements, de violations des droits humains et d&rsquo;abus &#8230; La vie et l\u2019avenir du peuple de Myanmar sont en jeu.\u202f\u00bb&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Sawm est le Secr\u00e9taire g\u00e9n\u00e9ral du MFES, <a href=\"https:\/\/www.facebook.com\/Myanmar-Fellowship-of-Evangelical-Students-MFES-1709327376022006\/\" target=\"_blank\" rel=\"noreferrer noopener\">le mouvement \u00e9tudiant au Myanmar<\/a>. Il rapporte que la vie est toujours loin d\u2019\u00eatre stable, m\u00eame si les gens retournent au travail et que plus d&rsquo;une ann\u00e9e s\u2019est \u00e9coul\u00e9e depuis le coup d&rsquo;\u00c9tat qui a men\u00e9 \u00e0 la \u00ab\u202fr\u00e9volution du printemps\u202f\u00bb. \u00ab\u202fLes militaires arr\u00eatent les jeunes qui se trouvent dans le voisinage de toute attaque r\u00e9alis\u00e9e par la branche arm\u00e9e du Gouvernement fant\u00f4me d&rsquo;unit\u00e9 nationale, c\u2019est-\u00e0-dire les Forces populaires de d\u00e9fense (PDF) \u2013 m\u00eame si ces jeunes n\u2019\u00e9taient pas concern\u00e9s\u202f\u00bb, dit Sawm. \u00ab\u202fDans de nombreuses villes, les gens ont peur de sortir l\u2019apr\u00e8s-midi et les maisons restent dans l\u2019obscurit\u00e9 la nuit. Certains, dont m\u00eame des enfants en \u00e2ge d\u2019\u00eatre coll\u00e9giens, ne peuvent pas rester dans leur propre village car ils risquent d\u2019\u00eatre accus\u00e9s de participer \u00e0 la r\u00e9sistance arm\u00e9e. Les militaires arr\u00eatent tous ceux qu&rsquo;ils soup\u00e7onnent, sans preuves.\u202f\u00bb&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Les jeunes n\u2019ont pas beaucoup d\u2019options\u202f: comme le dit Sawm, soit ils \u00ab\u202frejoignent les PDF, [soit ils] trouvent un travail mal pay\u00e9 dans les usines des villes ou ils quittent le pays.\u202f\u00bb La violence et l\u2019injustice g\u00e9n\u00e9rales et incessantes \u2013 qui ont entra\u00een\u00e9 le meurtre de l\u2019un des voisins de Sawm \u2013 ont aussi profond\u00e9ment marqu\u00e9 les \u00e9tudiants. De nombreux \u00e9tudiants potentiels <a href=\"https:\/\/www.aljazeera.com\/news\/2021\/11\/3\/military-coup-kills-higher-education-dreams-in-myanmar\" target=\"_blank\" rel=\"noreferrer noopener\">ont rejoint des groupes de r\u00e9sistance arm\u00e9e <\/a>au lieu des universit\u00e9s. \u00ab\u202fLa semaine derni\u00e8re, dit Sawm, l&rsquo;un de nos \u00e9tudiants a disparu alors qu\u2019il se rendait au culte. Nous ne savons toujours pas exactement o\u00f9 il se trouve, mais il semblerait qu&rsquo;il ait \u00e9t\u00e9 pris par les militaires. La m\u00eame semaine, trois autres ont crois\u00e9 des voleurs sur le bus et ont perdu leur t\u00e9l\u00e9phone portable et leur sac.\u202f\u00bb&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Mais dans tout ce d\u00e9sarroi et cette souffrance, Dieu est \u00e0 l\u2019\u0153uvre et le minist\u00e8re \u00e9tudiant continue.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">\u00ab\u202fDieu a r\u00e9pondu \u00e0 nos pri\u00e8res et nous a donn\u00e9 un centre de minist\u00e8re, un lieu s\u00fbr et confortable qui nous permet de d\u00e9velopper des amiti\u00e9s et de partager l\u2019\u00c9vangile\u202f\u00bb, t\u00e9moigne Sawm. \u00ab\u202fNous avons commenc\u00e9 un nouveau club d\u2019anglais, en plus de notre \u00e9tude biblique et des rassemblements pour la communion fraternelle.\u202f\u00bb La vision du MFES se base sur le succ\u00e8s initial du centre de minist\u00e8re\u202f: \u00ab\u202fNous voulons cr\u00e9er un espace neutre pour tous les \u00e9tudiants, o\u00f9 nous pouvons les aider sur le plan p\u00e9dagogique et le plan \u00e9motionnel pendant cette p\u00e9riode de crise et o\u00f9 nous pouvons partager l\u2019\u00c9vangile. Nous avons vraiment besoin de pri\u00e8re, de conseils et d\u2019aide afin de d\u00e9velopper un minist\u00e8re pertinent, efficace et croissant, m\u00eame dans la situation pr\u00e9sente.\u202f\u00bb&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Malgr\u00e9 tout, le mouvement constate de la croissance. Sawm passa r\u00e9cemment trois jours \u00e0 rendre visite aux \u00e9tudiants d&rsquo;une ville \u00e0 l\u2019autre extr\u00e9mit\u00e9 du pays. \u00ab\u202fC\u2019\u00e9tait un grand privil\u00e8ge, dit-il, d\u2019expliquer l\u2019importance du minist\u00e8re \u00e9tudiant pour r\u00e9pandre l\u2019\u00c9vangile dans tout le Myanmar et voir des changements dans notre soci\u00e9t\u00e9. Ensemble, nous avons repens\u00e9 les possibilit\u00e9s pour un minist\u00e8re \u00e9tudiant efficace.\u202f\u00bb \u00c0 travers l\u2019\u00e9tude de Colossiens, le groupe de Sawm \u00ab\u202fest revenu sur la Seigneurie de J\u00e9sus dans tous les aspects de notre vie et nous avons pri\u00e9 que cette v\u00e9rit\u00e9 nous fa\u00e7onne pour devenir \u2018sel et lumi\u00e8re\u2019 dans ce monde tourment\u00e9.\u202f\u00bb&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Priez avec nous pour Sawm et les \u00e9tudiants du MFES :&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-list\">\n<ul class=\"wp-block-list\"><li>Sawm nous demande de \u00ab\u202fcontinuer \u00e0 prier que le Seigneur gu\u00e9risse bient\u00f4t notre pays effondr\u00e9.\u202f\u00bb\u00a0<\/li><li>Priez que le Seigneur accorde de la sagesse et de la force au MFES pour le servir efficacement.\u00a0\u00a0<\/li><li>Louez Dieu pour le centre de minist\u00e8re qu&rsquo;il a pourvu et continuez \u00e0 prier pour les finances du centre.\u00a0<\/li><li>Priez pour que l\u2019\u00e9tudiant du MFES qui a \u00e9t\u00e9 d\u00e9tenu par les militaires soit lib\u00e9r\u00e9 rapidement et qu\u2019il puisse retourner chez lui sain et sauf.\u00a0<\/li><\/ul>\n<\/div>","protected":false},"featured_media":19389,"template":"","area":[957,1162],"theme":[],"class_list":["post-19454","prayerline","type-prayerline","status-publish","has-post-thumbnail","hentry","area-asie-du-sud","area-myanmar-asie-du-sud"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00e9anmoins Dieu est \u00e0 l\u2019\u0153uvre &#183; IFES Prayerline<\/title>\n<meta name=\"description\" content=\"Depuis le coup d\u2019\u00c9tat militaire survenu en f\u00e9vrier l&#039;ann\u00e9e pass\u00e9e, le peuple du Myanmar est victime d\u2019une violence g\u00e9n\u00e9ralis\u00e9e aux mains de la junte\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00e9anmoins Dieu est \u00e0 l\u2019\u0153uvre &#183; IFES Prayerline\" \/>\n<meta property=\"og:description\" content=\"Depuis le coup d\u2019\u00c9tat militaire survenu en f\u00e9vrier l&#039;ann\u00e9e pass\u00e9e, le peuple du Myanmar est victime d\u2019une violence g\u00e9n\u00e9ralis\u00e9e aux mains de la junte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/prayerline\/nonetheless-god-is-moving\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2022\/08\/myanmar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1155\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/nonetheless-god-is-moving\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/nonetheless-god-is-moving\\\/\",\"name\":\"N\u00e9anmoins Dieu est \u00e0 l\u2019\u0153uvre &#183; IFES Prayerline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/nonetheless-god-is-moving\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/nonetheless-god-is-moving\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/myanmar.jpg\",\"datePublished\":\"2022-08-16T05:16:00+00:00\",\"description\":\"Depuis le coup d\u2019\u00c9tat militaire survenu en f\u00e9vrier l'ann\u00e9e pass\u00e9e, le peuple du Myanmar est victime d\u2019une violence g\u00e9n\u00e9ralis\u00e9e aux mains de la junte\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/nonetheless-god-is-moving\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/nonetheless-god-is-moving\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/nonetheless-god-is-moving\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/myanmar.jpg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/myanmar.jpg\",\"width\":2048,\"height\":1155},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/nonetheless-god-is-moving\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prayerline\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"N\u00e9anmoins Dieu est \u00e0 l\u2019\u0153uvre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00e9anmoins Dieu est \u00e0 l\u2019\u0153uvre &#183; IFES Prayerline","description":"Depuis le coup d\u2019\u00c9tat militaire survenu en f\u00e9vrier l'ann\u00e9e pass\u00e9e, le peuple du Myanmar est victime d\u2019une violence g\u00e9n\u00e9ralis\u00e9e aux mains de la junte","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"N\u00e9anmoins Dieu est \u00e0 l\u2019\u0153uvre &#183; IFES Prayerline","og_description":"Depuis le coup d\u2019\u00c9tat militaire survenu en f\u00e9vrier l'ann\u00e9e pass\u00e9e, le peuple du Myanmar est victime d\u2019une violence g\u00e9n\u00e9ralis\u00e9e aux mains de la junte","og_url":"https:\/\/test.ifesworld.org\/en\/prayerline\/nonetheless-god-is-moving\/","og_site_name":"IFES","og_image":[{"width":2048,"height":1155,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2022\/08\/myanmar.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/nonetheless-god-is-moving\/","url":"https:\/\/test.ifesworld.org\/en\/prayerline\/nonetheless-god-is-moving\/","name":"N\u00e9anmoins Dieu est \u00e0 l\u2019\u0153uvre &#183; IFES Prayerline","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/nonetheless-god-is-moving\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/nonetheless-god-is-moving\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2022\/08\/myanmar.jpg","datePublished":"2022-08-16T05:16:00+00:00","description":"Depuis le coup d\u2019\u00c9tat militaire survenu en f\u00e9vrier l'ann\u00e9e pass\u00e9e, le peuple du Myanmar est victime d\u2019une violence g\u00e9n\u00e9ralis\u00e9e aux mains de la junte","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/nonetheless-god-is-moving\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/prayerline\/nonetheless-god-is-moving\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/nonetheless-god-is-moving\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2022\/08\/myanmar.jpg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2022\/08\/myanmar.jpg","width":2048,"height":1155},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/nonetheless-god-is-moving\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Prayerline","item":"https:\/\/test.ifesworld.org\/en\/prayerline\/"},{"@type":"ListItem","position":3,"name":"N\u00e9anmoins Dieu est \u00e0 l\u2019\u0153uvre"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/prayerline\/19454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/prayerline"}],"about":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/types\/prayerline"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media\/19389"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media?parent=19454"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/area?post=19454"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/theme?post=19454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}