{"id":16214,"date":"2021-08-10T10:24:20","date_gmt":"2021-08-10T09:24:20","guid":{"rendered":"https:\/\/test.ifesworld.org\/?post_type=prayerline&#038;p=16214"},"modified":"2021-08-10T10:24:21","modified_gmt":"2021-08-10T09:24:21","slug":"sedifier-les-uns-les-autres-en-tant-que-pierres-vivantes","status":"publish","type":"prayerline","link":"https:\/\/test.ifesworld.org\/fr\/prayerline\/sedifier-les-uns-les-autres-en-tant-que-pierres-vivantes\/","title":{"rendered":"S\u2019\u00e9difier les uns les autres en tant que Pierres Vivantes"},"content":{"rendered":"<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Au cours des 12 derni\u00e8res ann\u00e9es, notre Union a \u00e9t\u00e9 guid\u00e9e par une vision commune appel\u00e9e Pierres Vivantes. Nous sommes reconnaissants \u00e0 Dieu pour les fa\u00e7ons dont nous l\u2019avons vu agir au cours de ces 12 ann\u00e9es pour faire grandir et soutenir les \u00e9tudiants et les mouvements nationaux.&nbsp;En 2008, nous \u00e9tions 136 mouvements dans 130 pays. Nous sommes maintenant 160 mouvements nationaux affili\u00e9s, avec un travail en cours dans plus de 180 pays. Nous nous sommes unis comme jamais auparavant pour poursuivre un objectif commun : atteindre l\u2019universit\u00e9 pour J\u00e9sus.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Pierres Vivantes nous a permis d\u2019avoir un langage commun pour parler du minist\u00e8re parmi les \u00e9tudiants. Il en est r\u00e9sult\u00e9 des initiatives telles que L\u2019Interaction avec les \u00c9critures, L\u2019Evang\u00e9lisation Cr\u00e9ative et Interagir avec l\u2019Universit\u00e9. Ces initiatives ont aid\u00e9 les \u00e9tudiants \u00e0 prendre le minist\u00e8re en main. Les \u00e9tudiants apprennent \u00e0 aborder les \u00c9critures par eux-m\u00eames. Ils r\u00e9fl\u00e9chissent \u00e0 la mani\u00e8re d\u2019atteindre leurs amis par une \u00e9vang\u00e9lisation cr\u00e9ative. Ils d\u00e9veloppent \u00e9galement leurs capacit\u00e9s de leadership et font face \u00e0 des questions culturelles difficiles. Avec l\u2019aide du Renforcement de la Gouvernance et du D\u00e9veloppement du Soutien au Niveau Local, les mouvements d\u00e9veloppent une gouvernance et un financement durables \u00e0 partir de partenariats locaux. Et avec D\u00e9fricher de nouveaux territoires, ils apportent l\u2019\u00e9vangile \u00e0 de nouveaux campus dans le monde entier.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">En r\u00e9sum\u00e9, Pierres Vivantes a aid\u00e9 notre Union \u00e0 construire et \u00e0 renforcer les bases solides du minist\u00e8re parmi les \u00e9tudiants. Maintenant, nous sommes impatients de voir comment ces bases aideront les mouvements \u00e0 prosp\u00e9rer dans une nouvelle saison. Nous finalisons actuellement notre prochaine strat\u00e9gie, qui refl\u00e8te les changements intervenus dans le contexte du minist\u00e8re au cours de la derni\u00e8re d\u00e9cennie, tout en restant fid\u00e8le aux valeurs et priorit\u00e9s essentielles de l\u2019IFES.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Alors que nous nous dirigeons vers cette nouvelle phase passionnante, nous avons vraiment besoin de pri\u00e8re. Cette semaine, joignez-vous \u00e0 nous pour louer Dieu pour les nombreuses fa\u00e7ons dont il a utilis\u00e9 Pierres Vivantes au cours des douze derni\u00e8res ann\u00e9es, et pour prier pour le d\u00e9veloppement de la vision de l\u2019Union.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-list\">\n<ul class=\"wp-block-list\"><li>Louons Dieu que Pierres Vivantes ait permis \u00e0 de nombreux mouvements de rester stables pendant la pand\u00e9mie.&nbsp;&nbsp;<\/li><li>Louons Dieu pour le travail fid\u00e8le de&nbsp;l\u2019\u00e9quipe&nbsp;du personnel dirigeant de l&rsquo;IFES. Ils se sont r\u00e9unis virtuellement pendant de nombreux mois pour \u00e9laborer la nouvelle strat\u00e9gie.&nbsp;&nbsp;<\/li><li>Prions pour la vision renouvel\u00e9e de l\u2019IFES, que Dieu b\u00e9nisse cette nouvelle saison et nous guide.&nbsp;&nbsp;<\/li><li>Prions pour que notre Union grandisse gr\u00e2ce \u00e0 la contribution de Pierres Vivantes et \u00e0 la nouvelle p\u00e9riode strat\u00e9gique.&nbsp;&nbsp;<\/li><\/ul>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\"><em>Pour lire notre rapport complet sur la c\u00e9l\u00e9bration de Pierres Vivantes,&nbsp;<\/em><a href=\"https:\/\/mcusercontent.com\/39dc49d0fe69777a6d2894521\/files\/91df2ce8-3879-d766-8d95-280a9bc20725\/Living_Stones_Report_UK.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><em>cliquez ici<\/em><\/a><em>.&nbsp;<\/em>&nbsp;<\/p>\n<\/div>","protected":false},"featured_media":16187,"template":"","area":[],"theme":[],"class_list":["post-16214","prayerline","type-prayerline","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u2019\u00e9difier les uns les autres en tant que Pierres Vivantes &#183; IFES Prayerline<\/title>\n<meta name=\"description\" content=\"Au cours des 12 derni\u00e8res ann\u00e9es, notre Union a \u00e9t\u00e9 guid\u00e9e par une vision commune appel\u00e9e Pierres Vivantes. Nous sommes reconnaissants \u00e0 Dieu pour les\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u2019\u00e9difier les uns les autres en tant que Pierres Vivantes &#183; IFES Prayerline\" \/>\n<meta property=\"og:description\" content=\"Au cours des 12 derni\u00e8res ann\u00e9es, notre Union a \u00e9t\u00e9 guid\u00e9e par une vision commune appel\u00e9e Pierres Vivantes. Nous sommes reconnaissants \u00e0 Dieu pour les\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/prayerline\/built-together-as-living-stones\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-10T09:24:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/08\/Capture-decran-2021-08-04-101027.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1390\" \/>\n\t<meta property=\"og:image:height\" content=\"921\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/built-together-as-living-stones\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/built-together-as-living-stones\\\/\",\"name\":\"S\u2019\u00e9difier les uns les autres en tant que Pierres Vivantes &#183; IFES Prayerline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/built-together-as-living-stones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/built-together-as-living-stones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Capture-decran-2021-08-04-101027.jpg\",\"datePublished\":\"2021-08-10T09:24:20+00:00\",\"dateModified\":\"2021-08-10T09:24:21+00:00\",\"description\":\"Au cours des 12 derni\u00e8res ann\u00e9es, notre Union a \u00e9t\u00e9 guid\u00e9e par une vision commune appel\u00e9e Pierres Vivantes. Nous sommes reconnaissants \u00e0 Dieu pour les\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/built-together-as-living-stones\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/built-together-as-living-stones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/built-together-as-living-stones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Capture-decran-2021-08-04-101027.jpg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Capture-decran-2021-08-04-101027.jpg\",\"width\":1390,\"height\":921},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/built-together-as-living-stones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prayerline\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u2019\u00e9difier les uns les autres en tant que Pierres Vivantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u2019\u00e9difier les uns les autres en tant que Pierres Vivantes &#183; IFES Prayerline","description":"Au cours des 12 derni\u00e8res ann\u00e9es, notre Union a \u00e9t\u00e9 guid\u00e9e par une vision commune appel\u00e9e Pierres Vivantes. Nous sommes reconnaissants \u00e0 Dieu pour les","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"S\u2019\u00e9difier les uns les autres en tant que Pierres Vivantes &#183; IFES Prayerline","og_description":"Au cours des 12 derni\u00e8res ann\u00e9es, notre Union a \u00e9t\u00e9 guid\u00e9e par une vision commune appel\u00e9e Pierres Vivantes. Nous sommes reconnaissants \u00e0 Dieu pour les","og_url":"https:\/\/test.ifesworld.org\/en\/prayerline\/built-together-as-living-stones\/","og_site_name":"IFES","article_modified_time":"2021-08-10T09:24:21+00:00","og_image":[{"width":1390,"height":921,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/08\/Capture-decran-2021-08-04-101027.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/built-together-as-living-stones\/","url":"https:\/\/test.ifesworld.org\/en\/prayerline\/built-together-as-living-stones\/","name":"S\u2019\u00e9difier les uns les autres en tant que Pierres Vivantes &#183; IFES Prayerline","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/built-together-as-living-stones\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/built-together-as-living-stones\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/08\/Capture-decran-2021-08-04-101027.jpg","datePublished":"2021-08-10T09:24:20+00:00","dateModified":"2021-08-10T09:24:21+00:00","description":"Au cours des 12 derni\u00e8res ann\u00e9es, notre Union a \u00e9t\u00e9 guid\u00e9e par une vision commune appel\u00e9e Pierres Vivantes. Nous sommes reconnaissants \u00e0 Dieu pour les","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/built-together-as-living-stones\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/prayerline\/built-together-as-living-stones\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/built-together-as-living-stones\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/08\/Capture-decran-2021-08-04-101027.jpg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/08\/Capture-decran-2021-08-04-101027.jpg","width":1390,"height":921},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/built-together-as-living-stones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Prayerline","item":"https:\/\/test.ifesworld.org\/en\/prayerline\/"},{"@type":"ListItem","position":3,"name":"S\u2019\u00e9difier les uns les autres en tant que Pierres Vivantes"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/prayerline\/16214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/prayerline"}],"about":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/types\/prayerline"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media\/16187"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media?parent=16214"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/area?post=16214"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/theme?post=16214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}