{"id":16096,"date":"2021-07-27T05:24:00","date_gmt":"2021-07-27T04:24:00","guid":{"rendered":"https:\/\/test.ifesworld.org\/?post_type=prayerline&#038;p=16096"},"modified":"2021-07-26T11:26:36","modified_gmt":"2021-07-26T10:26:36","slug":"voler-a-laveugle","status":"publish","type":"prayerline","link":"https:\/\/test.ifesworld.org\/fr\/prayerline\/voler-a-laveugle\/","title":{"rendered":"Voler \u00e0 l\u2019aveugle"},"content":{"rendered":"<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Le sol se r\u00e9tr\u00e9cit tandis que Finlay lan\u00e7ait l\u2019avion dans les airs. Il regarda les minuscules voitures se croiser \u00e0 travers le paysage n\u00e9o-z\u00e9landais, et comme toujours, son esprit erra vers des r\u00e9flexions existentielles. Il avait beaucoup de questions sur&nbsp;sa vie et le futur. En tant qu\u2019\u00e9tudiant en derni\u00e8re ann\u00e9e d\u2019aviation, il y avait tant d\u2019incertitude sur ce qu&rsquo;il allait faire par la ensuite. Mais il avait aussi d\u2019autres questions. Par exemple : quel \u00e9tait le but de la vie ? Est-ce que Dieu existait ?&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Il \u00e9tait las de ces questions. Pendant des ann\u00e9es, il les avait refoul\u00e9es dans sa t\u00eate, les ressassant encore et encore, sans r\u00e9ponse. \u00c0 pr\u00e9sent, avec sa remise de dipl\u00f4me qui se profilait, il se sentait d\u2019autant plus submerg\u00e9 par l\u2019inconnu.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Il trouva du r\u00e9confort en parlant avec une amie. Finlay remarqua qu\u2019elle participait au groupe du TSCF sur le campus et qu\u2019elle parlait toujours avec confiance de la mani\u00e8re dont sa foi influen\u00e7ait son avenir. Quand elle l\u2019invita \u00e0 son \u00e9glise, Finlay accepta. Bien qu\u2019il avait occasionnellement \u00e9t\u00e9 \u00e0 l\u2019\u00e9glise en tant qu\u2019enfant, Finlay \u00e9tait attir\u00e9 d\u2019une nouvelle mani\u00e8re par les enseignements de J\u00e9sus.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Durant la pand\u00e9mie, il retourna chez lui pour finir ses travaux universitaires, puis obtint son dipl\u00f4me. Tandis qu&rsquo;il menait sa vie dans sa ville natale, les paroles de l\u2019\u00c9criture continuaient \u00e0 r\u00e9sonner dans sa t\u00eate. Rapidement, Finlay se retrouva \u00e0 l\u2019\u00e9glise, o\u00f9 il commen\u00e7a \u00e0 marcher fid\u00e8lement avec J\u00e9sus. Il d\u00e9couvrit que sa foi en Dieu l\u2019aidait \u00e0 g\u00e9rer les incertitudes de la vie.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">En r\u00e9fl\u00e9chissant aujourd\u2019hui \u00e0 rejoindre l\u2019Air Force ou \u00e0 devenir instructeur de vol, Finlay est certain que Dieu va continuer \u00e0 le guider. Dans sa vie apr\u00e8s la remise de dipl\u00f4me, il marche par la foi en soumettant ses plans \u00e0 Dieu et en croyant qu\u2019il guidera son futur.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">L\u2019histoire de Finlay est commune parmi les \u00e9tudiants et les dipl\u00f4m\u00e9s, mais ce type de t\u00e9moignage s\u2019est amplifi\u00e9 cette ann\u00e9e avec les bouleversements que la pand\u00e9mie a provoqu\u00e9s. Les \u00e9tudiants ont besoin de savoir qu&rsquo;il y a un Dieu qui les aime et qui a un plan pour leur vie. Les groupes sur campus, tels que le TSCF, et les groupes de dipl\u00f4m\u00e9s de&nbsp;<a href=\"https:\/\/www.cross-current.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cross Current<\/a>&nbsp;conduisent les \u00e9tudiants vers l\u2019esp\u00e9rance. Cette semaine, priez avec nous pour les \u00e9tudiants dans le monde entier qui ont besoin d\u2019entendre le fait que Dieu est au contr\u00f4le.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-list\">\n<ul class=\"wp-block-list\"><li>Priez pour les \u00e9tudiants qui connaissent encore des perturbations dans leurs \u00e9tudes \u00e0 cause de la pand\u00e9mie. Nombre d\u2019entre eux ont vu leurs plans acad\u00e9miques retard\u00e9s ou annul\u00e9s. D\u2019autres sont frustr\u00e9s au quotidien par une mauvaise connexion.&nbsp;&nbsp;<\/li><li>Priez pour les dipl\u00f4m\u00e9s qui ne savent pas ce que l\u2019avenir leur r\u00e9serve. Priez qu&rsquo;ils trouvent une communaut\u00e9 chr\u00e9tienne alors qu\u2019ils entrent dans la prochaine saison de leur vie.&nbsp;<\/li><li>Priez pour les groupes, tels que le TSCF, qui continuent d\u2019atteindre et de soutenir les \u00e9tudiants comme Finlay, qui ont de grandes questions sur la vie.&nbsp;&nbsp;<\/li><\/ul>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">* Cette histoire a \u00e9t\u00e9 adapt\u00e9e sur base d\u2019une interview r\u00e9alis\u00e9e par le TSCF.&nbsp;<a href=\"https:\/\/www.tscf.org.nz\/story-of-change\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lisez l\u2019interview compl\u00e8te<\/a>&nbsp;pour en apprendre plus sur l\u2019histoire de Finlay.&nbsp;<\/p>\n<\/div>","protected":false},"featured_media":16095,"template":"","area":[1181,958],"theme":[],"class_list":["post-16096","prayerline","type-prayerline","status-publish","has-post-thumbnail","hentry","area-nouvelle-zelande","area-pacifique-sud"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voler \u00e0 l\u2019aveugle &#183; IFES Prayerline<\/title>\n<meta name=\"description\" content=\"Le sol se r\u00e9tr\u00e9cit tandis que Finlay lan\u00e7ait l\u2019avion dans les airs. Il regarda les minuscules voitures se croiser \u00e0 travers le paysage n\u00e9o-z\u00e9landais, et\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voler \u00e0 l\u2019aveugle &#183; IFES Prayerline\" \/>\n<meta property=\"og:description\" content=\"Le sol se r\u00e9tr\u00e9cit tandis que Finlay lan\u00e7ait l\u2019avion dans les airs. Il regarda les minuscules voitures se croiser \u00e0 travers le paysage n\u00e9o-z\u00e9landais, et\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/prayerline\/flying-blind\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/07\/South-Pac.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1083\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/flying-blind\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/flying-blind\\\/\",\"name\":\"Voler \u00e0 l\u2019aveugle &#183; IFES Prayerline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/flying-blind\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/flying-blind\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/South-Pac.jpeg\",\"datePublished\":\"2021-07-27T04:24:00+00:00\",\"description\":\"Le sol se r\u00e9tr\u00e9cit tandis que Finlay lan\u00e7ait l\u2019avion dans les airs. Il regarda les minuscules voitures se croiser \u00e0 travers le paysage n\u00e9o-z\u00e9landais, et\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/flying-blind\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/flying-blind\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/flying-blind\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/South-Pac.jpeg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/South-Pac.jpeg\",\"width\":1440,\"height\":1083},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/flying-blind\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prayerline\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Voler \u00e0 l\u2019aveugle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voler \u00e0 l\u2019aveugle &#183; IFES Prayerline","description":"Le sol se r\u00e9tr\u00e9cit tandis que Finlay lan\u00e7ait l\u2019avion dans les airs. Il regarda les minuscules voitures se croiser \u00e0 travers le paysage n\u00e9o-z\u00e9landais, et","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Voler \u00e0 l\u2019aveugle &#183; IFES Prayerline","og_description":"Le sol se r\u00e9tr\u00e9cit tandis que Finlay lan\u00e7ait l\u2019avion dans les airs. Il regarda les minuscules voitures se croiser \u00e0 travers le paysage n\u00e9o-z\u00e9landais, et","og_url":"https:\/\/test.ifesworld.org\/en\/prayerline\/flying-blind\/","og_site_name":"IFES","og_image":[{"width":1440,"height":1083,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/07\/South-Pac.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/flying-blind\/","url":"https:\/\/test.ifesworld.org\/en\/prayerline\/flying-blind\/","name":"Voler \u00e0 l\u2019aveugle &#183; IFES Prayerline","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/flying-blind\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/flying-blind\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/07\/South-Pac.jpeg","datePublished":"2021-07-27T04:24:00+00:00","description":"Le sol se r\u00e9tr\u00e9cit tandis que Finlay lan\u00e7ait l\u2019avion dans les airs. Il regarda les minuscules voitures se croiser \u00e0 travers le paysage n\u00e9o-z\u00e9landais, et","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/flying-blind\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/prayerline\/flying-blind\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/flying-blind\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/07\/South-Pac.jpeg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/07\/South-Pac.jpeg","width":1440,"height":1083},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/flying-blind\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Prayerline","item":"https:\/\/test.ifesworld.org\/en\/prayerline\/"},{"@type":"ListItem","position":3,"name":"Voler \u00e0 l\u2019aveugle"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/prayerline\/16096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/prayerline"}],"about":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/types\/prayerline"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media\/16095"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media?parent=16096"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/area?post=16096"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/theme?post=16096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}