{"id":841,"date":"2019-01-15T11:31:39","date_gmt":"2019-01-15T11:31:39","guid":{"rendered":"https:\/\/test.ifesworld.org\/conexion\/le-jour-ou-dieu-a-parle-via-google\/"},"modified":"2019-07-03T13:43:53","modified_gmt":"2019-07-03T13:43:53","slug":"le-jour-ou-dieu-a-parle-via-google","status":"publish","type":"conexion","link":"https:\/\/test.ifesworld.org\/fr\/blog\/le-jour-ou-dieu-a-parle-via-google\/","title":{"rendered":"Le jour o\u00f9 Dieu a parl\u00e9 via Google"},"content":{"rendered":"<p>Dans la barre de recherche Google, j\u2019ai saisi\u00a0: \u00ab\u00a0Tout m\u2019angoisse\u00a0\u00bb.<\/p>\n<p>J\u2019\u00e9tais \u00e0 quelques mois de d\u00e9crocher mon dipl\u00f4me, mais j\u2019avais atteint le point de rupture. Depuis le d\u00e9but de l\u2019adolescence, je souffrais de phobie sociale. J\u2019avais b\u00e9n\u00e9fici\u00e9 d\u2019un suivi th\u00e9rapeutique (qui m\u2019avait un peu aid\u00e9), qui m\u2019a donn\u00e9 le go\u00fbt de la psychologie. J\u2019ai donc choisi de faire des \u00e9tudes universitaires dans ce domaine. Je me disais que si j\u2019\u00e9tudiais le sujet, je pourrais me lib\u00e9rer de l\u2019anxi\u00e9t\u00e9 et un jour aider d\u2019autres personnes qui souffraient de ce probl\u00e8me. Mais pendant mes \u00e9tudes, les choses ont empir\u00e9. J\u2019en suis arriv\u00e9 au point o\u00f9 j\u2019\u00e9tais devenu incapable de m\u2019adresser aux gens ou de quitter mon appartement. J\u2019ai commenc\u00e9 \u00e0 paniquer parce que ma vie ne se d\u00e9roulait pas du tout comme l\u2019avais pr\u00e9vu. J\u2019ai tout fait pour essayer de me d\u00e9barrasser de mon probl\u00e8me, mais rien ne semblait marcher.<\/p>\n<p>J\u2019ai cherch\u00e9 des solutions partout. Un jour, je me suis demand\u00e9 ce que Google avait \u00e0 dire sur le sujet\u2026<\/p>\n<h4>Fascin\u00e9 par la\u00a0Bbible<\/h4>\n<p>Alors que je faisais d\u00e9filer les r\u00e9ponses Google, je suis tomb\u00e9 sur des paroles de la Bible\u00a0:<\/p>\n<blockquote><p>\u00ab\u00a0Ne vous inqui\u00e9tez de rien, mais en toute chose faites conna\u00eetre vos besoins \u00e0 Dieu par des pri\u00e8res et des supplications, dans une attitude de reconnaissance. Et la paix de Dieu, qui d\u00e9passe tout ce que l\u2019on peut comprendre, gardera votre c\u0153ur et vos pens\u00e9es en J\u00e9sus-Christ.\u00a0\u00bb Philippiens 4.6,7<\/p><\/blockquote>\n<p>Alors que je lisais ces mots, j\u2019ai senti que Dieu me parlait. Alors sans attendre, j\u2019ai pri\u00e9 en demandant \u00e0 Dieu de m\u2019aider.<\/p>\n<p>Contrairement \u00e0 ce \u00e0 quoi je m\u2019attendais, Dieu n\u2019a pas imm\u00e9diatement r\u00e9pondu \u00e0 ma pri\u00e8re, mais il a mis dans mon c\u0153ur un profond d\u00e9sir d\u2019\u00e9tudier la Bible. Mon dipl\u00f4me en poche, je passais six heures par jour \u00e0 lire des livres chr\u00e9tiens, \u00e0 \u00e9couter des messages et \u00e0 regarder des vid\u00e9os d\u2019enseignements. J\u2019\u00e9tais fascin\u00e9.<\/p>\n<figure class=\"wp-caption\"><img decoding=\"async\" src=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/d89b4-1ixk91rixq0rharrke8z6gg.jpeg\" data-width=\"1280\" data-height=\"720\" \/><figcaption class=\"wp-caption-text\"> by <a href=\"https:\/\/unsplash.com\/photos\/G-_L3Eqkqmc?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\" target=\"_blank\" rel=\"noopener noreferrer\">Hannah Busing<\/a> on\u00a0<a href=\"https:\/\/unsplash.com\/?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\" target=\"_blank\" rel=\"noopener noreferrer\">Unsplash<\/a><\/figcaption><\/figure>\n<h4>En qu\u00eate de\u00a0v\u00e9rit\u00e9<\/h4>\n<p>J\u2019avais grandi \u00e0 Malte dans une famille catholique, comme 98 % de la population. J\u2019\u00e9tais all\u00e9 \u00e0 la messe tous les dimanches et au cat\u00e9chisme chaque semaine, plus par obligation que par envie. J\u2019avais du mal \u00e0 ne pas m\u2019endormir pendant la messe, et j\u2019allais au cat\u00e9chisme surtout pour jouer au foot et voir mes amis. Je n\u2019ai jamais remis en cause mes croyances, mais j\u2019ai toujours eu l\u2019impression que quelque chose clochait.<\/p>\n<p>Quand j\u2019ai commenc\u00e9 \u00e0 lire la Bible par moi-m\u00eame, j\u2019ai d\u00e9couvert de nombreuses contradictions avec ce que l\u2019on m\u2019avait enseign\u00e9 enfant. Au d\u00e9but, c\u2019\u00e9tait tr\u00e8s difficile \u00e0 accepter. Je me suis rendu compte que l\u2019on m\u2019avait enseign\u00e9 des choses qui ne correspondaient pas \u00e0 ce que je lisais dans la Bible. Alors dans ma qu\u00eate de v\u00e9rit\u00e9, j\u2019ai d\u00e9cid\u00e9 d\u2019aller dans une \u00c9glise \u00e9vang\u00e9lique. Apr\u00e8s le culte, un des pasteurs m\u2019a parl\u00e9 de l\u2019\u00c9vangile. Ce jour-l\u00e0, j\u2019ai reconnu que j\u2019\u00e9tais p\u00e9cheur et accept\u00e9 J\u00e9sus-Christ comme mon Sauveur personnel. Dix mois plus tard, je suis pass\u00e9 par les eaux du bapt\u00eame.<\/p>\n<h4>Savoir en quoi je\u00a0crois<\/h4>\n<p>J\u2019ai eu du mal \u00e0 parler \u00e0 mes parents de ma nouvelle foi en J\u00e9sus. Au d\u00e9but je n\u2019ai rien dit parce que toute ma famille est catholique, et je savais qu\u2019ils n\u2019approuveraient pas. Mais au bout de quelques semaines, mes parents m\u2019ont vu avec un livre sur la Bible. J\u2019ai d\u00fb leur dire la v\u00e9rit\u00e9. \u00c7a ne s\u2019est pas tr\u00e8s bien pass\u00e9. Et aujourd\u2019hui, un an apr\u00e8s, c\u2019est encore tr\u00e8s difficile. Ils pensent que je fais partie d\u2019une secte, et que je g\u00e2che ma vie \u00e0 \u00e9tudier un livre sans valeur. Ils ne veulent pas \u00e9couter.<\/p>\n<p>La plupart de mes amis ne me parlent plus et ceux qui ont gard\u00e9 le contact me critiquent et essaient de me convaincre de revenir au catholicisme. Je ne suis pas vraiment surpris par leur r\u00e9action. \u00c0 Malte, la plupart des gens pensent que le christianisme \u00e9vang\u00e9lique est une secte. Ils ne savent pas vraiment ce dont parle la Bible. C\u2019\u00e9tait pareil pour moi. Avant, je ne savais pas vraiment ce que je croyais. J\u2019estimais que tout ce que les pr\u00eatres et les enseignants catholiques disaient \u00e9tait vrai. Aujourd\u2019hui, je fais en sorte de m\u2019assurer que ce que j\u2019entends et crois vient de la Bible et de savoir pourquoi je crois ce que je crois.<\/p>\n<figure class=\"wp-caption\"><img decoding=\"async\" src=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/7026c-1bydjbafheaixijwei9zjxq.jpeg\" data-width=\"1280\" data-height=\"720\" \/><figcaption class=\"wp-caption-text\"> by <a href=\"https:\/\/unsplash.com\/photos\/nHRjqkRIuTE?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\" target=\"_blank\" rel=\"noopener noreferrer\">Amy Velazquez<\/a> on\u00a0<a href=\"https:\/\/unsplash.com\/?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\" target=\"_blank\" rel=\"noopener noreferrer\">Unsplash<\/a><\/figcaption><\/figure>\n<h4>D\u00e9fis rencontr\u00e9s dans la vie de\u00a0disciple<\/h4>\n<p>En partageant l\u2019\u00c9vangile autour de moi, j\u2019ai constat\u00e9 que la plupart des gens pensent \u00eatre de bonnes personnes. Ils pensent qu\u2019ils iront au ciel parce qu\u2019ils font plus de bien que de mal. Bien que certains d\u2019entre eux n\u2019approuvent pas tout qui leur a \u00e9t\u00e9 enseign\u00e9, ils n\u2019envisagent pas de changer. Ils disent que c\u2019est comme \u00e7a qu\u2019ils ont \u00e9t\u00e9 \u00e9lev\u00e9s.<\/p>\n<p>Depuis que j\u2019ai donn\u00e9 ma vie \u00e0 J\u00e9sus, je continue \u00e0 lutter avec mes angoisses. Mais la situation s\u2019est beaucoup am\u00e9lior\u00e9e, et d\u00e9sormais, lorsque j\u2019ai des angoisses, je les apporte \u00e0 Dieu dans la pri\u00e8re. Il me r\u00e9conforte et m\u2019aide \u00e0 avancer. Une autre difficult\u00e9 consiste \u00e0 trouver un travail. La plupart des postes exigent de travailler le dimanche, ce qui m\u2019emp\u00eache d\u2019aller \u00e0 l\u2019\u00c9glise. Je souffre de la solitude, car \u00e0 Malte tr\u00e8s peu de personnes suivent J\u00e9sus, surtout dans ma tranche d\u2019\u00e2ge. Actuellement je n\u2019ai pas d\u2019amis proches, mais je passe beaucoup de temps avec Dieu et il me r\u00e9conforte dans ces moments difficiles.<\/p>\n<p>Je suis en train de pr\u00e9parer une ma\u00eetrise en th\u00e9ologie en ligne et j\u2019envisage de devenir pasteur ou \u00e9vang\u00e9liste \u00e0 plein temps \u00e0 l\u2019\u00e9tranger. Je ne sais pas si Dieu m\u2019appellera \u00e0 quitter Malte. Pour l\u2019instant, je suis engag\u00e9 dans mon \u00c9glise locale, et ma priorit\u00e9 est de la servir.<\/p>\n<figure><\/figure>\n","protected":false},"featured_media":1008,"template":"","area":[952,1072],"theme":[1259],"class_list":["post-841","conexion","type-conexion","status-publish","has-post-thumbnail","hentry","area-europe-2","area-malte","theme-mon-histoire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le jour o\u00f9 Dieu a parl\u00e9 via Google &#183; IFES Conexi\u00f3n Blog<\/title>\n<meta name=\"description\" content=\"Dans la barre de recherche Google, j\u2019ai saisi\u00a0: \u00ab\u00a0Tout m\u2019angoisse\u00a0\u00bb. J\u2019\u00e9tais \u00e0 quelques mois de d\u00e9crocher mon dipl\u00f4me, mais j\u2019avais atteint le point de\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le jour o\u00f9 Dieu a parl\u00e9 via Google &#183; IFES Conexi\u00f3n Blog\" \/>\n<meta property=\"og:description\" content=\"Dans la barre de recherche Google, j\u2019ai saisi\u00a0: \u00ab\u00a0Tout m\u2019angoisse\u00a0\u00bb. J\u2019\u00e9tais \u00e0 quelques mois de d\u00e9crocher mon dipl\u00f4me, mais j\u2019avais atteint le point de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-03T13:43:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/bb162-11b8es2k5z5ee97c0ok12pw.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/\",\"name\":\"Le jour o\u00f9 Dieu a parl\u00e9 via Google &#183; IFES Conexi\u00f3n Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/bb162-11b8es2k5z5ee97c0ok12pw.jpeg\",\"datePublished\":\"2019-01-15T11:31:39+00:00\",\"dateModified\":\"2019-07-03T13:43:53+00:00\",\"description\":\"Dans la barre de recherche Google, j\u2019ai saisi\u00a0: \u00ab\u00a0Tout m\u2019angoisse\u00a0\u00bb. J\u2019\u00e9tais \u00e0 quelques mois de d\u00e9crocher mon dipl\u00f4me, mais j\u2019avais atteint le point de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/bb162-11b8es2k5z5ee97c0ok12pw.jpeg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/bb162-11b8es2k5z5ee97c0ok12pw.jpeg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conexi\u00f3n\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le jour o\u00f9 Dieu a parl\u00e9 via Google\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le jour o\u00f9 Dieu a parl\u00e9 via Google &#183; IFES Conexi\u00f3n Blog","description":"Dans la barre de recherche Google, j\u2019ai saisi\u00a0: \u00ab\u00a0Tout m\u2019angoisse\u00a0\u00bb. J\u2019\u00e9tais \u00e0 quelques mois de d\u00e9crocher mon dipl\u00f4me, mais j\u2019avais atteint le point de","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Le jour o\u00f9 Dieu a parl\u00e9 via Google &#183; IFES Conexi\u00f3n Blog","og_description":"Dans la barre de recherche Google, j\u2019ai saisi\u00a0: \u00ab\u00a0Tout m\u2019angoisse\u00a0\u00bb. J\u2019\u00e9tais \u00e0 quelques mois de d\u00e9crocher mon dipl\u00f4me, mais j\u2019avais atteint le point de","og_url":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/","og_site_name":"IFES","article_modified_time":"2019-07-03T13:43:53+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/bb162-11b8es2k5z5ee97c0ok12pw.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/","url":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/","name":"Le jour o\u00f9 Dieu a parl\u00e9 via Google &#183; IFES Conexi\u00f3n Blog","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/bb162-11b8es2k5z5ee97c0ok12pw.jpeg","datePublished":"2019-01-15T11:31:39+00:00","dateModified":"2019-07-03T13:43:53+00:00","description":"Dans la barre de recherche Google, j\u2019ai saisi\u00a0: \u00ab\u00a0Tout m\u2019angoisse\u00a0\u00bb. J\u2019\u00e9tais \u00e0 quelques mois de d\u00e9crocher mon dipl\u00f4me, mais j\u2019avais atteint le point de","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/bb162-11b8es2k5z5ee97c0ok12pw.jpeg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/bb162-11b8es2k5z5ee97c0ok12pw.jpeg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Conexi\u00f3n","item":"https:\/\/test.ifesworld.org\/en\/blog\/"},{"@type":"ListItem","position":3,"name":"Le jour o\u00f9 Dieu a parl\u00e9 via Google"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/conexion\/841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/conexion"}],"about":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/types\/conexion"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media\/1008"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media?parent=841"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/area?post=841"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/theme?post=841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}