{"id":770,"date":"2017-07-06T09:01:01","date_gmt":"2017-07-06T08:01:01","guid":{"rendered":"https:\/\/test.ifesworld.org\/conexion\/refleter-le-caractere-de-dieu\/"},"modified":"2019-05-20T14:16:14","modified_gmt":"2019-05-20T14:16:14","slug":"refleter-le-caractere-de-dieu","status":"publish","type":"conexion","link":"https:\/\/test.ifesworld.org\/fr\/blog\/refleter-le-caractere-de-dieu\/","title":{"rendered":"Refl\u00e9ter le caract\u00e8re de Dieu"},"content":{"rendered":"<h4>Daniel Bourdann\u00e9<\/h4>\n<p>Le Dr Denis Mukwege est m\u00e9decin et il soigne les personnes qui ont \u00e9t\u00e9 victimes de viol. En tant que gyn\u00e9cologue r\u00e9put\u00e9, il pourrait vivre dans un pays occidental. Mais il a choisi de travailler dans un des endroits les plus difficiles de la R\u00e9publique d\u00e9mocratique du Congo. Dans une r\u00e9gion d\u00e9chir\u00e9e par la guerre et des ann\u00e9es de violences sexuelles, cet homme apporte des soins \u00e0 de milliers de femmes, dont plusieurs ont \u00e9t\u00e9 victimes de viols collectifs brutaux. Il sauve des vies gr\u00e2ce \u00e0 son expertise m\u00e9dicale, mais il est aussi un ardent d\u00e9fenseur de l\u2019\u00e9galit\u00e9 des sexes dans ce pays. Ce cher fr\u00e8re de la RDC est un dipl\u00f4m\u00e9 du mouvement \u00e9tudiant de l\u2019IFES, au Burundi, o\u00f9 il a effectu\u00e9 une partie de ses \u00e9tudes de m\u00e9decine. Il s\u2019est m\u00e9rit\u00e9, en 2013, le prix Sakharov attribu\u00e9 par l\u2019Union Europ\u00e9enne et il a fait partie des candidats retenus pour un prix Nobel en 2016. Il est pour moi un mod\u00e8le d\u2019engagement chr\u00e9tien au sein de la soci\u00e9t\u00e9. Il refl\u00e8te humblement le caract\u00e8re de Dieu au milieu de ces gens bris\u00e9s.<\/p>\n<p>Nous aussi sommes appel\u00e9s \u00e0 avoir un impact dans ce monde pour la gloire du Christ. Nous nous sentons peut-\u00eatre impuissants devant l\u2019opposition et les effets d\u00e9vastateurs du p\u00e9ch\u00e9. Que pouvons-nous faire, au juste? D\u2019un c\u00f4t\u00e9, il est \u00e9vident que <em>nous<\/em> ne pouvons pas changer le monde qui nous entoure. Mais Dieu le peut. Et il nous appelle \u00e0 devenir ses agents de transformation. Il nous faut nous montrer hardis et intentionnels dans l\u2019accomplissement de ce mandat parce que Dieu veut \u0153uvrer \u00e0 travers nous. Il nous appelle \u00e0 \u00eatre sel et lumi\u00e8re au sein de nos soci\u00e9t\u00e9s bris\u00e9es.<\/p>\n<blockquote><p>\u00ab\u00a0Ce que nous sommes, nous le devons \u00e0 Dieu; car par notre union avec J\u00e9sus-Christ, Dieu nous a cr\u00e9\u00e9s pour une vie riche d\u2019\u0153uvres bonnes qu\u2019il a pr\u00e9par\u00e9es \u00e0 l\u2019avance afin que nous les accomplissions.\u00a0\u00bb \u00c9ph\u00e9siens 2.10,\u00a0BDS<\/p><\/blockquote>\n<p>Dans un minist\u00e8re comme celui de l\u2019IFES, nous formons des communaut\u00e9s d\u2019hommes et de femmes de Dieu, et il veut \u0153uvrer \u00e0 travers nous pour renverser certaines cons\u00e9quences du p\u00e9ch\u00e9 dans ce monde. Je veux nous encourager \u00e0 nous percevoir nous-m\u00eames<\/p>\n<p>comme des instruments de Dieu en vue de la transformation des universit\u00e9s, des familles, des soci\u00e9t\u00e9s et des \u00c9glises locales.<\/p>\n<p>Nous devrions garder continuellement \u00e0 l\u2019esprit la vision d\u2019ensemble de la Cr\u00e9ation de Dieu. Depuis les origines, nous avons \u00e9t\u00e9 mandat\u00e9s par lui pour avoir un impact sur sa cr\u00e9ation. \u00c0 cause de notre p\u00e9ch\u00e9, la mise en \u0153uvre de ce mandat est devenue plus difficile. Mais laissons-nous renouveler int\u00e9rieurement par ce mandat biblique et mettons-nous au travail par la puissance du Saint-Esprit en vue d\u2019avoir un impact positif et salutaire sur notre monde bris\u00e9. Dieu nous a fait \u00e0 son image. Il veut que sa gloire soit reconnue et c\u00e9l\u00e9br\u00e9e. Il nous a fait le cadeau incroyable de sa gr\u00e2ce pour que nous puissions transformer ce monde bris\u00e9.<\/p>\n<p>C\u2019est pourquoi nous aspirons \u00e0 influencer la soci\u00e9t\u00e9, mais pas seulement en vue de voir une transformation sociale se produire, ce qui est certainement un des aspects de notre action. Nous cherchons plut\u00f4t \u00e0 promouvoir la justice, parce que nous aspirons \u00e0 voir davantage la justice de Dieu refl\u00e9t\u00e9e dans la soci\u00e9t\u00e9. Nous nous portons publiquement \u00e0 la d\u00e9fense des droits des individus parce que nous aspirons \u00e0 voir davantage le caract\u00e8re de Dieu refl\u00e9t\u00e9 au sein de nos communaut\u00e9s. Lorsque la d\u00e9ch\u00e9ance humaine entra\u00eene un niveau de pauvret\u00e9 qui prive de leur dignit\u00e9 des individus cr\u00e9\u00e9s \u00e0 l\u2019image de Dieu, cela nous bouleverse profond\u00e9ment et nous pousse \u00e0 nous battre pour am\u00e9liorer les conditions de vie de ces gens. Nous ne luttons pas dans le but d\u2019accumuler des richesses mat\u00e9rielles, mais plut\u00f4t pour d\u00e9fendre la dignit\u00e9 des femmes et des hommes cr\u00e9\u00e9s \u00e0 l\u2019image de Dieu, et pour honorer le Dieu que nous adorons. Il y a une motivation spirituelle \u00e0 la base de notre engagement, c\u2019est pourquoi nous faisons tout ce que nous pouvons pour refl\u00e9ter davantage le caract\u00e8re de Dieu.<\/p>\n<p>Pour faire cela, nous devons r\u00e9sister \u00e0 la tentation de demeurer fig\u00e9s dans nos propres bulles et nos ghettos. Nous devons passer hardiment et courageusement \u00e0 l\u2019action pour \u00eatre pr\u00e9sents dans le monde et explorer les moyens qui nous sont offerts de refl\u00e9ter le caract\u00e8re de Dieu, quel qu\u2019en soit le prix. Il nous faut faire cela dans l\u2019ar\u00e8ne politique, sur nos campus universitaires, au sein de nos familles et des communaut\u00e9s ravag\u00e9es par la guerre. Ces contextes peuvent \u00eatre, de par leur nature, d\u00e9concertants et dangereux, mais soyons encourag\u00e9s et dynamis\u00e9s par notre grand Dieu qui nous nous dit: ne craint pas. C\u2019est son amour et sa puissance que nous sommes appel\u00e9s \u00e0 offrir aux gens bris\u00e9s qui nous entourent.<\/p>\n<figure><img decoding=\"async\" src=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/47e07-1zwypi-mhv-q9vlp-hl1ljq.jpeg\" data-width=\"640\" data-height=\"107\" \/><\/figure>\n<p>Daniel Bourdann\u00e9, Juin 2017<\/p>\n","protected":false},"featured_media":910,"template":"","area":[],"theme":[],"class_list":["post-770","conexion","type-conexion","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Refl\u00e9ter le caract\u00e8re de Dieu &#183; IFES Conexi\u00f3n Blog<\/title>\n<meta name=\"description\" content=\"Daniel Bourdann\u00e9 Le Dr Denis Mukwege est m\u00e9decin et il soigne les personnes qui ont \u00e9t\u00e9 victimes de viol. En tant que gyn\u00e9cologue r\u00e9put\u00e9, il pourrait\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Refl\u00e9ter le caract\u00e8re de Dieu &#183; IFES Conexi\u00f3n Blog\" \/>\n<meta property=\"og:description\" content=\"Daniel Bourdann\u00e9 Le Dr Denis Mukwege est m\u00e9decin et il soigne les personnes qui ont \u00e9t\u00e9 victimes de viol. En tant que gyn\u00e9cologue r\u00e9put\u00e9, il pourrait\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/blog\/last-word-reflecting-gods-character\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T14:16:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/aa9d2-1wjxpmucx7cwjyc-rjn-7mw.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/last-word-reflecting-gods-character\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/last-word-reflecting-gods-character\\\/\",\"name\":\"Refl\u00e9ter le caract\u00e8re de Dieu &#183; IFES Conexi\u00f3n Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/last-word-reflecting-gods-character\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/last-word-reflecting-gods-character\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/aa9d2-1wjxpmucx7cwjyc-rjn-7mw.jpeg\",\"datePublished\":\"2017-07-06T08:01:01+00:00\",\"dateModified\":\"2019-05-20T14:16:14+00:00\",\"description\":\"Daniel Bourdann\u00e9 Le Dr Denis Mukwege est m\u00e9decin et il soigne les personnes qui ont \u00e9t\u00e9 victimes de viol. En tant que gyn\u00e9cologue r\u00e9put\u00e9, il pourrait\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/last-word-reflecting-gods-character\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/last-word-reflecting-gods-character\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/last-word-reflecting-gods-character\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/aa9d2-1wjxpmucx7cwjyc-rjn-7mw.jpeg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/aa9d2-1wjxpmucx7cwjyc-rjn-7mw.jpeg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/last-word-reflecting-gods-character\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conexi\u00f3n\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Refl\u00e9ter le caract\u00e8re de Dieu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Refl\u00e9ter le caract\u00e8re de Dieu &#183; IFES Conexi\u00f3n Blog","description":"Daniel Bourdann\u00e9 Le Dr Denis Mukwege est m\u00e9decin et il soigne les personnes qui ont \u00e9t\u00e9 victimes de viol. En tant que gyn\u00e9cologue r\u00e9put\u00e9, il pourrait","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Refl\u00e9ter le caract\u00e8re de Dieu &#183; IFES Conexi\u00f3n Blog","og_description":"Daniel Bourdann\u00e9 Le Dr Denis Mukwege est m\u00e9decin et il soigne les personnes qui ont \u00e9t\u00e9 victimes de viol. En tant que gyn\u00e9cologue r\u00e9put\u00e9, il pourrait","og_url":"https:\/\/test.ifesworld.org\/en\/blog\/last-word-reflecting-gods-character\/","og_site_name":"IFES","article_modified_time":"2019-05-20T14:16:14+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/aa9d2-1wjxpmucx7cwjyc-rjn-7mw.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/blog\/last-word-reflecting-gods-character\/","url":"https:\/\/test.ifesworld.org\/en\/blog\/last-word-reflecting-gods-character\/","name":"Refl\u00e9ter le caract\u00e8re de Dieu &#183; IFES Conexi\u00f3n Blog","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/last-word-reflecting-gods-character\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/last-word-reflecting-gods-character\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/aa9d2-1wjxpmucx7cwjyc-rjn-7mw.jpeg","datePublished":"2017-07-06T08:01:01+00:00","dateModified":"2019-05-20T14:16:14+00:00","description":"Daniel Bourdann\u00e9 Le Dr Denis Mukwege est m\u00e9decin et il soigne les personnes qui ont \u00e9t\u00e9 victimes de viol. En tant que gyn\u00e9cologue r\u00e9put\u00e9, il pourrait","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/last-word-reflecting-gods-character\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/blog\/last-word-reflecting-gods-character\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/blog\/last-word-reflecting-gods-character\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/aa9d2-1wjxpmucx7cwjyc-rjn-7mw.jpeg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/aa9d2-1wjxpmucx7cwjyc-rjn-7mw.jpeg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/blog\/last-word-reflecting-gods-character\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Conexi\u00f3n","item":"https:\/\/test.ifesworld.org\/en\/blog\/"},{"@type":"ListItem","position":3,"name":"Refl\u00e9ter le caract\u00e8re de Dieu"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/conexion\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/conexion"}],"about":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/types\/conexion"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media\/910"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media?parent=770"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/area?post=770"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/theme?post=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}