{"id":762,"date":"2017-06-01T14:01:46","date_gmt":"2017-06-01T13:01:46","guid":{"rendered":"https:\/\/test.ifesworld.org\/conexion\/graines-despoir-deurope-et-dailleurs\/"},"modified":"2019-05-20T14:27:03","modified_gmt":"2019-05-20T14:27:03","slug":"graines-despoir-deurope-et-dailleurs","status":"publish","type":"conexion","link":"https:\/\/test.ifesworld.org\/fr\/blog\/graines-despoir-deurope-et-dailleurs\/","title":{"rendered":"Graines d\u2019espoir d\u2019Europe et d\u2019ailleurs"},"content":{"rendered":"<h4>Daniel Bourdann\u00e9, Secr\u00e9taire g\u00e9n\u00e9ral de l\u2019IFES, a vu pendant plus d\u2019une d\u00e9cennie des \u00e9tudiants \u00e0 travers le monde partager la Bonne Nouvelle de J\u00e9sus avec leurs\u00a0amis.<\/h4>\n<p><em>Qu\u2019est-ce qui l\u2019a le plus encourag\u00e9 cette ann\u00e9e\u00a0? Il partage ses r\u00e9flexions avec Conexi\u00f3n.<\/em><\/p>\n<p>D\u2019embl\u00e9e, j\u2019aimerais dire que je suis encourag\u00e9 de voir la mani\u00e8re dont les \u00e9tudiants et les mouvements nationaux entendent l\u2019appel et r\u00e9pondent \u00e0 l\u2019urgent besoin de partager la Bonne Nouvelle de J\u00e9sus-Christ au sein des universit\u00e9s.<\/p>\n<p>Je pourrais mentionner la centaine et plus de semaines d\u2019\u00e9vang\u00e9lisation men\u00e9es par des groupes UCCF cette ann\u00e9e un peu partout en Grande-Bretagne et comment dans une universit\u00e9, il y a eu plus de 30 professions de foi\u00a0; ou encore vous parler de l\u2019impact du guide d\u2019\u00e9tude biblique d\u2019\u00e9vang\u00e9lisation de l\u2019UCCF, <em>Uncover<\/em>, qui a \u00e9t\u00e9 traduit et utilis\u00e9 par diff\u00e9rents mouvements de l\u2019IFES \u00e0 travers le monde. Je pourrais parler de l\u2019\u00e9nergie des 1350 \u00e9tudiants qui ont particip\u00e9 au congr\u00e8s de l\u2019IFES <em>Pr\u00e9sence<\/em> pour l\u2019Europe, et de leur ardent d\u00e9sir de voir leur continent transform\u00e9 par l\u2019\u00c9vangile. Je pourrais partager des nouvelles du pays tr\u00e8s s\u00e9culier qu\u2019est la Belgique, o\u00f9 des \u00e9tudiants ont men\u00e9 une semaine d\u2019\u00e9vang\u00e9lisation dans une ville en particulier ces deux derni\u00e8res ann\u00e9es sans aucun r\u00e9sultat tangible. Mais, cette ann\u00e9e-ci, ils ont refait l\u2019exp\u00e9rience dans la m\u00eame ville avec l\u2019appui des \u00c9glises locales et des \u00e9tudiants, lesquels ont pri\u00e9 24\/7 cette semaine-l\u00e0 et nous savons maintenant que quatre \u00e9tudiants ont re\u00e7u le Christ durant la semaine.<\/p>\n<p>Ce ne sont l\u00e0 que quelques histoires concernant l\u2019Europe. Je ne vous ai pas encore parl\u00e9 de l\u2019engagement et des initiatives des \u00e9tudiants du N\u00e9pal, o\u00f9 une \u00e9quipe de huit membres du personnel du NBCBS encadre et soutient le travail de 1300 groupes \u00e9tudiants. Ou de Sierra Leone, o\u00f9 le SLEFES souligne avec emphase l\u2019importance de sonder continuellement les \u00c9critures, tandis que les \u00e9tudiants partagent librement l\u2019\u00c9vangile de la gr\u00e2ce et de la paix\u00a0; 10 nouveaux groupes pionniers sur campus ont \u00e9t\u00e9 \u00e9tablis au cours de l\u2019ann\u00e9e \u00e9coul\u00e9e et de nombreux \u00e9tudiants mettent leur foi en Christ. Ou encore l\u2019engagement renouvel\u00e9 d\u2019InterVarsity\/USA en vue d\u2019\u00e9tablir de nouveaux groupes et de les voir grandir.<\/p>\n<p>Alors, bien s\u00fbr, je suis tr\u00e8s encourag\u00e9 par l\u2019\u00e9nergie d\u00e9ploy\u00e9e par nos mouvements dans l\u2019\u00e9vang\u00e9lisation. Des \u00e9tudiants invitent leurs amis \u00e0 conna\u00eetre J\u00e9sus. Ils veulent r\u00e9pandre l\u2019\u00c9vangile en parole et en action. Et Dieu est celui qui r\u00e9compense un tel travail. Il continue d\u2019amener les gens \u00e0 la foi.<\/p>\n<p>Toutefois, le minist\u00e8re parmi les \u00e9tudiant\u200a\u2014\u200ade par sa nature m\u00eame\u200a\u2014\u200ademeure toujours fragile. Les \u00e9tudiants sont l\u00e0 durant un temps, puis ils doivent quitter. Vous avez peut-\u00eatre un groupe d\u2019\u00e9tudiants actifs, remplis d\u2019\u00e9nergie pour r\u00e9pondre \u00e0 leur appel au sein de l\u2019universit\u00e9, mais au bout de trois ans, ils seront partis. Il y aura alors de nouveaux \u00e9tudiants avec qui partager votre vision \u00e0 partir de z\u00e9ro. Devant une telle fragilit\u00e9, il importe que le minist\u00e8re \u00e9tudiant soit soutenu au niveau national pour en assurer la continuit\u00e9. Ce n\u2019est qu\u2019en cultivant un fort sentiment de vision et de mission, et en ayant en place les structures de soutien appropri\u00e9es que nous pourrons relever ce d\u00e9fi.<\/p>\n<p>Je vois nos mouvements comme des arbres. Certaines ann\u00e9es, il arrive que le feuillage et les fruits ne soient pas selon les attentes, mais si l\u2019arbre est bien enracin\u00e9, il y aura toujours un potentiel de croissance nouvelle, d\u2019une vie nouvelle et d\u2019une r\u00e9colte abondante dans les ann\u00e9es qui vont suivre. Et les grains de ce fruit multiplieront la r\u00e9colte des ann\u00e9es \u00e0 venir.<\/p>\n<p>Pour les mouvements nationaux, la viabilit\u00e9 est assur\u00e9e par une bonne gouvernance et une bonne \u00e9quipe dirigeante. C\u2019est la raison pour laquelle je suis \u00e9galement encourag\u00e9 par notre projet international de formation \u00e0 la gouvernance [link]. J\u2019entends parler de conseils d\u2019administration nationaux qui comprennent l\u2019importance de leur contribution et qui sont d\u00e9termin\u00e9s \u00e0 assurer \u00e0 leur mouvement de telles racines solides. Je suis reconnaissant envers les mouvements nationaux qui reconnaissent le d\u00e9vouement incroyable de notre personnel et qui les soutiennent afin de servir Dieu de mani\u00e8re efficace.<\/p>\n<p>Finalement, je suis encourag\u00e9 lorsque je vois le travail miraculeux que Dieu op\u00e8re \u00e0 travers l\u2019IFES. Nous sommes si souvent expos\u00e9s \u00e0 des situations impr\u00e9vues\u00a0: il y a des endroits o\u00f9 nous n\u2019avions aucun espoir de voir des \u00e9tudiants se rencontrer librement et partager leur foi, alors que c\u2019est maintenant ce qui arrive, en d\u00e9pit du caract\u00e8re exigeant de tels contextes. C\u2019est v\u00e9ritablement l\u00e0 le travail de Dieu. Parfois, nous sommes expos\u00e9s \u00e0 des difficult\u00e9s et nous nous sentons d\u00e9courag\u00e9s. C\u2019est alors le moment de nous rappeler que Dieu est toujours \u00e0 l\u2019\u0153uvre et que nous n\u2019avons pas besoin de nous sentir abattus.<\/p>\n<p>Cela rel\u00e8ve du miracle pour moi de constater que plus de 160 mouvements ont choisi de faire partie de la communaut\u00e9 de l\u2019IFES. Ces mouvements ont choisi de tisser des liens par le moyen de l\u2019IFES, et malgr\u00e9 leurs diff\u00e9rences culturelles et th\u00e9ologiques in\u00e9vitables, ils continuent de se tenir par la main autour de J\u00e9sus en r\u00e9pondant \u00e0 son appel de servir au sein des universit\u00e9s et des coll\u00e8ges du monde entier. Je ne veux jamais tenir cela pour acquis dans notre monde actuel si fragment\u00e9. C\u2019est l\u00e0 une manifestation claire de la gr\u00e2ce de Dieu. Je vous invite \u00e0 prier avec moi que nous puissions continuer \u00e0 faire preuve de sagesse et d\u2019amour les uns envers les autres, en ne perdant jamais de vue l\u2019appel que nous avons re\u00e7u de Dieu de faire conna\u00eetre sa gr\u00e2ce transformatrice au sein des universit\u00e9s.<\/p>\n","protected":false},"featured_media":850,"template":"","area":[],"theme":[],"class_list":["post-762","conexion","type-conexion","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Graines d\u2019espoir d\u2019Europe et d\u2019ailleurs &#183; IFES Conexi\u00f3n Blog<\/title>\n<meta name=\"description\" content=\"Daniel Bourdann\u00e9, Secr\u00e9taire g\u00e9n\u00e9ral de l\u2019IFES, a vu pendant plus d\u2019une d\u00e9cennie des \u00e9tudiants \u00e0 travers le monde partager la Bonne Nouvelle de J\u00e9sus avec\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Graines d\u2019espoir d\u2019Europe et d\u2019ailleurs &#183; IFES Conexi\u00f3n Blog\" \/>\n<meta property=\"og:description\" content=\"Daniel Bourdann\u00e9, Secr\u00e9taire g\u00e9n\u00e9ral de l\u2019IFES, a vu pendant plus d\u2019une d\u00e9cennie des \u00e9tudiants \u00e0 travers le monde partager la Bonne Nouvelle de J\u00e9sus avec\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/blog\/seeds-of-lasting-hope-from-europe-and-beyond\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T14:27:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/f8ffc-1_yfrmaplrbg4hys8oxeh_g.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1081\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/seeds-of-lasting-hope-from-europe-and-beyond\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/seeds-of-lasting-hope-from-europe-and-beyond\\\/\",\"name\":\"Graines d\u2019espoir d\u2019Europe et d\u2019ailleurs &#183; IFES Conexi\u00f3n Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/seeds-of-lasting-hope-from-europe-and-beyond\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/seeds-of-lasting-hope-from-europe-and-beyond\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/f8ffc-1_yfrmaplrbg4hys8oxeh_g.jpeg\",\"datePublished\":\"2017-06-01T13:01:46+00:00\",\"dateModified\":\"2019-05-20T14:27:03+00:00\",\"description\":\"Daniel Bourdann\u00e9, Secr\u00e9taire g\u00e9n\u00e9ral de l\u2019IFES, a vu pendant plus d\u2019une d\u00e9cennie des \u00e9tudiants \u00e0 travers le monde partager la Bonne Nouvelle de J\u00e9sus avec\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/seeds-of-lasting-hope-from-europe-and-beyond\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/seeds-of-lasting-hope-from-europe-and-beyond\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/seeds-of-lasting-hope-from-europe-and-beyond\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/f8ffc-1_yfrmaplrbg4hys8oxeh_g.jpeg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/f8ffc-1_yfrmaplrbg4hys8oxeh_g.jpeg\",\"width\":1920,\"height\":1081},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/seeds-of-lasting-hope-from-europe-and-beyond\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conexi\u00f3n\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Graines d\u2019espoir d\u2019Europe et d\u2019ailleurs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Graines d\u2019espoir d\u2019Europe et d\u2019ailleurs &#183; IFES Conexi\u00f3n Blog","description":"Daniel Bourdann\u00e9, Secr\u00e9taire g\u00e9n\u00e9ral de l\u2019IFES, a vu pendant plus d\u2019une d\u00e9cennie des \u00e9tudiants \u00e0 travers le monde partager la Bonne Nouvelle de J\u00e9sus avec","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Graines d\u2019espoir d\u2019Europe et d\u2019ailleurs &#183; IFES Conexi\u00f3n Blog","og_description":"Daniel Bourdann\u00e9, Secr\u00e9taire g\u00e9n\u00e9ral de l\u2019IFES, a vu pendant plus d\u2019une d\u00e9cennie des \u00e9tudiants \u00e0 travers le monde partager la Bonne Nouvelle de J\u00e9sus avec","og_url":"https:\/\/test.ifesworld.org\/en\/blog\/seeds-of-lasting-hope-from-europe-and-beyond\/","og_site_name":"IFES","article_modified_time":"2019-05-20T14:27:03+00:00","og_image":[{"width":1920,"height":1081,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/f8ffc-1_yfrmaplrbg4hys8oxeh_g.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/blog\/seeds-of-lasting-hope-from-europe-and-beyond\/","url":"https:\/\/test.ifesworld.org\/en\/blog\/seeds-of-lasting-hope-from-europe-and-beyond\/","name":"Graines d\u2019espoir d\u2019Europe et d\u2019ailleurs &#183; IFES Conexi\u00f3n Blog","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/seeds-of-lasting-hope-from-europe-and-beyond\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/seeds-of-lasting-hope-from-europe-and-beyond\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/f8ffc-1_yfrmaplrbg4hys8oxeh_g.jpeg","datePublished":"2017-06-01T13:01:46+00:00","dateModified":"2019-05-20T14:27:03+00:00","description":"Daniel Bourdann\u00e9, Secr\u00e9taire g\u00e9n\u00e9ral de l\u2019IFES, a vu pendant plus d\u2019une d\u00e9cennie des \u00e9tudiants \u00e0 travers le monde partager la Bonne Nouvelle de J\u00e9sus avec","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/seeds-of-lasting-hope-from-europe-and-beyond\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/blog\/seeds-of-lasting-hope-from-europe-and-beyond\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/blog\/seeds-of-lasting-hope-from-europe-and-beyond\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/f8ffc-1_yfrmaplrbg4hys8oxeh_g.jpeg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/f8ffc-1_yfrmaplrbg4hys8oxeh_g.jpeg","width":1920,"height":1081},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/blog\/seeds-of-lasting-hope-from-europe-and-beyond\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Conexi\u00f3n","item":"https:\/\/test.ifesworld.org\/en\/blog\/"},{"@type":"ListItem","position":3,"name":"Graines d\u2019espoir d\u2019Europe et d\u2019ailleurs"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/conexion\/762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/conexion"}],"about":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/types\/conexion"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media\/850"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media?parent=762"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/area?post=762"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/theme?post=762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}