{"id":187,"date":"2018-06-26T15:47:15","date_gmt":"2018-06-26T14:47:15","guid":{"rendered":"https:\/\/test.ifesworld.org\/conexion\/a-vous-de-choisir\/"},"modified":"2019-07-03T14:26:51","modified_gmt":"2019-07-03T14:26:51","slug":"a-vous-de-choisir","status":"publish","type":"conexion","link":"https:\/\/test.ifesworld.org\/fr\/blog\/a-vous-de-choisir\/","title":{"rendered":"\u00c0 vous de choisir"},"content":{"rendered":"<p>L\u2019\u00e9t\u00e9 dernier, j\u2019ai termin\u00e9 mes \u00e9tudes. J\u2019ai obtenu mon dipl\u00f4me et me suis r\u00e9jouie de la fin de cette saison passionnante. En me rappelant les quatre ann\u00e9es que j\u2019avais pass\u00e9 \u00e0 l\u2019universit\u00e9, je me sentais satisfaite de ce que j\u2019avais accompli\u200a\u2014\u200atant de dissertations r\u00e9dig\u00e9es, d\u2019examens pass\u00e9s, de livres lus, d\u2019exp\u00e9riences acquises et d\u2019amiti\u00e9s forg\u00e9es.<\/p>\n<p>N\u00e9anmoins, au fond de moi, j\u2019avais le sentiment que j\u2019aurais pu tirer bien plus de ces ann\u00e9es. En effet, si je suis honn\u00eate, j\u2019ai toujours \u00e9t\u00e9 une \u00e9tudiante plut\u00f4t fain\u00e9ante. Je calculais l\u2019effort minimum qu\u2019il me fallait faire afin d\u2019obtenir de bonnes notes. Cette attitude est peut-\u00eatre due au fait qu\u2019en cours du chemin, j\u2019avais perdu l\u2019enthousiasme pour ma discipline. Peut-\u00eatre parce que je n\u2019ai jamais beaucoup aim\u00e9 r\u00e9diger des documents universitaires. Ou peut-\u00eatre \u00e9tait-ce parce que, tout au long de mes ann\u00e9es universitaires, j\u2019\u00e9tais impliqu\u00e9e dans un mouvement \u00e9tudiant chr\u00e9tien dynamique et palpitant et que je donnais souvent la priorit\u00e9 \u00e0 ces r\u00e9unions, camps ou autres activit\u00e9s au d\u00e9pit de mes \u00e9tudes. Quelle qu\u2019en soit la cause, je dois avouer que je ne me suis jamais donn\u00e9e \u00e0 cent pour cent \u00e0 mes \u00e9tudes. Je ne m\u2019int\u00e9ressais pas aux actualit\u00e9s du domaine que j\u2019\u00e9tudiais. J\u2019ai tout simplement \u00ab\u00a0subi\u00a0\u00bb mes \u00e9tudes sans enthousiasme.<\/p>\n<p>Depuis, j\u2019ai eu l\u2019occasion d\u2019y r\u00e9fl\u00e9chir encore.<\/p>\n<p>Dans l\u2019\u00e9p\u00eetre aux Colossiens, Paul dit\u00a0:<\/p>\n<blockquote><p>\u00ab\u00a0Car c\u2019est en [Christ] qu\u2019ont \u00e9t\u00e9 cr\u00e9\u00e9es toutes choses dans les cieux comme sur la terre, les visibles, les invisibles, les Tr\u00f4nes et les Seigneuries, les Autorit\u00e9s, les Puissances. C\u2019est par lui et pour lui que Dieu a tout cr\u00e9\u00e9. Il est lui-m\u00eame bien avant toutes choses et tout subsiste en lui.\u00a0\u00bb Colossiens 1\u00a0:16\u201317\u00a0BDS<\/p><\/blockquote>\n<p>Ce passage nous enseigne que toutes choses\u200a\u2014\u200ay compris la mati\u00e8re que nous \u00e9tudions\u200a\u2014\u200asont cr\u00e9\u00e9es et subsistent en Christ. Cela signifie que ce n\u2019est pas une perte de temps que d\u2019approfondir nos \u00e9tudes. Au contraire, en creusant plus dans notre domaine d\u2019\u00e9tude, nous sommes certains d\u2019y rencontrer Christ.<\/p>\n<p>Je remarque que, quand il s\u2019agit de la motivation pour les \u00e9tudes, les chr\u00e9tiens ont un discours qui ressemble souvent \u00e0 celui des non-croyants. En fait, c\u2019est souvent le contraire\u00a0: ce sont les disciples de Christ qui veulent une exp\u00e9rience universitaire aussi rapide et facile que possible, sans participer aux d\u00e9bats universitaires ou creuser plus loin dans leur domaine acad\u00e9mique que n\u00e9cessaire. Est-ce parce que l\u2019universit\u00e9 enseigne trop de choses \u00ab\u00a0non-chr\u00e9tiennes\u00a0\u00bb que nous pr\u00e9f\u00e9rons ne pas examiner afin de prot\u00e9ger notre mentalit\u00e9 chr\u00e9tienne\u00a0? Ou parce que nous ne nous int\u00e9ressons pas \u00e0 ce qui se passe dans le milieu universitaire et que nous avons des choses plus importants \u00e0 faire, telles qu\u2019un minist\u00e8re \u00e0 l\u2019\u00e9glise\u00a0? Cette fa\u00e7on de penser m\u2019est bien famili\u00e8re\u00a0: j\u2019ai longtemps \u00e9t\u00e9 ce genre d\u2019\u00e9tudiante.<\/p>\n<p>Mais quel est le v\u00e9ritable objectif des \u00e9tudes et quelle devrait en \u00eatre la motivation\u00a0? Pour les chr\u00e9tiens, il s\u2019agit de bien plus que d\u2019une simple \u00e9ducation. Nos \u00e9tudes nous permettent d\u2019en apprendre plus sur notre Cr\u00e9ateur et son histoire dans ce monde. Chaque discipline acad\u00e9mique d\u00e9montre \u00e0 sa fa\u00e7on le miracle de la cr\u00e9ation, les cons\u00e9quences tragiques de la chute et l\u2019esp\u00e9rance future pour la r\u00e9demption du monde. Par exemple, un \u00e9tudiant en m\u00e9decine peut voir combien merveilleux est le corps humain que Dieu a cr\u00e9\u00e9 et, en faisant des recherches sur des maladies graves, il d\u00e9couvrira combien ce monde a d\u00e9vi\u00e9 du plan \u00e9tabli par Dieu. Les \u00e9tudiants en ing\u00e9nierie ou en sciences peuvent apprendre \u00e0 conna\u00eetre Dieu, l\u2019ing\u00e9nieur Tout-Puissant. Les \u00e9tudiants en art d\u00e9couvrent l\u2019Auteur de toute cr\u00e9ativit\u00e9. Les physiciens, Celui qui a cr\u00e9\u00e9 et qui maintient l\u2019univers. Les enseignants stagiaires, la Source de toute sagesse et le plus grand enseignant, J\u00e9sus Christ. Les philologues, le Dieu qui a cr\u00e9\u00e9 le monde par sa Parole et qui affiche son histoire dans le Livre le plus influent de tous les temps.<\/p>\n<p>Et si Dieu nous avait plac\u00e9s \u00e0 l\u2019universit\u00e9 pour un dessein plus grand\u00a0? Et s\u2019il souhaitait que nous soyons d\u00e9vou\u00e9s \u00e0 nos \u00e9tudes, que nous arr\u00eations de nous tenir \u00e0 distance de ce qui nous semble indigne de notre attention en tant que chr\u00e9tiens et que nous commencions \u00e0 nous poser la question\u00a0: comment puis-je participer \u00e0 ce sujet et \u00eatre une b\u00e9n\u00e9diction\u00a0? Quels sont les besoins et les enjeux actuels dans le domaine des \u00e9tudes et dans mon universit\u00e9\u00a0? Comment puis-je rendre ce lieu plus juste\u00a0?<\/p>\n<p>Quel genre d\u2019\u00e9tudiant souhaitez-vous \u00eatre\u00a0? Un \u00e9tudiant qui se pr\u00e9cipite \u00e0 travers ses ann\u00e9es universitaires et qui touche \u00e0 peine le milieu dans lequel il \u00e9tudie parce qu\u2019il y a toujours plus de choses \u00ab\u00a0chr\u00e9tiennes\u00a0\u00bb qui demandent son attention\u00a0? Ou souhaitez-vous \u00eatre \u00e0 la fois 100% chr\u00e9tien ET 100% \u00e9tudiant\u00a0: un \u00e9tudiant qui ne manque pas une seule occasion de glorifier le Seigneur dans son cursus universitaire et d\u2019apporter la justice et la lumi\u00e8re dans le domaine qu\u2019il a choisi\u00a0? \u00c0 vous de choisir.<\/p>\n<p><strong>El\u012bna, travail social\u00a0; dipl\u00f4m\u00e9e de LKSB Lettonie<\/strong><\/p>\n<hr \/>\n<p>El\u012bna \u00e9tait l\u2019une des 22 participants pr\u00e9sents \u00e0 la consultation sur les Grands enjeux de l\u2019IFES qui a eu lieu en Allemagne en d\u00e9but d\u2019ann\u00e9e\u00a0; c\u2019est \u00e0 la suite de celle-ci qu\u2019elle a partag\u00e9 ces pens\u00e9es. En 2018, des consultations r\u00e9gionales sur les Grands enjeux ont eu lieu en Europe et en Am\u00e9rique latine. Organis\u00e9es en partenariat avec les mouvements locaux, ces consultations ont r\u00e9uni des personnes de diff\u00e9rents pays pour aborder et approfondir ensemble les enjeux auxquels les chr\u00e9tiens sont confront\u00e9s dans leurs universit\u00e9s.<\/p>\n<p>Le projet Grands enjeux au sein de l\u2019universit\u00e9 vise \u00e0 promouvoir le dialogue et l\u2019engagement th\u00e9ologique au sein du corps enseignant, chez les \u00e9tudiants et le personnel de l\u2019IFES, concernant les grandes questions rencontr\u00e9es dans nos universit\u00e9s. Lire la suite sur la page Interagir avec l\u2019Universit\u00e9 de notre site Internet.<\/p>\n<p>Le nouveau cours en ligne de l\u2019IFES, \u00ab\u00a0Interagir \u00e0 l\u2019universit\u00e9\u00a0: introduction\u00a0\u00bb explore ces questions \u00e0 l\u2019aide de citations, de lectures, de vid\u00e9os, de questionnaires et d\u2019exercices propices \u00e0 la r\u00e9flexion.<\/p>\n<p>Disponible en ao\u00fbt 2018. Places limit\u00e9es, inscrivez-vous avant le 15 juillet 2018. Pour vous inscrire ou en savoir plus, \u00e9crivez, \u00e0 <a href=\"mailto:engagingtheuni@test.ifesworld.org\" target=\"_blank\" rel=\"noopener noreferrer\">engagingtheuni@test.ifesworld.org<\/a><\/p>\n<p>Voici une courte <a href=\"https:\/\/www.youtube.com\/watch?v=RtDTsiyac58\" target=\"_blank\" rel=\"noopener noreferrer\">animation<\/a> pour vous aider \u00e0 r\u00e9fl\u00e9chir \u00e0 comment vous pourriez, en tant que chr\u00e9tien, interagir avec l\u2019universit\u00e9.<\/p>\n<figure><\/figure>\n","protected":false},"featured_media":961,"template":"","area":[952,1067],"theme":[1224,1252],"class_list":["post-187","conexion","type-conexion","status-publish","has-post-thumbnail","hentry","area-europe-2","area-lettonie","theme-interagir-avec-luniversite","theme-ministere-parmi-les-diplomes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c0 vous de choisir &#183; IFES Conexi\u00f3n Blog<\/title>\n<meta name=\"description\" content=\"L\u2019\u00e9t\u00e9 dernier, j\u2019ai termin\u00e9 mes \u00e9tudes. J\u2019ai obtenu mon dipl\u00f4me et me suis r\u00e9jouie de la fin de cette saison passionnante. En me rappelant les quatre\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 vous de choisir &#183; IFES Conexi\u00f3n Blog\" \/>\n<meta property=\"og:description\" content=\"L\u2019\u00e9t\u00e9 dernier, j\u2019ai termin\u00e9 mes \u00e9tudes. J\u2019ai obtenu mon dipl\u00f4me et me suis r\u00e9jouie de la fin de cette saison passionnante. En me rappelant les quatre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/blog\/the-choice-is-yours\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-03T14:26:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/7c33f-1mophed8sw4kaw5cese33lq.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-choice-is-yours\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-choice-is-yours\\\/\",\"name\":\"\u00c0 vous de choisir &#183; IFES Conexi\u00f3n Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-choice-is-yours\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-choice-is-yours\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/7c33f-1mophed8sw4kaw5cese33lq.jpeg\",\"datePublished\":\"2018-06-26T14:47:15+00:00\",\"dateModified\":\"2019-07-03T14:26:51+00:00\",\"description\":\"L\u2019\u00e9t\u00e9 dernier, j\u2019ai termin\u00e9 mes \u00e9tudes. J\u2019ai obtenu mon dipl\u00f4me et me suis r\u00e9jouie de la fin de cette saison passionnante. En me rappelant les quatre\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-choice-is-yours\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-choice-is-yours\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-choice-is-yours\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/7c33f-1mophed8sw4kaw5cese33lq.jpeg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/7c33f-1mophed8sw4kaw5cese33lq.jpeg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-choice-is-yours\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conexi\u00f3n\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c0 vous de choisir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c0 vous de choisir &#183; IFES Conexi\u00f3n Blog","description":"L\u2019\u00e9t\u00e9 dernier, j\u2019ai termin\u00e9 mes \u00e9tudes. J\u2019ai obtenu mon dipl\u00f4me et me suis r\u00e9jouie de la fin de cette saison passionnante. En me rappelant les quatre","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"\u00c0 vous de choisir &#183; IFES Conexi\u00f3n Blog","og_description":"L\u2019\u00e9t\u00e9 dernier, j\u2019ai termin\u00e9 mes \u00e9tudes. J\u2019ai obtenu mon dipl\u00f4me et me suis r\u00e9jouie de la fin de cette saison passionnante. En me rappelant les quatre","og_url":"https:\/\/test.ifesworld.org\/en\/blog\/the-choice-is-yours\/","og_site_name":"IFES","article_modified_time":"2019-07-03T14:26:51+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/7c33f-1mophed8sw4kaw5cese33lq.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-choice-is-yours\/","url":"https:\/\/test.ifesworld.org\/en\/blog\/the-choice-is-yours\/","name":"\u00c0 vous de choisir &#183; IFES Conexi\u00f3n Blog","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-choice-is-yours\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-choice-is-yours\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/7c33f-1mophed8sw4kaw5cese33lq.jpeg","datePublished":"2018-06-26T14:47:15+00:00","dateModified":"2019-07-03T14:26:51+00:00","description":"L\u2019\u00e9t\u00e9 dernier, j\u2019ai termin\u00e9 mes \u00e9tudes. J\u2019ai obtenu mon dipl\u00f4me et me suis r\u00e9jouie de la fin de cette saison passionnante. En me rappelant les quatre","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-choice-is-yours\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/blog\/the-choice-is-yours\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-choice-is-yours\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/7c33f-1mophed8sw4kaw5cese33lq.jpeg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/7c33f-1mophed8sw4kaw5cese33lq.jpeg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-choice-is-yours\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Conexi\u00f3n","item":"https:\/\/test.ifesworld.org\/en\/blog\/"},{"@type":"ListItem","position":3,"name":"\u00c0 vous de choisir"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/conexion\/187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/conexion"}],"about":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/types\/conexion"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media\/961"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/media?parent=187"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/area?post=187"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/fr\/wp-json\/wp\/v2\/theme?post=187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}