{"id":26298,"date":"2023-05-16T12:51:40","date_gmt":"2023-05-16T11:51:40","guid":{"rendered":"https:\/\/test.ifesworld.org\/?post_type=prayerline&#038;p=26298"},"modified":"2023-05-16T12:51:42","modified_gmt":"2023-05-16T11:51:42","slug":"adquirir-la-vision-del-ministerio-pionero","status":"publish","type":"prayerline","link":"https:\/\/test.ifesworld.org\/es\/prayerline\/adquirir-la-vision-del-ministerio-pionero\/","title":{"rendered":"Adquirir la visi\u00f3n del ministerio pionero\u00a0"},"content":{"rendered":"<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">\u201cDios ha puesto una carga en mi coraz\u00f3n por las personas de Micronesia\u201d, comparte Mark, un reci\u00e9n graduado de los Estados Federados de Micronesia (EFM). Cuando estaba estudiando fuera en Guam, surgi\u00f3 en \u00e9l la pasi\u00f3n de compartir el evangelio con los estudiantes. Ahora piensa en regresar a casa y Mark reflexiona y ora para saber si el ministerio estudiantil podr\u00eda formar parte de su futuro.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">\u201cMi visi\u00f3n para el ministerio estudiantil surgi\u00f3 simplemente de las conversaciones diarias con mis compa\u00f1eros micronesios de la residencia universitaria y de escuchar sus creencias sobre qui\u00e9n es Dios\u201d, explica. \u201cHe visto c\u00f3mo las pr\u00e1cticas religiosas y culturales de nuestra naci\u00f3n nos ha llevado muy lejos de saber qui\u00e9n es Dios realmente y esto ha provocado en m\u00ed un deseo de empezar un estudio b\u00edblico y de ense\u00f1arles qui\u00e9n es el Dios de la Biblia, el Dios viviente y verdadero\u201d.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Los Estados Federados de Micronesia est\u00e1n compuestos por m\u00e1s de 600 islas en el Pac\u00edfico Occidental. Aproximadamente un 95% de la poblaci\u00f3n se identifica como cristiano. Ir a la iglesia es algo normal. Pero Mark dice que para mucha gente su fe se basa en la tradici\u00f3n y en la cultura y no en la Biblia.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">\u201cMe ha animado mucho ver a los estudiantes que han venido a algunos de nuestros estudios b\u00edblicos y han escuchado historias de Jes\u00fas por primera vez, a pesar de llevar toda la vida asistiendo a la iglesia\u201d, dice.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Despu\u00e9s de mudarse a Guam para estudiar Administraci\u00f3n P\u00fablica, Mark empez\u00f3 a participar en el ministerio estudiantil pionero llevado por Sam, un obrero de <a href=\"https:\/\/link.intervarsity.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">InterVarsity Link<\/a>, de quien ya hablamos en un art\u00edculo anterior de <a href=\"https:\/\/test.ifesworld.org\/es\/prayerline\/dios-arruina-un-plan-perfecto\/\" target=\"_blank\" rel=\"noreferrer noopener\">Prayerline<\/a>.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-quote is-style-plain\">\n<blockquote class=\"wp-block-quote is-style-plain is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEstoy muy agradecido a Sam por venir hasta Guam y dirigir los estudios b\u00edblicos para los estudiantes del colegio universitario\u201d, dice Mark. \u201cMe anim\u00f3 mucho poder tener comuni\u00f3n con mis compa\u00f1eros que tambi\u00e9n son cristianos fieles\u201d.\u00a0<\/p><\/blockquote>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Mark empez\u00f3 a dirigir estudios b\u00edblicos en la residencia universitaria de la Universidad de Guam, donde viven m\u00e1s de 150 estudiantes de otras islas micronesias como EFM, Palau y las Islas Marshall. Despu\u00e9s de terminar un M\u00e1ster el a\u00f1o pasado, Mark decidi\u00f3 quedarse en Guam a trabajar y seguir de voluntario en el ministerio estudiantil. A medida que busca oportunidades para regresar a casa, Mark reflexiona sobre c\u00f3mo Dios podr\u00eda utilizar esta pasi\u00f3n y experiencia en el ministerio en el futuro en Pohnpei, la isla m\u00e1s grande y m\u00e1s poblada de EFM.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-quote is-style-plain\">\n<blockquote class=\"wp-block-quote is-style-plain is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEspero que Dios traiga a los Estados Federados de Micronesia obreros que sean j\u00f3venes y tengan pasi\u00f3n por compartir el evangelio entre los estudiantes. Si es su voluntad, ser\u00eda maravilloso que \u00c9l abriera puertas para que yo pueda trabajar en el ministerio estudiantil all\u00ed\u201d.\u00a0<\/p><\/blockquote>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Pero conociendo su pa\u00eds, Mark sabe que no ser\u00e1 f\u00e1cil.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">\u201cA veces es dif\u00edcil desafiar las creencias \u2018religiosas\u2019 tradicionales con las Escrituras porque puede parecer que estamos faltando al respeto a nuestros ancianos, nuestras tradiciones y nuestra cultura\u201d. A menudo hay una reacci\u00f3n en contra de los j\u00f3venes creyentes cuando hablan con valor de las verdades b\u00edblicas. Esto es algo que he experimentado yo mismo incluso.\u201d&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">EFM es uno de aproximadamente siete pa\u00edses o territorios en el Pac\u00edfico Sur que actualmente no tienen movimiento afiliado de IFES. Es complicado desarrollar un ministerio estudiantil en estas naciones isle\u00f1as remotas porque muchos grupos estudiantiles y campus universitarios est\u00e1n geogr\u00e1ficamente aislados unos de otros.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Adem\u00e1s, algunas de estas naciones del Pac\u00edfico no ofrecen carreras t\u00edpicas de cuatro a\u00f1os. EFM, por ejemplo, no tiene una universidad principal, sino un colegio universitario donde los estudiantes pueden estudiar durante dos a\u00f1os para despu\u00e9s terminar sus estudios en otra instituci\u00f3n en otro pa\u00eds o por internet. No obstante, IFES cree que las instituciones de educaci\u00f3n superior son lugares estrat\u00e9gicos para la misi\u00f3n. En algunas naciones esto puede significar que la obra se centra en las universidades, mientras que en otras puede ser en escuelas secundarias o colegios universitarios.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">\u201cEstos y otros factores hacen que la posibilidad de plantar un nuevo movimiento estudiantil en EFM sea un verdadero reto\u201d, cuenta David Walter, Secretario Regional de IFES para el Pac\u00edfico Sur. \u201cPero Dios es bueno\u201d.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Ora por Mark y por los estudiantes de los Estados Federados de Micronesia (tanto los que estudian all\u00ed como lo que son de all\u00ed):&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-list\">\n<ul class=\"wp-block-list\"><li>Ora para que Dios gu\u00ede a Mark y abra puertas a medida que explora oportunidades para el ministerio en el futuro en su isla natal de Pohnpei.&nbsp;<\/li><li>Ora para que los j\u00f3venes seguidores de Jes\u00fas tengan valor y sabidur\u00eda en EFM.&nbsp;<\/li><li>Ora para que el Se\u00f1or env\u00ede \u201cobreros a su cosecha\u201d, para que los estudiantes micronesios puedan escuchar las buenas nuevas de Jes\u00fas, ya sea en su propio pa\u00eds o mientras estudian en otros pa\u00edses.&nbsp;<\/li><\/ul>\n<\/div>","protected":false},"featured_media":26240,"template":"","area":[920,712],"theme":[],"class_list":["post-26298","prayerline","type-prayerline","status-publish","has-post-thumbnail","hentry","area-estados-federados-de-micronesia","area-pacifico-sur"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adquirir la visi\u00f3n del ministerio pionero\u00a0 &#183; IFES Prayerline<\/title>\n<meta name=\"description\" content=\"\u201cDios ha puesto una carga en mi coraz\u00f3n por las personas de Micronesia\u201d, comparte Mark, un reci\u00e9n graduado de los Estados Federados de Micronesia (EFM).\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adquirir la visi\u00f3n del ministerio pionero\u00a0 &#183; IFES Prayerline\" \/>\n<meta property=\"og:description\" content=\"\u201cDios ha puesto una carga en mi coraz\u00f3n por las personas de Micronesia\u201d, comparte Mark, un reci\u00e9n graduado de los Estados Federados de Micronesia (EFM).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/es\/prayerline\/adquirir-la-vision-del-ministerio-pionero\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-16T11:51:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2023\/05\/Mark-FSM1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/prayerline\\\/adquirir-la-vision-del-ministerio-pionero\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/prayerline\\\/adquirir-la-vision-del-ministerio-pionero\\\/\",\"name\":\"Adquirir la visi\u00f3n del ministerio pionero\u00a0 &#183; IFES Prayerline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/prayerline\\\/adquirir-la-vision-del-ministerio-pionero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/prayerline\\\/adquirir-la-vision-del-ministerio-pionero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Mark-FSM1-scaled.jpg\",\"datePublished\":\"2023-05-16T11:51:40+00:00\",\"dateModified\":\"2023-05-16T11:51:42+00:00\",\"description\":\"\u201cDios ha puesto una carga en mi coraz\u00f3n por las personas de Micronesia\u201d, comparte Mark, un reci\u00e9n graduado de los Estados Federados de Micronesia (EFM).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/prayerline\\\/adquirir-la-vision-del-ministerio-pionero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/prayerline\\\/adquirir-la-vision-del-ministerio-pionero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/prayerline\\\/adquirir-la-vision-del-ministerio-pionero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Mark-FSM1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Mark-FSM1-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/prayerline\\\/adquirir-la-vision-del-ministerio-pionero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prayerline\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adquirir la visi\u00f3n del ministerio pionero\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adquirir la visi\u00f3n del ministerio pionero\u00a0 &#183; IFES Prayerline","description":"\u201cDios ha puesto una carga en mi coraz\u00f3n por las personas de Micronesia\u201d, comparte Mark, un reci\u00e9n graduado de los Estados Federados de Micronesia (EFM).","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Adquirir la visi\u00f3n del ministerio pionero\u00a0 &#183; IFES Prayerline","og_description":"\u201cDios ha puesto una carga en mi coraz\u00f3n por las personas de Micronesia\u201d, comparte Mark, un reci\u00e9n graduado de los Estados Federados de Micronesia (EFM).","og_url":"https:\/\/test.ifesworld.org\/es\/prayerline\/adquirir-la-vision-del-ministerio-pionero\/","og_site_name":"IFES","article_modified_time":"2023-05-16T11:51:42+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2023\/05\/Mark-FSM1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/es\/prayerline\/adquirir-la-vision-del-ministerio-pionero\/","url":"https:\/\/test.ifesworld.org\/es\/prayerline\/adquirir-la-vision-del-ministerio-pionero\/","name":"Adquirir la visi\u00f3n del ministerio pionero\u00a0 &#183; IFES Prayerline","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/es\/prayerline\/adquirir-la-vision-del-ministerio-pionero\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/es\/prayerline\/adquirir-la-vision-del-ministerio-pionero\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2023\/05\/Mark-FSM1-scaled.jpg","datePublished":"2023-05-16T11:51:40+00:00","dateModified":"2023-05-16T11:51:42+00:00","description":"\u201cDios ha puesto una carga en mi coraz\u00f3n por las personas de Micronesia\u201d, comparte Mark, un reci\u00e9n graduado de los Estados Federados de Micronesia (EFM).","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/es\/prayerline\/adquirir-la-vision-del-ministerio-pionero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/es\/prayerline\/adquirir-la-vision-del-ministerio-pionero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.ifesworld.org\/es\/prayerline\/adquirir-la-vision-del-ministerio-pionero\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2023\/05\/Mark-FSM1-scaled.jpg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2023\/05\/Mark-FSM1-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/es\/prayerline\/adquirir-la-vision-del-ministerio-pionero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/es\/"},{"@type":"ListItem","position":2,"name":"Prayerline","item":"https:\/\/test.ifesworld.org\/en\/prayerline\/"},{"@type":"ListItem","position":3,"name":"Adquirir la visi\u00f3n del ministerio pionero\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/prayerline\/26298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/prayerline"}],"about":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/types\/prayerline"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/media\/26240"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/media?parent=26298"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/area?post=26298"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/theme?post=26298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}