{"id":16557,"date":"2021-09-21T04:29:00","date_gmt":"2021-09-21T03:29:00","guid":{"rendered":"https:\/\/test.ifesworld.org\/?post_type=prayerline&#038;p=16557"},"modified":"2021-09-16T16:30:56","modified_gmt":"2021-09-16T15:30:56","slug":"que-el-mundo-conozca","status":"publish","type":"prayerline","link":"https:\/\/test.ifesworld.org\/es\/prayerline\/que-el-mundo-conozca\/","title":{"rendered":"Que el mundo conozca"},"content":{"rendered":"<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Inspirar a los estudiantes para que amen las misiones es solo el principio. Despu\u00e9s, es cuesti\u00f3n de verlos usar sus pasiones y dones para tomar el control. Comisi\u00f3n, organizado por FOCUS Kenia, tiene como objetivo ser ese catalizador. Se trata de un congreso de misiones dise\u00f1ado para ayudar a estudiantes, graduados e iglesias a descubrir la misi\u00f3n de Dios y su responsabilidad en ella. Este congreso ha significado un tiempo de formaci\u00f3n para muchos estudiantes:<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-quote\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cEmpec\u00e9 en las misiones despu\u00e9s de mi experiencia durante el congreso Comisi\u00f3n. He ido de puerta en puerta para evangelizar a mis compa\u00f1eros del campus y a mis vecinos. Hasta el momento, diez personas se han comprometido a seguir a Cristo\u201d.<\/em> <\/p><cite><em>Ilenji, estudiante<\/em><\/cite><\/blockquote>\n<\/div>\n\n<div class=\"wp-block block-core-quote\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cEl congreso Comisi\u00f3n cambi\u00f3 mi vida y le estoy realmente agradecido a Dios. Pude descubrir el don que \u00c9l me ha dado. Tambi\u00e9n fue durante este congreso que me propuse apoyar a las misiones econ\u00f3micamente\u201d.<\/em><\/p><cite><em>Brian, estudiante<\/em><\/cite><\/blockquote>\n<\/div>\n\n<div class=\"wp-block block-core-quote\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cDesde Comisi\u00f3n, he ido compartiendo la palabra de Dios con mis compa\u00f1eros de clase y uno de ellos se ha unido a mi grupo de estudio b\u00edblico\u201d.<\/em> <\/p><cite><meta charset=\"utf-8\"><p>Abigail, estudiante<\/p><\/cite><\/blockquote>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">El 11\u00ba congreso Comisi\u00f3n tendr\u00e1 lugar este a\u00f1o desde el 30 de octubre hasta el 14 de noviembre. M\u00e1s de 5000 delegados de Kenia y otros pa\u00edses se reunir\u00e1n para hablar acerca de la evangelizaci\u00f3n como estilo de vida, de las misiones integrales y de c\u00f3mo apoyar la obra misionera a trav\u00e9s de las oraciones y las finanzas. De este congreso saldr\u00e1n iniciativas robustas de evangelizaci\u00f3n organizadas por estudiantes y dirigidas a sus compa\u00f1eros de campus. En congresos anteriores, Dios tambi\u00e9n llam\u00f3 a algunos delegados a que oraran, apoyaran o sirvieran a grupos espec\u00edficos todav\u00eda sin alcanzar.<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Los organizadores esperan que este a\u00f1o contin\u00fae el poderoso legado de estudiantes que experimentan el coraz\u00f3n de Dios para las misiones. Debido a que, este a\u00f1o, el evento ser\u00e1 principalmente en l\u00ednea, existe la oportunidad de que participen m\u00e1s personas de fuera de Kenia. \u00bfQuieres unirte a ellos? <a href=\"https:\/\/conferences.focuskenya.org\/\">Descubrir m\u00e1s<\/a>.<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">\u00bfOrar\u00e1s con nosotros por este evento?<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-list\">\n<ul class=\"wp-block-list\"><li>Ora para que Dios levante a muchos delegados a fin de llevar la carga de alcanzar a otros con el evangelio.<\/li><li>Ora por gracia, fortaleza y sabidur\u00eda para el equipo de planificaci\u00f3n.<\/li><li>Ora para que todos los ponentes oigan claramente la voz de Dios mientras preparan sus aportaciones para el congreso.<\/li><li>Pide a Dios que provea recursos, materiales y herramientas para que este congreso sea todo un \u00e9xito.<\/li><\/ul>\n<\/div>","protected":false},"featured_media":16551,"template":"","area":[704,765],"theme":[],"class_list":["post-16557","prayerline","type-prayerline","status-publish","has-post-thumbnail","hentry","area-africa-anglofona-y-lusofona","area-kenia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Que el mundo conozca &#183; IFES Prayerline<\/title>\n<meta name=\"description\" content=\"Inspirar a los estudiantes para que amen las misiones es solo el principio. Despu\u00e9s, es cuesti\u00f3n de verlos usar sus pasiones y dones para tomar el\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Que el mundo conozca &#183; IFES Prayerline\" \/>\n<meta property=\"og:description\" content=\"Inspirar a los estudiantes para que amen las misiones es solo el principio. Despu\u00e9s, es cuesti\u00f3n de verlos usar sus pasiones y dones para tomar el\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/prayerline\/that-the-world-may-know\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/09\/210920-Kenya.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/that-the-world-may-know\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/that-the-world-may-know\\\/\",\"name\":\"Que el mundo conozca &#183; IFES Prayerline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/that-the-world-may-know\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/that-the-world-may-know\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/210920-Kenya.jpg\",\"datePublished\":\"2021-09-21T03:29:00+00:00\",\"description\":\"Inspirar a los estudiantes para que amen las misiones es solo el principio. Despu\u00e9s, es cuesti\u00f3n de verlos usar sus pasiones y dones para tomar el\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/that-the-world-may-know\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/that-the-world-may-know\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/that-the-world-may-know\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/210920-Kenya.jpg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/210920-Kenya.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/that-the-world-may-know\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prayerline\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Que el mundo conozca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Que el mundo conozca &#183; IFES Prayerline","description":"Inspirar a los estudiantes para que amen las misiones es solo el principio. Despu\u00e9s, es cuesti\u00f3n de verlos usar sus pasiones y dones para tomar el","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Que el mundo conozca &#183; IFES Prayerline","og_description":"Inspirar a los estudiantes para que amen las misiones es solo el principio. Despu\u00e9s, es cuesti\u00f3n de verlos usar sus pasiones y dones para tomar el","og_url":"https:\/\/test.ifesworld.org\/en\/prayerline\/that-the-world-may-know\/","og_site_name":"IFES","og_image":[{"width":1920,"height":1280,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/09\/210920-Kenya.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/that-the-world-may-know\/","url":"https:\/\/test.ifesworld.org\/en\/prayerline\/that-the-world-may-know\/","name":"Que el mundo conozca &#183; IFES Prayerline","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/that-the-world-may-know\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/that-the-world-may-know\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/09\/210920-Kenya.jpg","datePublished":"2021-09-21T03:29:00+00:00","description":"Inspirar a los estudiantes para que amen las misiones es solo el principio. Despu\u00e9s, es cuesti\u00f3n de verlos usar sus pasiones y dones para tomar el","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/that-the-world-may-know\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/prayerline\/that-the-world-may-know\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/that-the-world-may-know\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/09\/210920-Kenya.jpg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/09\/210920-Kenya.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/that-the-world-may-know\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/es\/"},{"@type":"ListItem","position":2,"name":"Prayerline","item":"https:\/\/test.ifesworld.org\/en\/prayerline\/"},{"@type":"ListItem","position":3,"name":"Que el mundo conozca"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/prayerline\/16557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/prayerline"}],"about":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/types\/prayerline"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/media\/16551"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/media?parent=16557"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/area?post=16557"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/theme?post=16557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}