{"id":14503,"date":"2020-12-08T05:14:00","date_gmt":"2020-12-08T05:14:00","guid":{"rendered":"https:\/\/test.ifesworld.org\/?post_type=prayerline&#038;p=14503"},"modified":"2020-12-07T16:15:01","modified_gmt":"2020-12-07T16:15:01","slug":"salir-de-la-zona-de-confort","status":"publish","type":"prayerline","link":"https:\/\/test.ifesworld.org\/es\/prayerline\/salir-de-la-zona-de-confort\/","title":{"rendered":"Salir de la zona de confort"},"content":{"rendered":"<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Todo empez\u00f3 con la oraci\u00f3n. Sobre una mesita en el centro de estudiantes de la Universidad de Houston, Hannah Chang y Elizabeth Barrera inclinaron la cabeza juntas, pidiendo a Dios que las guiara hacia los estudiantes adecuados.<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Hannah, l\u00edder estudiantil de InterVarsity USA, sent\u00eda carga por los estudiantes latinos. Recientemente se enter\u00f3 de que constitu\u00edan el 32&nbsp;% del cuerpo estudiantil. Sin embargo, sus grupos de estudiantes de InterVarsity no reflejaban esto. Le pidi\u00f3 a Elizabeth, coordinadora ministerial de una regi\u00f3n cercana, que le diera consejos sobre c\u00f3mo llegar a estos estudiantes. Elizabeth sugiri\u00f3 que primero hicieran una caminata de oraci\u00f3n por el centro de estudiantes.<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Su caminata de oraci\u00f3n los llev\u00f3 a Edith y Milagros. Despu\u00e9s de entablar conversaci\u00f3n, Hannah vio que se estaban inscribiendo en citas de asesoramiento acad\u00e9mico. Hannah dice que este peque\u00f1o detalle dio lugar a una conversaci\u00f3n con un gran resultado.<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-quote is-style-default\">\n<blockquote class=\"wp-block-quote is-style-default is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cDurante el resto de la conversaci\u00f3n, me estuvieron haciendo preguntas sobre la mejor manera de conseguir citas de asesoramiento. En ese momento, me di cuenta de que generar confianza no solo significa hablar del evangelio. Significa vivir el Evangelio conociendo a las personas en sus lugares y viendo c\u00f3mo podemos convivir. Al final de la conversaci\u00f3n, las invit\u00e9 a almorzar conmigo el lunes siguiente, y ambas accedieron. En el almuerzo, les pregunt\u00e9 si estar\u00edan dispuestas a hacer un estudio b\u00edblico conmigo el viernes, \u00a1y volvieron a aceptar!\u201d.<\/em><\/p><\/blockquote>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Hannah es una estudiante asi\u00e1ticoamericana que dice que sab\u00eda poco sobre la cultura latina antes de conocer a Edith y Milagros. Explic\u00f3 que inicialmente se sent\u00eda nerviosa por invitarlas a un estudio b\u00edblico, pero sab\u00eda que Dios la estaba guiando.<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Ha seguido conociendo e invitando a m\u00e1s estudiantes latinos a su estudio b\u00edblico. Dice que el cruce cultural no tiene por qu\u00e9 dar miedo. M\u00e1s bien ha descubierto que la mejor manera de aprender sobre otra cultura es simplemente haciendo amigos.<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-quote is-style-default\">\n<blockquote class=\"wp-block-quote is-style-default is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cMientras continuaba construyendo relaciones con los estudiantes latinos, segu\u00ed aprendiendo m\u00e1s sobre sus familias, sus tradiciones y sus historias. El cruce cultural es dif\u00edcil, pero nos perdemos mucho si elegimos quedarnos solo con nuestros propios grupos \u00e9tnicos. Dios ha creado diferentes culturas y etnias, y las ama a todas. Buscar la comunidad cristiana a trav\u00e9s de las l\u00edneas raciales nos permite ver partes de Dios que no siempre vemos en la nuestra\u201d.<\/em><\/p><\/blockquote>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Esta semana, alabemos a Dios por la hermosa y diversa iglesia que ha creado y oremos por los estudiantes que se est\u00e1n aventurando fuera de su propia cultura para alcanzar a otros.<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-list\">\n<ul class=\"wp-block-list\"><li>Ora para que los estudiantes se den cuenta de la necesidad de acercarse a diversos grupos y culturas en sus campus.<\/li><li>Ora para que los estudiantes tengan el valor de ir m\u00e1s all\u00e1 de sus propias burbujas culturales y para que se acerquen a nuevas culturas con un esp\u00edritu de aprendizaje.<\/li><li>Ora por los grupos de estudiantes no alcanzados en los campus de todo el mundo. Ora para que est\u00e9n abiertos a la amistad con los estudiantes de IFES que se preocupan por ellos.<\/li><\/ul>\n<\/div>","protected":false},"featured_media":14490,"template":"","area":[710,907],"theme":[],"class_list":["post-14503","prayerline","type-prayerline","status-publish","has-post-thumbnail","hentry","area-america-del-norte","area-estados-unidos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salir de la zona de confort &#183; IFES Prayerline<\/title>\n<meta name=\"description\" content=\"Todo empez\u00f3 con la oraci\u00f3n. Sobre una mesita en el centro de estudiantes de la Universidad de Houston, Hannah Chang y Elizabeth Barrera inclinaron la\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salir de la zona de confort &#183; IFES Prayerline\" \/>\n<meta property=\"og:description\" content=\"Todo empez\u00f3 con la oraci\u00f3n. Sobre una mesita en el centro de estudiantes de la Universidad de Houston, Hannah Chang y Elizabeth Barrera inclinaron la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/prayerline\/stepping-out\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2020\/12\/prayerlineLaFe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/stepping-out\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/stepping-out\\\/\",\"name\":\"Salir de la zona de confort &#183; IFES Prayerline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/stepping-out\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/stepping-out\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/prayerlineLaFe.jpg\",\"datePublished\":\"2020-12-08T05:14:00+00:00\",\"description\":\"Todo empez\u00f3 con la oraci\u00f3n. Sobre una mesita en el centro de estudiantes de la Universidad de Houston, Hannah Chang y Elizabeth Barrera inclinaron la\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/stepping-out\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/stepping-out\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/stepping-out\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/prayerlineLaFe.jpg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/prayerlineLaFe.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/stepping-out\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prayerline\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/prayerline\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Salir de la zona de confort\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salir de la zona de confort &#183; IFES Prayerline","description":"Todo empez\u00f3 con la oraci\u00f3n. Sobre una mesita en el centro de estudiantes de la Universidad de Houston, Hannah Chang y Elizabeth Barrera inclinaron la","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Salir de la zona de confort &#183; IFES Prayerline","og_description":"Todo empez\u00f3 con la oraci\u00f3n. Sobre una mesita en el centro de estudiantes de la Universidad de Houston, Hannah Chang y Elizabeth Barrera inclinaron la","og_url":"https:\/\/test.ifesworld.org\/en\/prayerline\/stepping-out\/","og_site_name":"IFES","og_image":[{"width":960,"height":720,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2020\/12\/prayerlineLaFe.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/stepping-out\/","url":"https:\/\/test.ifesworld.org\/en\/prayerline\/stepping-out\/","name":"Salir de la zona de confort &#183; IFES Prayerline","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/stepping-out\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/stepping-out\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2020\/12\/prayerlineLaFe.jpg","datePublished":"2020-12-08T05:14:00+00:00","description":"Todo empez\u00f3 con la oraci\u00f3n. Sobre una mesita en el centro de estudiantes de la Universidad de Houston, Hannah Chang y Elizabeth Barrera inclinaron la","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/stepping-out\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/prayerline\/stepping-out\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/stepping-out\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2020\/12\/prayerlineLaFe.jpg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2020\/12\/prayerlineLaFe.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/prayerline\/stepping-out\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/es\/"},{"@type":"ListItem","position":2,"name":"Prayerline","item":"https:\/\/test.ifesworld.org\/en\/prayerline\/"},{"@type":"ListItem","position":3,"name":"Salir de la zona de confort"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/prayerline\/14503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/prayerline"}],"about":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/types\/prayerline"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/media\/14490"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/media?parent=14503"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/area?post=14503"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/theme?post=14503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}