{"id":15699,"date":"2021-05-13T10:51:19","date_gmt":"2021-05-13T09:51:19","guid":{"rendered":"https:\/\/test.ifesworld.org\/?post_type=conexion&#038;p=15699"},"modified":"2021-05-13T10:51:20","modified_gmt":"2021-05-13T09:51:20","slug":"la-transicion-mas-vulnerable","status":"publish","type":"conexion","link":"https:\/\/test.ifesworld.org\/es\/blog\/la-transicion-mas-vulnerable\/","title":{"rendered":"La transici\u00f3n m\u00e1s vulnerable"},"content":{"rendered":"<div class=\"wp-block block-core-heading\">\n<h3 class=\"wp-block-heading\"><strong>El mundo ante ti<\/strong>&nbsp;<\/h3>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Te acabas de graduar y el mundo entero est\u00e1 ante ti.&nbsp;Te sientes como si pudieras ir a cualquier parte y hacer lo que quisieras. Encuentras tu primer trabajo. Un trabajo&nbsp;<em>de verdad<\/em>.&nbsp;No te puedes creer que alguien te est\u00e9 pagando por hacer esto. Quiz\u00e1s te acabas de mudar a una ciudad nueva.&nbsp;Encontraste un apartamento excelente y tienes un compa\u00f1ero de piso que parece agradable.&nbsp;Y te sientes integrado en tu nueva vida.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Sin embargo, al cabo de unos meses&#8230;. las cosas se complican. Tienes much\u00edsimo trabajo. Es imposible seguir el ritmo de los dem\u00e1s. As\u00ed que pasas otra semana sin ir a la iglesia para no quedarte atr\u00e1s respecto a tus compa\u00f1eros de trabajo. Tampoco importa tanto&#8230; Ni siquiera has encontrado una buena iglesia en tu nueva ciudad.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">\u00bfY tu compa\u00f1ero de piso? Es agradable y todo eso, pero lo \u00fanico de lo que quiere hablar es de grandes temas filos\u00f3ficos.&nbsp;T\u00fa sabes que Jes\u00fas es la respuesta a sus preguntas, pero no tienes ni idea de c\u00f3mo integrar la fe a vuestros debates.&nbsp;Lo mismo pasa en el trabajo.&nbsp;Cada lunes consigues evitar las preguntas de tus compa\u00f1eros acerca de lo que hiciste el domingo. Adem\u00e1s, \u00bfpor qu\u00e9 querr\u00edan hablar de la iglesia? Es mejor mantener el trabajo al margen.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Te dices a ti mismo que todo pasar\u00e1 si te esfuerzas m\u00e1s.&nbsp;Encontrar\u00e1s la manera tu solo.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-heading\">\n<h3 class=\"wp-block-heading\"><strong>Una transici\u00f3n vulnerable<\/strong>&nbsp;<\/h3>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Cuando los graduados dejan la universidad, tiene lugar una crisis de desarrollo . En todo el mundo, hay pruebas que indican que una gran parte de los adolescentes cristianos deja de asistir a la iglesia antes de cumplir los 25 a\u00f1os.&nbsp;Los obreros afirman que, a menudo, los estudiantes se alejan de la fe porque no comprenden c\u00f3mo pueden conectar su trabajo con ella y les falta una rendici\u00f3n de cuentas y m\u00e1s ayuda para tratar la tentaci\u00f3n moral.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">El hecho de no tener apoyo en estas \u00e1reas en el momento en que los estudiantes pasan de una etapa de vida a otra, es un problema enorme. Las suposiciones que tienen sobre la vida y sus visiones del mundo son puestas en duda, tanto por las nuevas circunstancias como por un c\u00edrculo cada vez m\u00e1s grande de conocidos con diferentes ideas.&nbsp;La transici\u00f3n m\u00e1s vulnerable de todas ellas se produce cuando los graduados empiezan a trabajar.&nbsp;Es probable que tengan que mudarse a una ciudad o pa\u00eds nuevos, se tengan que enfrentar a presiones nuevas y tengan menos tiempo para el apoyo cristiano, ya que est\u00e1n consumidos por su nuevo trabajo.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">El problema no es necesariamente que estos estudiantes tengan dudas sobre su fe.&nbsp;El problema es que su fe no crece para adaptarse a esta nueva etapa de la vida.&nbsp;Tim Vickers, Director de Impacto de los Graduados de IFES, afirma:&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-quote is-style-default\">\n<blockquote class=\"wp-block-quote is-style-default is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cTodos los cristianos en todo el mundo, en todo momento, est\u00e1n siendo discipulados (o guiados), o bien hacia una relaci\u00f3n m\u00e1s \u00edntima con Jes\u00fas, o bien, lamentablemente, a alejarse de \u00e9l. Este proceso de discipulado tiene lugar a trav\u00e9s de las relaciones y conversaciones con otros y los mensajes culturales con que se les bombardea. A menudo, la fuerza ganadora (o bien la que los acerca a Jes\u00fas, o bien la que los aleja de \u00e9l) es aquella que parece dar m\u00e1s sentido al mundo tal y como lo experimentan.\u00a0Muchos adultos j\u00f3venes se enfrentan a dos transiciones importantes entre los 18 y los 25\u00a0a\u00f1os de edad: en primer lugar, cuando se van de casa para empezar la universidad y, en segundo lugar, cuando acaban la universidad y empiezan a trabajar.\u00a0En ambas transiciones, necesitan decidir otra vez por s\u00ed mismos si tanto su visi\u00f3n del mundo como sus creencias todav\u00eda son ciertas\u201d.<\/em>\u00a0<\/p><\/blockquote>\n<\/div>\n\n<div class=\"wp-block block-core-heading\">\n<h3 class=\"wp-block-heading\"><strong>Un impacto duradero, o una tragedia<\/strong>&nbsp;<\/h3>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">\u00bfDeber\u00edan los graduados tener que enfrentarse solos a estos asuntos, una vez han dejado sus grupos estudiantiles universitarios? IFES opina que no.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">En 2003, el te\u00f3logo John Stott describi\u00f3 la obra de Impacto de los Graduados como el trabajo m\u00e1s estrat\u00e9gico dentro de la iglesia en Europa y explic\u00f3 que \u201cno puedes culpar a la carne por pudrirse, pues esto es precisamente lo que hace la carne. Sin embargo, s\u00ed puedes culpar a la sal por no estar all\u00ed\u201d. IFES se ha comprometido a estar ah\u00ed para los graduados que est\u00e1n empezando sus vidas profesionales.&nbsp;Tim Vickers nos dice:&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-quote is-style-default\">\n<blockquote class=\"wp-block-quote is-style-default is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cCreo que, si conseguimos hacerlo bien, entonces tendr\u00e1 un impacto que perdurar\u00e1 a lo largo de los a\u00f1os. Si no conseguimos hacerlo bien, corremos el riesgo de llevar a cabo una evangelizaci\u00f3n brillante entre los estudiantes solo para verlos distanciarse de Cristo en el momento que dejen sus grupos, y esto ser\u00eda una tragedia\u201d.<\/em>\u00a0<\/p><\/blockquote>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">As\u00ed, \u00bfc\u00f3mo podemos \u201cconseguir hacerlo bien\u201d?&nbsp;Creando espacios para que los graduados puedan hablar de sus luchas en esta nueva etapa, ofreci\u00e9ndoles oportunidades para rendir cuentas y ayud\u00e1ndoles a ver que el trabajo y la fe no tienen&nbsp;por qu\u00e9&nbsp;estar separados.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-quote is-style-default\">\n<blockquote class=\"wp-block-quote is-style-default is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cNuestra visi\u00f3n es que los j\u00f3venes integren la fe y el trabajo y florezcan como individuos en ambos contextos. Para que vivan unas vidas de misi\u00f3n integral y que puedan vivir y hablar en todos los contextos con un distintivo cristiano que atraiga a los dem\u00e1s hacia Cristo.\u00a0Para que sean personas con integridad que emplean la plataforma que les ha otorgado su profesi\u00f3n para ser sal y luz en nuestro mundo no creyente\u201d.<\/em>\u00a0<\/p><\/blockquote>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Aqu\u00ed es donde entra en juego Cross-Current. Cross-Current es una parte de Impacto de los Graduados, un ministerio de IFES que ofrece apoyo y mentorazgo a los graduados en Europa que navegan por el mundo profesional.&nbsp;Los grupos Cross-Current conectan a profesionales j\u00f3venes con otros cristianos que est\u00e1n en la misma etapa de la vida y les ayudan a desarrollar ra\u00edces profundas que les sirvan de manera adecuada en su nuevo contexto misionero: \u00a1el mundo laboral!&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Mediante la reflexi\u00f3n y el estudio b\u00edblico, los grupos dan a los graduados los fundamentos b\u00edblicos necesarios para entender el trabajo de la misma forma que Jes\u00fas y adoptar un modelo diferente de testimonio cristiano que funcione en el mundo laboral. Los graduados pueden asistir, o bien a los grupos centrados en su industria o disciplina, o bien a aquellos abiertos a diferentes profesiones.&nbsp;Cross-Current tambi\u00e9n involucra a mentores cristianos maduros con una larga experiencia en practicar su fe en el contexto profesional.&nbsp;La provisi\u00f3n de este tipo de apoyo a los graduados los ayuda a desarrollar una nueva visi\u00f3n del mundo suficientemente amplia como para incluir a Jes\u00fas y el trabajo.&nbsp;En \u00faltima instancia, los moldea para que sean profesionales apasionados por traer el evangelio a su lugar de trabajo.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-quote is-style-default\">\n<blockquote class=\"wp-block-quote is-style-default is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cNuestro trabajo es alcanzar a las universidades con las buenas nuevas de Jesucristo para, m\u00e1s tarde, nutrir a la siguiente generaci\u00f3n de adultos a fin de que est\u00e9n capacitados para traer la influencia del evangelio a nuestras sociedades. Tanto a nivel global como estrat\u00e9gico, no existe otra organizaci\u00f3n tan bien situada para esta obra estrat\u00e9gica&#8230; Es nuestra responsabilidad, nuestra oportunidad\u201d.<\/em>\u00a0<\/p><\/blockquote>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Si te has graduado hace poco o eres un profesional joven navegando por el mundo laboral por primera vez, no est\u00e1s solo.&nbsp;\u00danete a una comunidad de cristianos como tu que quieren traer su fe al lugar de trabajo.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Cross-Current empez\u00f3 en Europa y Eurasia, pero en la actualidad apoya a l\u00edderes en cualquier lugar del mundo donde se necesiten grupos. Si te gustar\u00eda descubrir m\u00e1s, visita www.cross-current.org. Si te gustar\u00eda hablar con alguien acerca de c\u00f3mo involucrarte como miembro de grupo, obrero nacional de IFES o futuro l\u00edder, por favor, env\u00eda un correo electr\u00f3nico a&nbsp;<a href=\"mailto:admin@graduateimpact.org\" target=\"_blank\" rel=\"noreferrer noopener\">admin@graduateimpact.org<\/a>.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">El equipo de Impacto de los Graduados de IFES organizar\u00e1 una presentaci\u00f3n online en la que se explorar\u00e1n los tres a\u00f1os de investigaci\u00f3n llevada a cabo a fin de ayudar a moldear un ministerio eficaz para los profesionales j\u00f3venes a medida que dejan atr\u00e1s los grupos estudiantiles de IFES y se convierten en graduados.\u00a0Si te gustar\u00eda asistir a las presentaciones del 2 y 4 de junio, por favor, env\u00eda un correo electr\u00f3nico a\u00a0<a href=\"mailto:admin@graduateimpact.org\" target=\"_blank\" rel=\"noreferrer noopener\">admin@graduateimpact.org<\/a>.\u00a0\u00a0<\/p>\n<\/div>\n\n<div class=\"wp-block block-acf-ifesbutton\">\n<div class=\"\">\n    <a id=\"btn-block_609cf52bfad09\" target=\"\" href=\"https:\/\/give.test.ifesworld.org\/customgiving?t=1&#038;d=ER000_PGRAD&#038;s=18UKCX&#038;a=0\" class=\"btn btn--cta-link\">\n        <span>\n                    <span class=\"icon\"><svg class=\"icon\"><use xlink:href=\"#chevron-circle-right-solid\"\/><\/svg><\/span>\n        Haz un donativo para apoyar a este ministerio        <\/span>\n    <\/a>\n<\/div>\n\n<\/div>","protected":false},"featured_media":15694,"template":"","area":[],"theme":[],"class_list":["post-15699","conexion","type-conexion","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La transici\u00f3n m\u00e1s vulnerable &#183; IFES Conexi\u00f3n Blog<\/title>\n<meta name=\"description\" content=\"El mundo ante ti&nbsp; Te acabas de graduar y el mundo entero est\u00e1 ante ti.&nbsp;Te sientes como si pudieras ir a cualquier parte y hacer lo que\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La transici\u00f3n m\u00e1s vulnerable &#183; IFES Conexi\u00f3n Blog\" \/>\n<meta property=\"og:description\" content=\"El mundo ante ti&nbsp; Te acabas de graduar y el mundo entero est\u00e1 ante ti.&nbsp;Te sientes como si pudieras ir a cualquier parte y hacer lo que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/blog\/the-most-vulnerable-transition\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-13T09:51:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/05\/DSC4837-scaled-e1620898060461.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1356\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-most-vulnerable-transition\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-most-vulnerable-transition\\\/\",\"name\":\"La transici\u00f3n m\u00e1s vulnerable &#183; IFES Conexi\u00f3n Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-most-vulnerable-transition\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-most-vulnerable-transition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/DSC4837-scaled-e1620898060461.jpg\",\"datePublished\":\"2021-05-13T09:51:19+00:00\",\"dateModified\":\"2021-05-13T09:51:20+00:00\",\"description\":\"El mundo ante ti&nbsp; Te acabas de graduar y el mundo entero est\u00e1 ante ti.&nbsp;Te sientes como si pudieras ir a cualquier parte y hacer lo que\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-most-vulnerable-transition\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-most-vulnerable-transition\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-most-vulnerable-transition\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/DSC4837-scaled-e1620898060461.jpg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/DSC4837-scaled-e1620898060461.jpg\",\"width\":2560,\"height\":1356},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-most-vulnerable-transition\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conexi\u00f3n\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La transici\u00f3n m\u00e1s vulnerable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La transici\u00f3n m\u00e1s vulnerable &#183; IFES Conexi\u00f3n Blog","description":"El mundo ante ti&nbsp; Te acabas de graduar y el mundo entero est\u00e1 ante ti.&nbsp;Te sientes como si pudieras ir a cualquier parte y hacer lo que","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"La transici\u00f3n m\u00e1s vulnerable &#183; IFES Conexi\u00f3n Blog","og_description":"El mundo ante ti&nbsp; Te acabas de graduar y el mundo entero est\u00e1 ante ti.&nbsp;Te sientes como si pudieras ir a cualquier parte y hacer lo que","og_url":"https:\/\/test.ifesworld.org\/en\/blog\/the-most-vulnerable-transition\/","og_site_name":"IFES","article_modified_time":"2021-05-13T09:51:20+00:00","og_image":[{"width":2560,"height":1356,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/05\/DSC4837-scaled-e1620898060461.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-most-vulnerable-transition\/","url":"https:\/\/test.ifesworld.org\/en\/blog\/the-most-vulnerable-transition\/","name":"La transici\u00f3n m\u00e1s vulnerable &#183; IFES Conexi\u00f3n Blog","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-most-vulnerable-transition\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-most-vulnerable-transition\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/05\/DSC4837-scaled-e1620898060461.jpg","datePublished":"2021-05-13T09:51:19+00:00","dateModified":"2021-05-13T09:51:20+00:00","description":"El mundo ante ti&nbsp; Te acabas de graduar y el mundo entero est\u00e1 ante ti.&nbsp;Te sientes como si pudieras ir a cualquier parte y hacer lo que","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-most-vulnerable-transition\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/blog\/the-most-vulnerable-transition\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-most-vulnerable-transition\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/05\/DSC4837-scaled-e1620898060461.jpg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2021\/05\/DSC4837-scaled-e1620898060461.jpg","width":2560,"height":1356},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-most-vulnerable-transition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/es\/"},{"@type":"ListItem","position":2,"name":"Conexi\u00f3n","item":"https:\/\/test.ifesworld.org\/en\/blog\/"},{"@type":"ListItem","position":3,"name":"La transici\u00f3n m\u00e1s vulnerable"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/conexion\/15699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/conexion"}],"about":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/types\/conexion"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/media\/15694"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/media?parent=15699"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/area?post=15699"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/theme?post=15699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}