{"id":1157,"date":"2019-01-15T11:18:38","date_gmt":"2019-01-15T11:18:38","guid":{"rendered":"https:\/\/test.ifesworld.org\/conexion\/cuando-dios-hablo-por-medio-de-google\/"},"modified":"2019-07-03T13:44:17","modified_gmt":"2019-07-03T13:44:17","slug":"cuando-dios-hablo-por-medio-de-google","status":"publish","type":"conexion","link":"https:\/\/test.ifesworld.org\/es\/blog\/cuando-dios-hablo-por-medio-de-google\/","title":{"rendered":"Cuando Dios habl\u00f3 por medio de Google"},"content":{"rendered":"<p>\u201cTodo me da ansiedad\u201d escrib\u00ed en Google.<\/p>\n<p>Solo faltaban unos meses para graduarme, pero hab\u00eda llegado a mi l\u00edmite. Desde mi m\u00e1s temprana adolescencia hab\u00eda luchado contra una intensa ansiedad social. Asist\u00ed a terapia (que me ayud\u00f3 mucho) lo que me hizo interesarme por la psicolog\u00eda. Por eso decid\u00ed estudiar psicolog\u00eda en la universidad. Pens\u00e9 que si estudiaba esta carrera podr\u00eda salvarme de mi propia ansiedad, y en un futuro, ayudar a otros con el mismo problema que yo. Pero, empeor\u00f3 mientras era estudiante. Llegu\u00e9 al punto en el que no pod\u00eda hablar con otros ni salir de mi casa. Empec\u00e9 a tener ataques de p\u00e1nico porque mi vida no se estaba desarrollando como hab\u00eda planificado. Estaba intentando todo lo posible para eliminar mi problema, pero nada funcionaba.<\/p>\n<p>Buscaba una respuesta en cualquier lugar. \u00bfQu\u00e9 ten\u00eda que decir Google?<\/p>\n<h4>Cautivado por la\u00a0Biblia<\/h4>\n<p>Seg\u00fan iba viendo las respuestas en Google, mis ojos se posaron en unas palabras de la Biblia:<\/p>\n<blockquote><p>\u201cNo se inquieten por nada; m\u00e1s bien, en toda ocasi\u00f3n, con oraci\u00f3n y ruego, presenten sus peticiones a Dios y denle gracias.\u201c \u201dY la paz de Dios, que sobrepasa todo entendimiento, cuidar\u00e1 sus corazones y sus pensamientos en Cristo Jes\u00fas.\u201d Filipenses 4:6,7\u00a0[NVI]<\/p><\/blockquote>\n<p>Sent\u00eda que Dios me estaba hablando seg\u00fan le\u00eda. As\u00ed que, ah\u00ed mismo, or\u00e9 y ped\u00ed ayuda.<\/p>\n<p>Dios no respondi\u00f3 mi oraci\u00f3n de inmediato ni en la forma que yo esperaba, sino que puso en m\u00ed un deseo muy fuerte por estudiar la Biblia. Cuando termin\u00e9 mis estudios, pod\u00eda llegar a pasar seis horas al d\u00eda leyendo libros cristianos, escuchando sermones y viendo lecciones. Me hab\u00eda cautivado.<\/p>\n<figure class=\"wp-caption\"><img decoding=\"async\" src=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/8decc-1ixk91rixq0rharrke8z6gg.jpeg\" data-width=\"1280\" data-height=\"720\" \/><figcaption class=\"wp-caption-text\"> by <a href=\"https:\/\/unsplash.com\/photos\/G-_L3Eqkqmc?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\" target=\"_blank\" rel=\"noopener noreferrer\">Hannah Busing<\/a> on\u00a0<a href=\"https:\/\/unsplash.com\/?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\" target=\"_blank\" rel=\"noopener noreferrer\">Unsplash<\/a><\/figcaption><\/figure>\n<h4>Buscando la\u00a0verdad.<\/h4>\n<p>Me cri\u00e9 en Malta en la Iglesia Cat\u00f3lica Romana, al igual que el 98% de la poblaci\u00f3n del pa\u00eds. Iba a Misa todos los domingos y a Catequesis durante la semana, pero iba porque deb\u00eda, no porque quer\u00eda. Me costaba mantenerme despierto durante la Misa, y la raz\u00f3n por la que iba a Catequesis era para jugar al f\u00fatbol y ver a mis amigos. Jam\u00e1s cuestion\u00e9 mis creencias, pero siempre sent\u00ed que algo no estaba del todo bien.<\/p>\n<p>Cuando empec\u00e9 a leer la Biblia por m\u00ed mismo, descubr\u00ed muchas contradicciones con lo que me hab\u00edan ense\u00f1ado cuando era peque\u00f1o. Al principio, me cost\u00f3 mucho aceptarlo. Me di cuenta que me hab\u00edan ense\u00f1ado cosas que no se correspond\u00edan con lo que estaba leyendo en la Biblia. Como parte de mi b\u00fasqueda de la verdad, decid\u00ed visitar una iglesia evang\u00e9lica. Tras el culto, uno de los pastores comparti\u00f3 el Evangelio conmigo. Ese mismo d\u00eda, admit\u00ed que era un pecador y acept\u00e9 a Jesucristo como mi Salvador personal. Y me bautic\u00e9 unos meses m\u00e1s tarde.<\/p>\n<h4>Conociendo en qu\u00e9\u00a0creo.<\/h4>\n<p>Me cost\u00f3 hablarle a mis padres de acerca de mi nueva fe en Jes\u00fas. Lo mantuve en secreto porque mi familia entera es Cat\u00f3lica, y sab\u00eda que no lo aprobar\u00edan. Pero, tras unas pocas semanas, mis padres me pillaron con un libro acerca de la Biblia en las manos. Les tuve que decir la verdad. Y no fue nada bien. Y ahora, un a\u00f1o m\u00e1s tarde, sigue siendo complicado. Creen que me he unido a una secta. Creen que estoy perdiendo mi vida estudiando un libro que carece de valor. No quieren escucharme.<\/p>\n<p>La mayor\u00eda de mis amigos se alejaron de m\u00ed, y los pocos que se quedaron siguen critic\u00e1ndome y me intentan persuadir de volver a la fe Cat\u00f3lica. No me sorprende su reacci\u00f3n. En Malta, la mayor\u00eda cree que el cristianismo evang\u00e9lico es una secta. No conocen realmente lo que dice la Biblia. Mi caso era igual que el suyo. Antes, desconoc\u00eda en lo que cre\u00eda. Daba por hecho que todo lo que ense\u00f1aban los sacerdotes y maestros Cat\u00f3licos era cierto. Ahora me aseguro de que lo que escucho y creo venga de la Biblia y que s\u00e9 por qu\u00e9 creo lo que creo.<\/p>\n<figure class=\"wp-caption\"><img decoding=\"async\" src=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/db832-1bydjbafheaixijwei9zjxq.jpeg\" data-width=\"1280\" data-height=\"720\" \/><figcaption class=\"wp-caption-text\"> by <a href=\"https:\/\/unsplash.com\/photos\/nHRjqkRIuTE?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\" target=\"_blank\" rel=\"noopener noreferrer\">Amy Velazquez<\/a> on\u00a0<a href=\"https:\/\/unsplash.com\/?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\" target=\"_blank\" rel=\"noopener noreferrer\">Unsplash<\/a><\/figcaption><\/figure>\n<h4>Los retos de vivir como un seguidor de\u00a0Jes\u00fas.<\/h4>\n<p>Seg\u00fan iba compartiendo el Evangelio con otros, pude descubrir que muchas personas creen que son buenos. Creen que ir\u00e1n al cielo porque hacen m\u00e1s cosas buenas que malas. Aunque algunos de ellos no est\u00e1n de acuerdo con todo lo que se les ense\u00f1a, no se plantean cambiar. Dicen: me cri\u00e9 as\u00ed.<\/p>\n<p>Desde que llegu\u00e9 a mi fe en Jes\u00fas, he seguido luchando contra mi ansiedad. Pero he mejorado mucho. Ahora, cuando me preocupo, acudo a Dios en oraci\u00f3n. Me consuela y me ayuda a superarlo. Otro reto que he tenido ha sido encontrar un trabajo. Muchos trabajos exigen que trabaje en domingo, lo que me impedir\u00eda ir a la iglesia. He luchado contra la soledad, dado que apenas hay seguidores de Jes\u00fas de mi edad en Malta. Por el momento, no tengo amigos cercanos, pero paso mucho tiempo con Dios y \u00c9l me consuela en estos momentos tan dif\u00edciles.<\/p>\n<p>Ahora estoy estudiando un M\u00e1ster en teolog\u00eda online y estoy considerando hacerme pastor o trabajar como evangelista fuera de mi pa\u00eds en el futuro. No s\u00e9 si Dios me llamar\u00e1 a salir de Malta. Por ahora, estoy comprometido con mi iglesia local, y servir ah\u00ed es mi prioridad.<\/p>\n<figure><\/figure>\n","protected":false},"featured_media":1328,"template":"","area":[706,827],"theme":[1244],"class_list":["post-1157","conexion","type-conexion","status-publish","has-post-thumbnail","hentry","area-europa","area-malta-europa","theme-mi-historia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuando Dios habl\u00f3 por medio de Google &#183; IFES Conexi\u00f3n Blog<\/title>\n<meta name=\"description\" content=\"\u201cTodo me da ansiedad\u201d escrib\u00ed en Google. Solo faltaban unos meses para graduarme, pero hab\u00eda llegado a mi l\u00edmite. Desde mi m\u00e1s temprana adolescencia hab\u00eda\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuando Dios habl\u00f3 por medio de Google &#183; IFES Conexi\u00f3n Blog\" \/>\n<meta property=\"og:description\" content=\"\u201cTodo me da ansiedad\u201d escrib\u00ed en Google. Solo faltaban unos meses para graduarme, pero hab\u00eda llegado a mi l\u00edmite. Desde mi m\u00e1s temprana adolescencia hab\u00eda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-03T13:44:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/f5fd6-11b8es2k5z5ee97c0ok12pw.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/\",\"name\":\"Cuando Dios habl\u00f3 por medio de Google &#183; IFES Conexi\u00f3n Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/f5fd6-11b8es2k5z5ee97c0ok12pw.jpeg\",\"datePublished\":\"2019-01-15T11:18:38+00:00\",\"dateModified\":\"2019-07-03T13:44:17+00:00\",\"description\":\"\u201cTodo me da ansiedad\u201d escrib\u00ed en Google. Solo faltaban unos meses para graduarme, pero hab\u00eda llegado a mi l\u00edmite. Desde mi m\u00e1s temprana adolescencia hab\u00eda\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/f5fd6-11b8es2k5z5ee97c0ok12pw.jpeg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/f5fd6-11b8es2k5z5ee97c0ok12pw.jpeg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/when-god-spoke-through-google\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conexi\u00f3n\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cuando Dios habl\u00f3 por medio de Google\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuando Dios habl\u00f3 por medio de Google &#183; IFES Conexi\u00f3n Blog","description":"\u201cTodo me da ansiedad\u201d escrib\u00ed en Google. Solo faltaban unos meses para graduarme, pero hab\u00eda llegado a mi l\u00edmite. Desde mi m\u00e1s temprana adolescencia hab\u00eda","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Cuando Dios habl\u00f3 por medio de Google &#183; IFES Conexi\u00f3n Blog","og_description":"\u201cTodo me da ansiedad\u201d escrib\u00ed en Google. Solo faltaban unos meses para graduarme, pero hab\u00eda llegado a mi l\u00edmite. Desde mi m\u00e1s temprana adolescencia hab\u00eda","og_url":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/","og_site_name":"IFES","article_modified_time":"2019-07-03T13:44:17+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/f5fd6-11b8es2k5z5ee97c0ok12pw.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/","url":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/","name":"Cuando Dios habl\u00f3 por medio de Google &#183; IFES Conexi\u00f3n Blog","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/f5fd6-11b8es2k5z5ee97c0ok12pw.jpeg","datePublished":"2019-01-15T11:18:38+00:00","dateModified":"2019-07-03T13:44:17+00:00","description":"\u201cTodo me da ansiedad\u201d escrib\u00ed en Google. Solo faltaban unos meses para graduarme, pero hab\u00eda llegado a mi l\u00edmite. Desde mi m\u00e1s temprana adolescencia hab\u00eda","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/f5fd6-11b8es2k5z5ee97c0ok12pw.jpeg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/f5fd6-11b8es2k5z5ee97c0ok12pw.jpeg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/blog\/when-god-spoke-through-google\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/es\/"},{"@type":"ListItem","position":2,"name":"Conexi\u00f3n","item":"https:\/\/test.ifesworld.org\/en\/blog\/"},{"@type":"ListItem","position":3,"name":"Cuando Dios habl\u00f3 por medio de Google"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/conexion\/1157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/conexion"}],"about":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/types\/conexion"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/media\/1328"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/media?parent=1157"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/area?post=1157"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/theme?post=1157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}