{"id":1107,"date":"2017-12-06T09:36:52","date_gmt":"2017-12-06T09:36:52","guid":{"rendered":"https:\/\/test.ifesworld.org\/conexion\/el-regalo-de-la-fragilidad\/"},"modified":"2019-05-20T12:54:02","modified_gmt":"2019-05-20T12:54:02","slug":"el-regalo-de-la-fragilidad","status":"publish","type":"conexion","link":"https:\/\/test.ifesworld.org\/es\/blog\/el-regalo-de-la-fragilidad\/","title":{"rendered":"El regalo de la fragilidad"},"content":{"rendered":"<p>Navidad. Como familia, es el tiempo en que volvemos a casa desde diferentes partes del mundo. Recordamos juntos a Cristo, el precioso regalo de Dios para nosotros. \u00a1Qu\u00e9 incre\u00edble es que Dios viniera a nosotros y nos fuera accesible (en vez de haberse distanciado)! Vino como Emanuel, Dios con nosotros, y como nuestro verdadero mediador. Sin embargo, la Navidad siempre ha sido m\u00e1s que un mero recordar. Es el tiempo de anhelar que la salvaci\u00f3n redentora de Dios toque el centro de nuestra identidad: nuestra familia, nuestra iglesia, nuestros vecinos y nuestra naci\u00f3n.<\/p>\n<p>Nuestro Rey majestuoso se hizo voluntariamente vulnerable y honr\u00f3 nuestras vidas manchadas por el pecado. As\u00ed, la venida de Jes\u00fas indica la aparici\u00f3n de una nueva esperanza en medio de tantas cosas que solo causan desesperaci\u00f3n, desilusi\u00f3n y duda. Tal y como dijo Isa\u00edas: \u00abEl pueblo que andaba en tinieblas vio gran luz\u2026\u00bb (Isa\u00edas 9:2). Este es el gran evento que toda la historia ha estado esperando, \u00a1incluida mi familia!<\/p>\n<p>Por ello, la Navidad nunca podr\u00e1 ser simplemente un d\u00eda en el a\u00f1o para m\u00ed. M\u00e1s bien es el manantial de vida que brota de nuestras vidas, las moldea y las redime. Cada d\u00eda tiene sentido solo porque Cristo ha venido y ya ha empezado su obra de hacer nuevas todas las cosas, incluso si a\u00fan estamos lejos de ver el final.<\/p>\n<p>Mis celebraciones han sido moldeadas por lo que se ha ido pasando de generaci\u00f3n a generaci\u00f3n, tanto en mi casa como en mi peque\u00f1a iglesia evang\u00e9lica metodista. Nuestra perspectiva fue formada en un pa\u00eds donde, hasta 2010, la libertad religiosa era un hecho. Viv\u00edamos en una cultura multi\u00e9tnica y multireligiosa marcada por el respeto mutuo, la curiosidad en la fe de los dem\u00e1s y un inter\u00e9s aut\u00e9ntico por el pr\u00f3jimo. Ahora, con la amenaza de un fanatismo religioso a la vuelta de la esquina, las palabras \u00abDios que est\u00e1 a nuestro lado\u00bb me ayudan a seguir firme.<\/p>\n<p>Creo que el gozo de ser mujer es que muchas personas se sienten libres de compartir sus historias conmigo, pues hacemos el peregrinaje juntas. Como obrera de IFES con FES Malasia durante 30 a\u00f1os, tengo el privilegio de escuchar historias dolorosas de las vidas de mis estudiantes, lo que me lleva a luchar con Dios y preguntarle si realmente est\u00e1 con nosotros. Mis l\u00e1grimas riegan su altar mientras peleo con \u00e9l sobre mis estudiantes y su ministerio conmigo ha moldeado a\u00fan m\u00e1s mi s\u00f3lida convicci\u00f3n de que ciertamente Dios est\u00e1 con nosotros, nuestro Emanuel, y s\u00e9 que ha o\u00eddo nuestras peticiones. Las buenas nuevas de la Navidad son que Dios ha venido a nosotros y que \u00a1va a volver!<\/p>\n<p>A menudo me considero como una pilluela, privilegiada de que Dios me levante en brazos una y otra vez con su gracia y misericordia infinitas. Por ello, entiendo que mi labor en la vida es ser un heraldo de este \u00abDios con nosotros\u00bb que gu\u00eda a las personas hacia su reino del \u00abya pero a\u00fan no\u00bb. Y sea cual sea mi puesto de trabajo formal, esta labor no cambia. Evidentemente, tambi\u00e9n soy una mujer en el liderazgo, por lo que tengo que estar alerta acerca de la tentaci\u00f3n de pensar que se me ha tratado injustamente o que no soy tan buena como otros. Necesito no tomarme a m\u00ed misma demasiado seriamente y ser libre de ser yo misma.<\/p>\n<p>Para m\u00ed, este es el verdadero significado de vivir la encarnaci\u00f3n: saber que Dios est\u00e1 de nuestra parte, nos entiende y nos llama a un ideal alto \u00a1mientras vivimos nuestras vidas en fragilidad y vulnerabilidad como regalo a \u00e9l y al mundo!<\/p>\n<p><strong>Annette Arulrajah<\/strong>, Secretaria Regional de IFES para Asia del Este.<\/p>\n<p><em>Annette Arulrajah, de Malasia, fue nombrada Secretaria Regional de IFES para Asia del Este en agosto 2017. Annette ha servido en el equipo regional de IFES durante los \u00faltimos seis a\u00f1os, habiendo previamente liderado el movimiento estudiantil en Malasia. Es una l\u00edder con un coraz\u00f3n para el servicio y posee un profundo entendimiento de c\u00f3mo Dios trabaja mediante sus debilidades, adem\u00e1s de tener una visi\u00f3n de continuar viendo a Dios obrar en las vidas de los estudiantes de la regi\u00f3n.<\/em><\/p>\n<p><strong><em>Daniel Bourdann\u00e9<\/em><\/strong><em>, Secretario General IFES<\/em><\/p>\n","protected":false},"featured_media":1213,"template":"","area":[],"theme":[],"class_list":["post-1107","conexion","type-conexion","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El regalo de la fragilidad &#183; IFES Conexi\u00f3n Blog<\/title>\n<meta name=\"description\" content=\"Navidad. Como familia, es el tiempo en que volvemos a casa desde diferentes partes del mundo. Recordamos juntos a Cristo, el precioso regalo de Dios para\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El regalo de la fragilidad &#183; IFES Conexi\u00f3n Blog\" \/>\n<meta property=\"og:description\" content=\"Navidad. Como familia, es el tiempo en que volvemos a casa desde diferentes partes del mundo. Recordamos juntos a Cristo, el precioso regalo de Dios para\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/blog\/the-gift-of-fragility\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T12:54:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/8bbbd-1j67rqynfj_clwkici6dprq.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"543\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-gift-of-fragility\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-gift-of-fragility\\\/\",\"name\":\"El regalo de la fragilidad &#183; IFES Conexi\u00f3n Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-gift-of-fragility\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-gift-of-fragility\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/8bbbd-1j67rqynfj_clwkici6dprq.jpeg\",\"datePublished\":\"2017-12-06T09:36:52+00:00\",\"dateModified\":\"2019-05-20T12:54:02+00:00\",\"description\":\"Navidad. Como familia, es el tiempo en que volvemos a casa desde diferentes partes del mundo. Recordamos juntos a Cristo, el precioso regalo de Dios para\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-gift-of-fragility\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-gift-of-fragility\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-gift-of-fragility\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/8bbbd-1j67rqynfj_clwkici6dprq.jpeg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/8bbbd-1j67rqynfj_clwkici6dprq.jpeg\",\"width\":1200,\"height\":543},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/the-gift-of-fragility\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conexi\u00f3n\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El regalo de la fragilidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El regalo de la fragilidad &#183; IFES Conexi\u00f3n Blog","description":"Navidad. Como familia, es el tiempo en que volvemos a casa desde diferentes partes del mundo. Recordamos juntos a Cristo, el precioso regalo de Dios para","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"El regalo de la fragilidad &#183; IFES Conexi\u00f3n Blog","og_description":"Navidad. Como familia, es el tiempo en que volvemos a casa desde diferentes partes del mundo. Recordamos juntos a Cristo, el precioso regalo de Dios para","og_url":"https:\/\/test.ifesworld.org\/en\/blog\/the-gift-of-fragility\/","og_site_name":"IFES","article_modified_time":"2019-05-20T12:54:02+00:00","og_image":[{"width":1200,"height":543,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/8bbbd-1j67rqynfj_clwkici6dprq.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-gift-of-fragility\/","url":"https:\/\/test.ifesworld.org\/en\/blog\/the-gift-of-fragility\/","name":"El regalo de la fragilidad &#183; IFES Conexi\u00f3n Blog","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-gift-of-fragility\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-gift-of-fragility\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/8bbbd-1j67rqynfj_clwkici6dprq.jpeg","datePublished":"2017-12-06T09:36:52+00:00","dateModified":"2019-05-20T12:54:02+00:00","description":"Navidad. Como familia, es el tiempo en que volvemos a casa desde diferentes partes del mundo. Recordamos juntos a Cristo, el precioso regalo de Dios para","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-gift-of-fragility\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/blog\/the-gift-of-fragility\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-gift-of-fragility\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/8bbbd-1j67rqynfj_clwkici6dprq.jpeg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/8bbbd-1j67rqynfj_clwkici6dprq.jpeg","width":1200,"height":543},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/blog\/the-gift-of-fragility\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/es\/"},{"@type":"ListItem","position":2,"name":"Conexi\u00f3n","item":"https:\/\/test.ifesworld.org\/en\/blog\/"},{"@type":"ListItem","position":3,"name":"El regalo de la fragilidad"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/conexion\/1107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/conexion"}],"about":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/types\/conexion"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/media\/1213"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/media?parent=1107"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/area?post=1107"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/theme?post=1107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}