{"id":1097,"date":"2017-10-05T15:19:02","date_gmt":"2017-10-05T14:19:02","guid":{"rendered":"https:\/\/test.ifesworld.org\/conexion\/de-una-evangelizacion-basada-en-sandwiches-tostados-a-una-generosidad-enfocada-en-las-misiones\/"},"modified":"2019-05-20T13:49:16","modified_gmt":"2019-05-20T13:49:16","slug":"de-una-evangelizacion-basada-en-sandwiches-tostados-a-una-generosidad-enfocada-en-las-misiones","status":"publish","type":"conexion","link":"https:\/\/test.ifesworld.org\/es\/blog\/de-una-evangelizacion-basada-en-sandwiches-tostados-a-una-generosidad-enfocada-en-las-misiones\/","title":{"rendered":"De una evangelizaci\u00f3n basada en s\u00e1ndwiches tostados a una generosidad enfocada en las misiones"},"content":{"rendered":"<h4>C\u00f3mo los estudiantes en Nueva Zelanda apoyan la misi\u00f3n estudiantil en todo el\u00a0mundo<\/h4>\n<p><em>El s\u00e1ndwich tostado de queso. Un simple y humilde s\u00e1ndwich tostado, un refrigerio amado por estudiantes de todo el mundo. En Lincoln, Nueva Zelanda, la venta de s\u00e1ndwiches tostados ha sido, durante muchos a\u00f1os, una estrategia evangel\u00edstica clave para el grupo de IFES, el Lincoln University Christian Fellowship de TSCF.<\/em><\/p>\n<h4>Sirviendo a los estudiantes en\u00a0Lincoln<\/h4>\n<p>Centenares de estudiantes de la Universidad de Lincoln viven en las residencias universitarias. Cada mi\u00e9rcoles por la noche, un bar de la zona vende bebidas alcoh\u00f3licas a bajo precio. En Lincoln, hay una fuerte cultura de consumo de alcohol y, durante a\u00f1os, los estudiantes cristianos han servido a su facultad vendiendo s\u00e1ndwiches tostados a los estudiantes ebrios que vuelven a sus dormitorios despu\u00e9s de haber estado en el bar. A la universidad le gusta esta iniciativa, por lo que provee ingredientes gratuitos y est\u00e1 dise\u00f1ando una nueva cafeter\u00eda para cubrir las necesidades de este proyecto.<\/p>\n<p>Vender s\u00e1ndwiches tostados es una oportunidad para desembriagar un poco a los estudiantes, as\u00ed como para darles panfletos y hablarles de Jes\u00fas. Cada semana, estudiantes en diferentes estados de embriaguez preguntan: \u00ab\u00bfOs pagan para hacer esto?\u00bb y, cada semana, la respuesta es: \u00abNo. Somos la Comunidad Cristiana y lo hacemos como expresi\u00f3n del amor y el afecto de Jes\u00fas para usted\u00bb.<\/p>\n<h4><strong>Compartiendo las ganancias<\/strong><\/h4>\n<p>Aunque el precio de los s\u00e1ndwiches tostados es m\u00ednimo, con el tiempo ha ido generando un beneficio de varios miles de d\u00f3lares. Ha sido un gozo ver la generosidad y el compromiso con el evangelio que han mostrado los estudiantes de TSCF Lincoln con este dinero.<\/p>\n<p>Las ganancias se han usado para:<\/p>\n<ul>\n<li>Proveer fondos para los estudiantes de los grupos de TSCF m\u00e1s nuevos a fin de que puedan asistir a los campamentos de formaci\u00f3n b\u00edblica, debido al deseo de invertir en las misiones estudiantiles m\u00e1s nuevas.<\/li>\n<li>Apoyar a los grupos IFES en Fiji, debido al fuerte deseo de que los estudiantes de todo el Pac\u00edfico oigan acerca de Jes\u00fas.<\/li>\n<li>Proveer alimentos para las comidas de los mi\u00e9rcoles organizadas por TSCF Lincoln, para que todos en la facultad tengan la oportunidad de comer algo y examinar las afirmaciones de Jes\u00fas en la Biblia.<\/li>\n<\/ul>\n<p><em>El s\u00e1ndwich tostado es solo un peque\u00f1o refrigerio. Sin embargo, en las manos de los estudiantes de TSCF Lincoln no solo ha sido una herramienta evangel\u00edstica, sino tambi\u00e9n una oportunidad para recaudar fondos y usarlos para el trabajo de IFES en varios contextos. Doy gracias a Dios por la generosidad b\u00edblica que demuestran estos estudiantes.<\/em><\/p>\n<p>En este breve v\u00eddeo encontrar\u00e1 una peque\u00f1a muestra de los s\u00e1ndwiches tostados de Lincoln:<\/p>\n<p><iframe loading=\"lazy\" title=\"TSCF: Students Reaching Students For Christ\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/9hHA4r5RkSU?feature=oembed&#038;cc_load_policy=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h4>Colaboraciones a larga distancia<\/h4>\n<p>No solo son los estudiantes de Lincoln que est\u00e1n colaborando con otros movimientos IFES. Cada a\u00f1o, grupos de toda Nueva Zelanda buscan maneras creativas para recaudar fondos para el ministerio de IFES. Durante muchos a\u00f1os, los grupos de TSCF han estado apoyando a cuatro movimientos IFES de todo el mundo: PSFC en Fiji y Tonga, CECE en Ecuador y UESI en la India.<\/p>\n<figure><img decoding=\"async\" src=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/f5334-11offxegxfvdk1tsgxkgxww.png\" data-width=\"1459\" data-height=\"720\" \/><\/figure>\n<p>En la Conferencia Regional de Pac\u00edfico Sur (SPARC) en 2016 y que tuvo lugar en Nueva Zelanda, tuvimos la bendici\u00f3n de conocer algunos de los estudiantes y obreros de PSCF y CECE. Estos estudiantes compartieron un poco sobre sus pa\u00edses, cultura y comunidades universitarias, as\u00ed como tambi\u00e9n historias alentadoras sobre c\u00f3mo Dios ha estado obrando en sus ministerios estudiantiles. Tambi\u00e9n pudimos ver y escuchar de primera mano c\u00f3mo el dinero recaudado hab\u00eda llegado a cambiar las vidas de estudiantes en otros pa\u00edses.<\/p>\n<blockquote><p>Fue un gozo poder continuar cultivando y profundizando nuestra relaci\u00f3n con hermanos y hermanas de diferentes nacionalidades.<\/p><\/blockquote>\n<p>Los estudiantes se esfuerzan para recaudar fondos de maneras innovadoras. Recientemente, Auckland Overseas Christian Fellowship organiz\u00f3 una velada como su evento de recaudaci\u00f3n de fondos anual. Los grupos de TSCF en la Universidad de Otago se reunieron para dise\u00f1ar, imprimir y vender sudaderas y enviar los beneficios a diferentes grupos IFES de todo el mundo. Tambi\u00e9n est\u00e1n pensando en hacer lo mismo para ayudar a los estudiantes de todo el Pac\u00edfico a que puedan asistir al pr\u00f3ximo congreso regional en el 2018.<\/p>\n<p>Este a\u00f1o durante nuestro encuentro nacional de estudiantes, continuamos nuestra tradici\u00f3n de organizar una subasta con varios objetos ecuatorianos que nos trajo Ruth Hicks, de TSCF y que en la actualidad trabaja con el movimiento IFES de all\u00ed. Bufandas de colores, granos de caf\u00e9, camisetas de deporte nacionales\u2026 Tanto obreros como estudiantes clamaron (de buena manera) para llevarse las especialidades latinoamericanas. Todas las ganancias se usaron para ayudar a estudiantes y obreros de CECE Ecuador. La generosidad pura de los que estaban en aquella habitaci\u00f3n fue asombrosa. Era evidente que contribuir al trabajo en el extranjero estaba en el centro de los corazones de todos.<\/p>\n<blockquote><p>Ver el amor demostrado en la generosidad de los estudiantes hacia sus hermanos y hermanas en Cristo, incluso m\u00e1s all\u00e1 de las costas de Nueva Zelanda, es un testimonio de la gracia de Dios que trae unidad a todas las naciones. Para estos estudiantes, dar a IFES no es una obligaci\u00f3n sino un gozo, y una causa con importancia eterna.<\/p><\/blockquote>\n<p><em>Escrito por Tim Hodge, Jenny Huang y Michael Bresler, TSCF Nueva Zelanda.<\/em><\/p>\n<h4><strong>Responda:<\/strong><\/h4>\n<ul>\n<li>\u00bfColabora con otros movimientos IFES con los que podr\u00eda crear lazos m\u00e1s fuertes? \u00bfPodr\u00eda empezar una nueva colaboraci\u00f3n?<\/li>\n<li>\u00bfC\u00f3mo podr\u00eda apoyar a otro movimiento IFES? \u00bfPodr\u00eda considerar recaudar fondos una vez al a\u00f1o para ayudar a otro movimiento IFES?<\/li>\n<\/ul>\n<hr \/>\n<h4><strong>\u00danase al D\u00eda Mundial del Estudiante:<\/strong><\/h4>\n<p>El D\u00eda Mundial del Estudiante es una oportunidad genial para empezar y desarrollar estos v\u00ednculos internacionales. \u00bfPor qu\u00e9 no intenta orar regularmente por el mismo movimiento y conectar con este mediante una videoconferencia?<\/p>\n<p>Encuentre <a href=\"https:\/\/ifesdme.org\/ideas\" target=\"_blank\" rel=\"noopener noreferrer\">ideas para empezar nuevos v\u00ednculos en la p\u00e1gina web<\/a>, o utilice <a href=\"https:\/\/ifes.world\/dme17fb\" target=\"_blank\" rel=\"noopener noreferrer\">el evento de Facebook<\/a> para encontrar a alguien con quien conectar.<\/p>\n<figure><\/figure>\n","protected":false},"featured_media":1233,"template":"","area":[],"theme":[],"class_list":["post-1097","conexion","type-conexion","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De una evangelizaci\u00f3n basada en s\u00e1ndwiches tostados a una generosidad enfocada en las misiones &#183; IFES Conexi\u00f3n Blog<\/title>\n<meta name=\"description\" content=\"C\u00f3mo los estudiantes en Nueva Zelanda apoyan la misi\u00f3n estudiantil en todo el\u00a0mundo El s\u00e1ndwich tostado de queso. Un simple y humilde s\u00e1ndwich tostado, un\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De una evangelizaci\u00f3n basada en s\u00e1ndwiches tostados a una generosidad enfocada en las misiones &#183; IFES Conexi\u00f3n Blog\" \/>\n<meta property=\"og:description\" content=\"C\u00f3mo los estudiantes en Nueva Zelanda apoyan la misi\u00f3n estudiantil en todo el\u00a0mundo El s\u00e1ndwich tostado de queso. Un simple y humilde s\u00e1ndwich tostado, un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.ifesworld.org\/en\/blog\/turning-toastie-evangelism-into-mission-minded-giving\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-20T13:49:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/8f108-1nljvsk_opihm2fuzdzxn6q.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"669\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/turning-toastie-evangelism-into-mission-minded-giving\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/turning-toastie-evangelism-into-mission-minded-giving\\\/\",\"name\":\"De una evangelizaci\u00f3n basada en s\u00e1ndwiches tostados a una generosidad enfocada en las misiones &#183; IFES Conexi\u00f3n Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/turning-toastie-evangelism-into-mission-minded-giving\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/turning-toastie-evangelism-into-mission-minded-giving\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/8f108-1nljvsk_opihm2fuzdzxn6q.jpeg\",\"datePublished\":\"2017-10-05T14:19:02+00:00\",\"dateModified\":\"2019-05-20T13:49:16+00:00\",\"description\":\"C\u00f3mo los estudiantes en Nueva Zelanda apoyan la misi\u00f3n estudiantil en todo el\u00a0mundo El s\u00e1ndwich tostado de queso. Un simple y humilde s\u00e1ndwich tostado, un\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/turning-toastie-evangelism-into-mission-minded-giving\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/turning-toastie-evangelism-into-mission-minded-giving\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/turning-toastie-evangelism-into-mission-minded-giving\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/8f108-1nljvsk_opihm2fuzdzxn6q.jpeg\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/8f108-1nljvsk_opihm2fuzdzxn6q.jpeg\",\"width\":1200,\"height\":669},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/turning-toastie-evangelism-into-mission-minded-giving\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conexi\u00f3n\",\"item\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"De una evangelizaci\u00f3n basada en s\u00e1ndwiches tostados a una generosidad enfocada en las misiones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/test.ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/test.ifesworld.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De una evangelizaci\u00f3n basada en s\u00e1ndwiches tostados a una generosidad enfocada en las misiones &#183; IFES Conexi\u00f3n Blog","description":"C\u00f3mo los estudiantes en Nueva Zelanda apoyan la misi\u00f3n estudiantil en todo el\u00a0mundo El s\u00e1ndwich tostado de queso. Un simple y humilde s\u00e1ndwich tostado, un","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"De una evangelizaci\u00f3n basada en s\u00e1ndwiches tostados a una generosidad enfocada en las misiones &#183; IFES Conexi\u00f3n Blog","og_description":"C\u00f3mo los estudiantes en Nueva Zelanda apoyan la misi\u00f3n estudiantil en todo el\u00a0mundo El s\u00e1ndwich tostado de queso. Un simple y humilde s\u00e1ndwich tostado, un","og_url":"https:\/\/test.ifesworld.org\/en\/blog\/turning-toastie-evangelism-into-mission-minded-giving\/","og_site_name":"IFES","article_modified_time":"2019-05-20T13:49:16+00:00","og_image":[{"width":1200,"height":669,"url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/8f108-1nljvsk_opihm2fuzdzxn6q.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.ifesworld.org\/en\/blog\/turning-toastie-evangelism-into-mission-minded-giving\/","url":"https:\/\/test.ifesworld.org\/en\/blog\/turning-toastie-evangelism-into-mission-minded-giving\/","name":"De una evangelizaci\u00f3n basada en s\u00e1ndwiches tostados a una generosidad enfocada en las misiones &#183; IFES Conexi\u00f3n Blog","isPartOf":{"@id":"https:\/\/test.ifesworld.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/turning-toastie-evangelism-into-mission-minded-giving\/#primaryimage"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/turning-toastie-evangelism-into-mission-minded-giving\/#primaryimage"},"thumbnailUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/8f108-1nljvsk_opihm2fuzdzxn6q.jpeg","datePublished":"2017-10-05T14:19:02+00:00","dateModified":"2019-05-20T13:49:16+00:00","description":"C\u00f3mo los estudiantes en Nueva Zelanda apoyan la misi\u00f3n estudiantil en todo el\u00a0mundo El s\u00e1ndwich tostado de queso. Un simple y humilde s\u00e1ndwich tostado, un","breadcrumb":{"@id":"https:\/\/test.ifesworld.org\/en\/blog\/turning-toastie-evangelism-into-mission-minded-giving\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ifesworld.org\/en\/blog\/turning-toastie-evangelism-into-mission-minded-giving\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.ifesworld.org\/en\/blog\/turning-toastie-evangelism-into-mission-minded-giving\/#primaryimage","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/8f108-1nljvsk_opihm2fuzdzxn6q.jpeg","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/05\/8f108-1nljvsk_opihm2fuzdzxn6q.jpeg","width":1200,"height":669},{"@type":"BreadcrumbList","@id":"https:\/\/test.ifesworld.org\/en\/blog\/turning-toastie-evangelism-into-mission-minded-giving\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.ifesworld.org\/es\/"},{"@type":"ListItem","position":2,"name":"Conexi\u00f3n","item":"https:\/\/test.ifesworld.org\/en\/blog\/"},{"@type":"ListItem","position":3,"name":"De una evangelizaci\u00f3n basada en s\u00e1ndwiches tostados a una generosidad enfocada en las misiones"}]},{"@type":"WebSite","@id":"https:\/\/test.ifesworld.org\/en\/#website","url":"https:\/\/test.ifesworld.org\/en\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/test.ifesworld.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.ifesworld.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/test.ifesworld.org\/en\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/test.ifesworld.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/test.ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/test.ifesworld.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/conexion\/1097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/conexion"}],"about":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/types\/conexion"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/media\/1233"}],"wp:attachment":[{"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/media?parent=1097"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/area?post=1097"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/test.ifesworld.org\/es\/wp-json\/wp\/v2\/theme?post=1097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}